{"id":47052,"date":"2016-04-23T08:21:33","date_gmt":"2016-04-23T11:21:33","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=47052"},"modified":"2016-04-23T08:21:33","modified_gmt":"2016-04-23T11:21:33","slug":"47052-2","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/47052-2\/","title":{"rendered":"Los sindicatos amenazan con paro general si Macri veta la ley antidespidos"},"content":{"rendered":"<p>Las cinco centrales obreras anunciaron que elevar\u00e1n la conflictividad si el presidente traba el proyecto de ley que busca aprobar el Congreso.<\/p>\n<p><span style=\"line-height: 1.5\">Sindicalistas de las cinco centrales obreras anunciaron que lanzar\u00e1n un paro general si el presidente Mauricio Macri veta la ley antidespidos que busca aprobar el Congreso Nacional en los pr\u00f3ximos d\u00edas.<\/span><\/p>\n<p>La sanci\u00f3n de la ley de Emergencia ocupacional, impulsada por los bloques de la oposici\u00f3n y el sindicalismo, podr\u00eda ser rechazada por el presidente que ya anunci\u00f3 su disconformidad con la medida.<\/p>\n<p>Si esto sucede, los gremios amenazaron con una serie de medidas para mediados de mayo que podr\u00eda incluir un paro general.<\/p>\n<p>\u00abSi el Gobierno frena o insiste en vetar la emergencia ocupacional no tengo dudas de que tenemos que ir a un paro nacional en mayo\u00bb, expres\u00f3 Pablo Micheli, en di\u00e1logo con Ambito Financiero.<\/p>\n<h6>Fuente: InfoNews<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Las cinco centrales obreras anunciaron que elevar\u00e1n la conflictividad si el presidente traba el proyecto de ley que busca aprobar el Congreso.<\/p>\n","protected":false},"author":2,"featured_media":47053,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[21],"class_list":["post-47052","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-nacional","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/47052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=47052"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/47052\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/47053"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=47052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=47052"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=47052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}