{"id":47122,"date":"2016-04-25T07:34:29","date_gmt":"2016-04-25T10:34:29","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=47122"},"modified":"2016-04-25T07:34:29","modified_gmt":"2016-04-25T10:34:29","slug":"cubanos-podran-viajar-eeuu-mar-traves-los-cruceros","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/cubanos-podran-viajar-eeuu-mar-traves-los-cruceros\/","title":{"rendered":"Cubanos podr\u00e1n viajar a EEUU por mar a trav\u00e9s de los cruceros"},"content":{"rendered":"<p><span style=\"line-height: 1.5\">El gobierno de la isla adelant\u00f3 que en el futuro tambi\u00e9n ser\u00e1 en yates.<\/span><\/p>\n<p>El gobierno de Ra\u00fal Castro levant\u00f3 el viernes las restricciones para los viajes mar\u00edtimos de los cubanos, impuestas hace m\u00e1s de medio siglo, tras lo cual se reanudar\u00e1n a partir de mayo los cruceros entre Estados Unidos y la isla comunista.<\/p>\n<p>Las medidas, que entrar\u00e1n en vigor el martes pr\u00f3ximo, permitir\u00e1n el ingreso y salida de cubanos como pasajeros y tripulantes de buques mercantes y cruceros, seg\u00fan una nota oficial.<\/p>\n<p>El gobierno decidi\u00f3 \u00abautorizar la entrada y salida de ciudadanos cubanos, con independencia de su condici\u00f3n migratoria, en calidad de pasajeros y tripulantes en cruceros\u00bb, precisa el mensaje divulgado por los medios estatales.<\/p>\n<p>Cuba accedi\u00f3 a liberar los viajes mar\u00edtimos de sus ciudadanos como parte del proceso de normalizaci\u00f3n de relaciones con Estados Unidos iniciado en diciembre de 2014, y que alcanz\u00f3 su punto m\u00e1ximo con la hist\u00f3rica visita del presidente Barack Obama a La Habana en marzo.<\/p>\n<p>Las restricciones fueron impuestas despu\u00e9s del triunfo de la Revoluci\u00f3n Cubana en 1959, a ra\u00edz del desembarco y ataque de grupos anticastristas ayudados por Estados Unidos en el marco de la Guerra Fr\u00eda.<\/p>\n<p>Las autoridades cubanas tambi\u00e9n anunciaron que prev\u00e9n \u00abautorizar de forma gradual y una vez creadas las condiciones\u00bb, la entrada y salida de cubanos en yates, aunque no adelantaron una fecha.<\/p>\n<p>El paso dado por Cuba es especialmente sensible teniendo en cuenta que muchos cubanos todav\u00eda intentan migrar hacia Estados Unidos por v\u00eda mar\u00edtima, en precarias embarcaciones en las que arriesgan sus vidas.<\/p>\n<p>Las autoridades estadounidenses, que mantienen en vigor el embargo econ\u00f3mico contra la isla pese a la flexibilizaci\u00f3n de algunos puntos, conceden beneficios migratorios a los cubanos que logren pisar tierra norteamericana, pero deporta a los isle\u00f1os que son interceptados en el mar.<\/p>\n<p>La Habana ha insistido en la derogaci\u00f3n de las ventajas migratorias.<\/p>\n<h6>fuente: El Tribuno, Jujuy<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno de la isla adelant\u00f3 que en el futuro tambi\u00e9n ser\u00e1 en yates.<\/p>\n","protected":false},"author":2,"featured_media":47123,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[57],"class_list":["post-47122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-mundo","tag-el-mundo"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/47122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=47122"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/47122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/47123"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=47122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=47122"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=47122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}