{"id":47174,"date":"2016-04-26T07:16:36","date_gmt":"2016-04-26T10:16:36","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=47174"},"modified":"2016-04-26T07:16:36","modified_gmt":"2016-04-26T10:16:36","slug":"gobierno-insiste-negar-los-despidos-asegura-creo-empleo","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/gobierno-insiste-negar-los-despidos-asegura-creo-empleo\/","title":{"rendered":"El gobierno insiste en negar los despidos y asegura que cre\u00f3 empleo"},"content":{"rendered":"<p>Conferencia del jefe de Gabinete y el ministro de Trabajo. Desde el Ejecutivo mostraron cifras sobre empleo privado registrado de febrero. Dicen que hubo un leve aumento de la ocupaci\u00f3n.<\/p>\n<p><span style=\"line-height: 1.5\">El jefe de Gabinete, Marcos Pe\u00f1a, y el ministro de Trabajo, Jorge Triaca, aseguraron ayer que el pa\u00eds no est\u00e1 \u00aben proceso de destrucci\u00f3n de empleo, ni en una situaci\u00f3n de emergencia\u00bb y que ya existe un \u00abcrecimiento\u00bb en la cantidad de puestos de trabajo del sector privado, principalmente en las \u00e1reas de comercio y servicios.<\/span><\/p>\n<p>Los funcionarios reafirmaron la posici\u00f3n del gobierno de Mauricio Macri frente a los crecientes reclamos para que cesen los despidos masivos que, seg\u00fan informes privados y de los sindicatos, superan los 120 mil desde que asumi\u00f3. Este malestar se expondr\u00e1 en la movilizaci\u00f3n programada para el viernes por las cinco centrales sindicales y alimenta proyectos parlamentarios para frenar los despidos y reponer la doble indemnizaci\u00f3n.<\/p>\n<p>El Ejecutivo nacional, que blande el fantasma del veto a cualquier iniciativa que limite las cesant\u00edas, present\u00f3 una iniciativa destinada a eximir de las cargas sociales a las empresas que contraten a j\u00f3venes de entre 18 y 24 a\u00f1os.<\/p>\n<p>Fue en ese marco, que gobierno redobl\u00f3 la apuesta a la hora de evitar el \u00absinceramiento\u00bb sobre la realidad laboral. En una conferencia de prensa junto a Pe\u00f1a, el ministro de Trabajo asegur\u00f3 incluso que existe \u00abcrecimiento del empleo, principalmente en el sector del comercio y los servicios\u00bb.<\/p>\n<p>Los funcionarios detallaron que los datos presentados surgen de la Encuesta de Indicadores Laborales y del Sistema Integrado Provisional Argentino (Sipa). Este \u00faltimo indicador marca que en febrero, el trabajo registrado en el sector privado fue de 6.240.400 personas frente a 6.211.844 de febrero del a\u00f1o anterior lo que refleja un incremento del empleo del 0,5 por ciento.<\/p>\n<p>Triaca acept\u00f3 que \u00aben el sector privado registrado hay dos sectores que tienen niveles de tensi\u00f3n\u00bb, que son los de la construcci\u00f3n y de manufacturas.<\/p>\n<p>La cifras de Triaca informan las altas y bajas en el sector privado registrado, la mitad del total de ocupados que registra la Encuesta Permanente de Hogares (EPH). Dentro de este universo est\u00e1n tambi\u00e9n los estatales, los cuentapropistas y los precarizados. El nivel de informalidad es de un tercio de los asalariados en el pa\u00eds. Construcci\u00f3n e industria representan las principales fuentes de ocupaci\u00f3n en muchos aglomerados, como el del Gran Rosario.<\/p>\n<p>De acuerdo a gremios, entidades empresariales y sindicatos, como Came, la UIA,las dos CTA y consultoras como Tendencias Econ\u00f3micas, los despidos en el Estado y el sector privado suman entre 120 mil y 140 mil. Las noticias de cierres, despidos y suspensiones son diarias en esta regi\u00f3n. La situaci\u00f3n se agrav\u00f3 en marzo.<\/p>\n<p>En este marco, el diputado nacional Diego Bossio () les pidi\u00f3 a los funcionarios que no nieguen el desempleo.<\/p>\n<p>El secretario adjunto de Camioneros, Pablo Moyano, fue m\u00e1s all\u00e1. Dijo que \u00abel gobierno siente amor por los empresarios y odio por los trabajadores\u00bb.<\/p>\n<p>El gobernador de Santa Fe, Miguel Lifschitz, se manifest\u00f3 \u00abfavorable\u00bb al proyecto de ley opositor que busca prohibir los despidos de trabajadores.<\/p>\n<p><strong>Techint echa<\/strong><\/p>\n<p>Unos 15 trabajadores de la planta sider\u00fargica de Tenaris Siat en la localidad bonaerense de Valent\u00edn Alsina fueron despedidos y el resto de los operarios inici\u00f3 un paro por tiempo indeterminado, por lo que hoy habr\u00e1 una audiencia en el Ministerio de Trabajo.<\/p>\n<h6>Fuente: La capital, Rosario<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Conferencia del jefe de Gabinete y el ministro de Trabajo. Desde el Ejecutivo mostraron cifras sobre empleo privado registrado de febrero. Dicen que hubo un leve aumento de la ocupaci\u00f3n.<\/p>\n","protected":false},"author":2,"featured_media":47175,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[21],"class_list":["post-47174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-nacional","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/47174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=47174"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/47174\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/47175"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=47174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=47174"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=47174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}