{"id":47216,"date":"2016-04-26T08:18:21","date_gmt":"2016-04-26T11:18:21","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=47216"},"modified":"2016-04-26T08:18:21","modified_gmt":"2016-04-26T11:18:21","slug":"exigiran-erradicar-una-planta-acopio-cerealero-marcos-juarez","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/exigiran-erradicar-una-planta-acopio-cerealero-marcos-juarez\/","title":{"rendered":"Exigir\u00e1n erradicar una planta de acopio cerealero en Marcos Ju\u00e1rez"},"content":{"rendered":"<p>El Concejo Deliberante de esta ciudad, con mayor\u00eda del PRO, no dar\u00e1 m\u00e1s pr\u00f3rroga para que funcione all\u00ed una empresa de alta contaminaci\u00f3n para la ciudad. Sin embargo, el predio que quedar\u00e1 libre, ser\u00e1 usufructuado por Federico Braun, t\u00edo del actual secretario de Comercio de la Naci\u00f3n.<\/p>\n<p>El Concejo Deliberante vot\u00f3 por la negativa un nuevo pedido de excepci\u00f3n al Plan de Ordenamiento Urbano y pr\u00f3rroga para la erradicaci\u00f3n de la planta de acopio que funciona al sur de la ciudad solicitado por una empresa local.<\/p>\n<p>Al mismo tiempo se inst\u00f3 a la Asesor\u00eda Letrada para que el departamento ejecutivo pueda continuar con los procedimientos y obligue a retirar del sector residencial la estructura.<\/p>\n<p>La concejala oficialista Mariana Perotti record\u00f3 que hay un expediente referido a la empresa y consider\u00f3 que \u201cdespu\u00e9s de todo este tiempo la firma no ha demostrado razones suficientes o no ha hecho lo suficiente para erradicarse, ya que no puede estar en ese lugar\u201d. Adem\u00e1s destac\u00f3 \u201clos reclamos de los vecinos que viven en el sector\u201d y agreg\u00f3 que a pesar de haber transcurrido varios a\u00f1os \u201cno ha presentado un plan de erradicaci\u00f3n veraz o cierto, que muestre voluntad de ir erradic\u00e1ndose porque entendemos que una empresa de esa magnitud o de esa actividad no puede irse de un d\u00eda para otro\u201d.<\/p>\n<p>Por su parte, el edil justicialista Hern\u00e1n Passerini sostuvo que las acciones administrativas referidas al cese de actividades que hab\u00eda iniciado el anterior gobierno hab\u00edan quedado suspendidas ante esta presentaci\u00f3n de la empresa pero que no existe \u201cargumento s\u00f3lido\u201d para el plan de erradicaci\u00f3n que present\u00f3. Se trata de una propuesta a 5 a\u00f1os de plazo.<\/p>\n<p>\u201cEste plan no es adecuado y menos a\u00fan tolerar la continuaci\u00f3n de la planta con los reclamos de los vecinos\u201d, agreg\u00f3.<\/p>\n<p>Por su parte, la vecinalista Sonia Lingua record\u00f3 que en julio del 2015, en ocasi\u00f3n de los debates para la instalaci\u00f3n del supermercado La An\u00f3nima, hab\u00edan elaborado una carta para comenzar hablar del tema en la cual ped\u00edan \u201cdesestimar la acci\u00f3n judicial de la Municipalidad contra la empresa por el terreno de Lardiz\u00e1bal, lo que se concret\u00f3, adem\u00e1s del cierre y desmantelamiento de la planta de Juan B. Justo, lo cual no se concret\u00f3\u201d.<\/p>\n<p>Lingua pidi\u00f3 que \u201cse obre con todo el rigor de la ley porque esta firma desde hace mucho tiempo est\u00e1 acostumbrada a toda costa a imponer sus intereses privados en contra de los intereses colectivos. Se le han dado y se le han vencido todos los plazos correspondientes, ha tenido mucha relaci\u00f3n con el Ejecutivo y se ha beneficiado en demas\u00eda con la venta del terreno donde se va a implantar La An\u00f3nima as\u00ed que creo que ahora tendr\u00eda que cumplir en tiempo y forma y aplic\u00e1rsele todo el rigor de la ley para el desmantelamiento de esa planta ubicada en calle Juan B. Justo\u201d.<\/p>\n<p>Desde hace m\u00e1s de 10 a\u00f1os se le reclama al propietario que retire la planta, sin embargo con diferentes solicitudes de pr\u00f3rroga a los plazos la actividad de acopio de cereales, continu\u00f3. Se trata de una zona residencial de Marcos Ju\u00e1rez, en la que los vecinos conviven con el desecho que produce a diario.<\/p>\n<p>Las normas vigentes proh\u00edben que se desarrolle esta actividad en este sector, y la negativa a aprobar una nueva excepci\u00f3n desde el Concejo Deliberante obligar\u00e1 al Departamento Ejecutivo Municipal a iniciar las acciones legales correspondientes.<\/p>\n<h6>Fuente: La Ma\u00f1ana de C\u00f3rdoba<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El Concejo Deliberante de esta ciudad, con mayor\u00eda del PRO, no dar\u00e1 m\u00e1s pr\u00f3rroga para que funcione all\u00ed una empresa de alta contaminaci\u00f3n para la ciudad. Sin embargo, el predio que quedar\u00e1 libre, ser\u00e1 usufructuado por Federico Braun, t\u00edo del actual secretario de Comercio de la Naci\u00f3n.<\/p>\n","protected":false},"author":2,"featured_media":47217,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[3],"class_list":["post-47216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-cordoba"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/47216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=47216"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/47216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/47217"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=47216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=47216"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=47216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}