{"id":47225,"date":"2016-04-26T06:00:58","date_gmt":"2016-04-26T09:00:58","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=47225"},"modified":"2016-04-26T08:36:12","modified_gmt":"2016-04-26T11:36:12","slug":"municipio-posadas-invierte-4-millones-pesos-maquinaria-obras-publicas","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/municipio-posadas-invierte-4-millones-pesos-maquinaria-obras-publicas\/","title":{"rendered":"El consumidor pag\u00f3 5,6 veces m\u00e1s en marzo que lo que recibi\u00f3 el productor"},"content":{"rendered":"<p>Los datos sugen del \u00cdndice de Precios en Origen y Destino (IPOD) que elabor\u00f3 el \u00e1rea de Econom\u00edas Regionales de CAME para una canasta de 20 alimentos de origen vegetal.<\/p>\n<p>La diferencia entre lo que pag\u00f3 el consumidor por los productos agr\u00edcolas y lo que recibi\u00f3 el productor en el campo se fue de 5,6 veces m\u00e1s en marzo, seg\u00fan el\u00a0\u00cdndice de Precios en Origen y Destino (IPOD)\u00a0que elabor\u00f3 el \u00e1rea de Econom\u00edas Regionales de la\u00a0Confederaci\u00f3n Argentina de la Mediana Empresa\u00a0(CAME)\u00a0para una canasta de 20 alimentos de origen vegetal.<\/p>\n<p><span style=\"line-height: 1.5\">\u201cEl aumento importante que tuvieron los precios al p\u00fablico de muchos de los productos agr\u00edcolas en el tercer mes del a\u00f1o, la brecha se mantuvo sin cambios frente a febrero porque mejoraron simult\u00e1neamente los precios recibidos por el productor\u201d, aunque \u201cpor factores estacionales y por las distorsiones propias de las cadenas de frutas y verduras, existen productos cuyas diferencias de precios siguen siendo elevadas\u201d, se\u00f1al\u00f3 la entidad empresaria.<\/span><\/p>\n<p><span style=\"line-height: 1.5\">Tal es el caso del arroz, donde la diferencia entre el precio de origen y destino fue de 11,26 veces ($ 2,1 por kilo al productor \u2013 $ 23,1 por kilo en g\u00f3ndola); lo sigui\u00f3 la naranja, con una brecha de 10,33 veces ($ 2,50 \u2013 $ 25,8) provocada por el ajuste en los precios pagados al productor; la manzana roja, con una diferencia de 9,74 veces ($ 2,85 \u2013 $ 27,8); la acelga, con una brecha de 8,86 veces ($ 4,44 \u2013 $ 39,3); la pera, con una disparidad de precios de 8,42 veces ($ 2,50 &#8211; $ 21) y la frutilla, con una distancia entre los valores de 7,92 veces ($ 10 \u2013 $ 79,2).<\/span><\/p>\n<p><span style=\"line-height: 1.5\">En contraposici\u00f3n, los productos que menos se multiplicaron en los precios desde que salieron del campo fueron el repollo, con una brecha de s\u00f3lo 2,43 veces ($ 6,50 &#8211; $ 15,8); la lechuga, con una diferencia de 2,93 veces ($ 12,20 &#8211; $ 35,7) entre lo que paga el consumidor y lo que recibe el productor; la mandarina (3,17 veces) y la berenjena (3,54 veces).<\/span><\/p>\n<p><span style=\"line-height: 1.5\">En marzo hubo nueve productos relevados que registraron una mejora en la diferencia entre los valores de origen y destino.<\/span><\/p>\n<p><span style=\"line-height: 1.5\">Esos fueron la pera, la cual que obtuvo el valor m\u00e1s bajo que desde agosto de 2015, fecha en que CAME empez\u00f3 a realizar esta medici\u00f3n, como consecuencia de los mayores pagos al productor, aunque sigue siendo una de las frutas con mayor distorsi\u00f3n de precios, a la que siguieron el repollo, con un descenso de 3,08, veces y del br\u00f3coli con un retroceso de 2,87 veces.<\/span><\/p>\n<p><span style=\"line-height: 1.5\">Lo contrario ocurri\u00f3 con el arroz, donde la brecha creci\u00f3 6,86 veces (aunque ese aumento se explica exclusivamente por una modificaci\u00f3n en la metodolog\u00eda de estimaci\u00f3n del precio de origen); tambi\u00e9n lo hizo la naranja, en 6,70 veces; la calabaza en 2,15 veces; el lim\u00f3n en 1,9 veces; y la papa, con un ascenso de 1,42 veces en la brecha.<\/span><\/p>\n<p><span style=\"line-height: 1.5\">Cuando se agrupan los productos por origen, se observa que las mayores distorsiones en la cadena ocurren en los productos de origen vegetal.<\/span><\/p>\n<p><span style=\"line-height: 1.5\">Seg\u00fan CAME, es en la cadena de los productos de origen vegetal donde se observan \u201clas mayores distorsiones\u201d, ya que, en lo que respecta a la cadena de origen animal, que concentra cuatro productos (huevo, carne de pollo, carne de ternera y leche) mostr\u00f3 una brecha de precios de 3,8 veces en marzo, con una mejora de 5,5% con respecto a febrero.<\/span><\/p>\n<p><span style=\"line-height: 1.5\">Si se concentran ambos IPOD, la diferencia se ubica en 5,3 puntos, con una leve mejora frente a febrero.<\/span><\/p>\n<h6>Fuente: Uno, Entre R\u00edos<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Los datos sugen del \u00cdndice de Precios en Origen y Destino (IPOD) que elabor\u00f3 el \u00e1rea de Econom\u00edas Regionales de CAME para una canasta de 20 alimentos de origen vegetal.<\/p>\n","protected":false},"author":2,"featured_media":47226,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[21],"class_list":["post-47225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-nacional","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/47225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=47225"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/47225\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/47226"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=47225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=47225"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=47225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}