{"id":47235,"date":"2016-04-27T06:28:37","date_gmt":"2016-04-27T09:28:37","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=47235"},"modified":"2016-04-27T06:28:37","modified_gmt":"2016-04-27T09:28:37","slug":"47235-2","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/47235-2\/","title":{"rendered":"#Panam\u00e1Papers: La oposici\u00f3n acorrala a Jorge Macri y pide que comparezca ante el Senado"},"content":{"rendered":"<p>Un proyecto impulsado por los bloques opositores del PJ, FpV y FR busca obligar a comparecer ante el senado a Jorge Macri, presidente del Grupo Bapro, por su aparici\u00f3n en el esc\u00e1ndalo de las cuentas offshore.<\/p>\n<p>Jorge Macri deber\u00e1 comparecer ante el Senado bonaerense por su vinculaci\u00f3n con sociedades offshore, reveladas en el marco del esc\u00e1ndalo internacional de Panam\u00e1 Papers, si prospera un proyecto presentado por las bancas opositoras del FpV, PJ y Frente Renovador.<\/p>\n<p>Los tres espacios coincidieron en pedir la comparecencia de Macri, presidente del Grupo Bapro, basados en \u201clo normado en los art\u00edculos 90 y 92 de la Constituci\u00f3n Provincial y art\u00edculo 142 del Reglamento Interno de esta Honorable C\u00e1mara de Senadores\u201d.<\/p>\n<p>En concreto, buscan que Macri concurra al recinto \u201ca fin de informar verbalmente a este cuerpo, y presentar la documentaci\u00f3n que avale sus dichos, sobre su implicancia en la maniobra financiera internacional\u201d, a la que atribuyeron \u201cgravedad institucional\u201d y una \u201cmanifiesta contraposici\u00f3n al cargo que se encuentra desempe\u00f1ando\u201d.<\/p>\n<p>Macri, vale recordar, fue vinculado al esc\u00e1ndalo por sus v\u00ednculos con dos empresas, Latium Investments y Artecity, radicadas en el para\u00edso fiscal de Panam\u00e1.<\/p>\n<h6>Fuente: InfoCielo<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Un proyecto impulsado por los bloques opositores del PJ, FpV y FR busca obligar a comparecer ante el senado a Jorge Macri, presidente del Grupo Bapro, por su aparici\u00f3n en el esc\u00e1ndalo de las cuentas offshore.<\/p>\n","protected":false},"author":2,"featured_media":47236,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[12],"class_list":["post-47235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-politico","tag-buenos-aires"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/47235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=47235"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/47235\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/47236"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=47235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=47235"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=47235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}