{"id":47268,"date":"2016-04-27T07:13:43","date_gmt":"2016-04-27T10:13:43","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=47268"},"modified":"2016-04-27T07:13:43","modified_gmt":"2016-04-27T10:13:43","slug":"la-idea-salario-costo","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/la-idea-salario-costo\/","title":{"rendered":"Medios comunitarios"},"content":{"rendered":"<p>El Grupo de investigaci\u00f3n Conicet\/Defensor\u00eda del P\u00fablico traza un panorama de las nuevas dificultades y obst\u00e1culos que enfrentan los medios de comunicaci\u00f3n sin fines de lucro como consecuencia de las medidas adoptadas por el Poder Ejecutivo que cambian las reglas de juego en materia de comunicaci\u00f3n en el pa\u00eds y en el escenario econ\u00f3mico.<\/p>\n<p>Por\u00a0Grupo de investigaci\u00f3n Conicet\/Defensor\u00eda del P\u00fablico *<\/p>\n<p>A poco de iniciar su mandato, el nuevo gobierno nacional introdujo cambios en la regulaci\u00f3n de las comunicaciones e implement\u00f3 otras pol\u00edticas que impactan en los medios comunitarios, populares, alternativos y cooperativos.<\/p>\n<p>Los decretos de necesidad y urgencia 13 y 267 modifican la Ley de Servicios de Comunicaci\u00f3n Audiovisual (LSCA). Si bien no cambian los art\u00edculos espec\u00edficamente referidos a los medios no lucrativos excepto a las cooperativas que proveen televisi\u00f3n por cable, es claro que se fundan en el paradigma de la comunicaci\u00f3n como mercanc\u00eda y no como derecho humano. El cambio no es menor. Se abre entonces una nueva etapa para los medios del sector social de Argentina.<\/p>\n<p>Entre los recientes obst\u00e1culos para estas emisoras sobresale la par\u00e1lisis del Fondo de Fomento Concursable de los Medios de Comunicaci\u00f3n Audiovisual (Fomeca). El nuevo organismo de regulaci\u00f3n de la comunicaci\u00f3n audiovisual y las telecomunicaciones, el Enacom, no s\u00f3lo no abri\u00f3 nuevas l\u00edneas de fomento, sino que tambi\u00e9n adeuda pagos en proyectos adjudicados. Asimismo, la Direcci\u00f3n de Proyectos Especiales, encargada del desarrollo del Fondo, sufri\u00f3 un achicamiento importante. Estos fondos adjudicados mediante concursos p\u00fablicos, hab\u00edan permitido a radios y televisoras comunitarias y de pueblos originarios mejorar su posici\u00f3n en un mercado hipercompetitivo: equiparse, producir contenidos, contratar servicios, regularizar su gesti\u00f3n.<\/p>\n<p>Las cooperativas prestadoras de servicios p\u00fablicos que proveen televisi\u00f3n por cable \u2013el grupo de medios no lucrativos que en los \u00faltimos cinco a\u00f1os m\u00e1s creci\u00f3 en n\u00famero y en cantidad de licencias\u2013 dejaron de estar regidas por la LSCA. Son discriminadas frente a los operadores dominantes porque son las \u00fanicas cuya licencia para gestionar servicios convergentes puede ser impugnada y, en ese caso, deben someterse a un examen del \u00e1rea de Defensa de la Competencia.<\/p>\n<p>Considerando los cambios de prioridades en las pol\u00edticas p\u00fablicas y el desmantelamiento de algunas \u00e1reas del Estado, existe incertidumbre sobre la continuidad de programas destinados al desarrollo de radios populares, campesinas e ind\u00edgenas, e implementados por la Secretar\u00eda de Agricultura Familiar, el Instituto Nacional de Tecnolog\u00eda Agropecuaria (INTA), la Comisi\u00f3n Nacional de Bibliotecas Populares (Conabip), el Ministerio de Cultura y otros organismos nacionales.<\/p>\n<p>Por otra parte, los aumentos en las tarifas de luz redundan en un incremento de los costos de producci\u00f3n de los medios alternativos en un contexto generalizado de retracci\u00f3n econ\u00f3mica. Dos radios comunitarias de la Ciudad de Buenos Aires sirven de ejemplo: de pagar $3.700 mensuales, la de mayor alcance pas\u00f3 a pagar $ 12.000; y de pagar $2.500 bimensuales, la de menor alcance pas\u00f3 a pagar $ 5000 mensuales.<\/p>\n<p>Este nuevo escenario encuentra a la mayor\u00eda de los medios sin fines de lucro en una situaci\u00f3n de legalidad todav\u00eda precaria. Si bien en los \u00faltimos a\u00f1os se entregaron licencias y habilitaciones para funcionar, la no realizaci\u00f3n del plan t\u00e9cnico de frecuencias de radio constituy\u00f3 un obst\u00e1culo para mensurar el 33% del espectro que la ley 26522 ordena reservar para estos medios, e impidi\u00f3 realizar concursos en zonas de conflicto. Donde se hicieron concursos, falt\u00f3 avanzar en ampliar a\u00fan m\u00e1s las condiciones diferenciadas para estas emisoras.<\/p>\n<p>Enacom tiene en sus manos un caso testigo para comprobar su atenci\u00f3n al sector. Barricada TV, Urbana TV y Pares TV resultaron adjudicatarios de licencias en televisi\u00f3n digital abierta en baja potencia dentro de la categor\u00eda sin fines de lucro. El canal digital concursado por Barricada TV, el n\u00famero 33, est\u00e1 ocupado actualmente por Canal 13 cuando una resoluci\u00f3n de Afsca lo ubica en el n\u00famero 35. En estas condiciones, la recepci\u00f3n de sus se\u00f1ales resulta claramente dificultada: estos medios deben transmitir con una potencia de 150 vatios, mientras que Canal 13 lo hace con 12.500. A la fecha no hubo respuesta oficial.<\/p>\n<p>Los objetivos de diversidad, pluralismo, acceso y equidad de la LSCA y del DNU 267 s\u00f3lo pueden alcanzarse con pol\u00edticas que contemplen el escenario real en el que los medios comunitarios, populares y alternativos debieron y deben realizar su actividad y ejercitar su derecho a la libertad de expresi\u00f3n. Esto implica revertir \u2013en lugar de consolidar\u2013 las condiciones desiguales construidas hist\u00f3ricamente por las diversas regulaciones y pol\u00edticas que impactaron en el sector.<\/p>\n<p>* Ana Laura Hidalgo, Larisa Kejval, Alejandro Linares, Ver\u00f3nica Longo, Mar\u00eda Soledad Segura y Natalia Vinelli integran el equipo del proyecto de investigaci\u00f3n \u201cLas radios y televisoras comunitarias desde la Ley 26.522. Condiciones, estrategias y desaf\u00edos\u201d.<\/p>\n<h6>Fuente: P\u00e1gina 12<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El Grupo de investigaci\u00f3n Conicet\/Defensor\u00eda del P\u00fablico traza un panorama de las nuevas dificultades y obst\u00e1culos que enfrentan los medios de comunicaci\u00f3n sin fines de lucro como consecuencia de las medidas adoptadas por el Poder Ejecutivo <\/p>\n","protected":false},"author":2,"featured_media":47269,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[21],"class_list":["post-47268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-nacional","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/47268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=47268"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/47268\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/47269"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=47268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=47268"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=47268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}