{"id":47307,"date":"2016-04-27T05:14:16","date_gmt":"2016-04-27T08:14:16","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=47307"},"modified":"2016-04-27T08:16:28","modified_gmt":"2016-04-27T11:16:28","slug":"propusieron-teleferico-una-encarnacion-posadas","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/propusieron-teleferico-una-encarnacion-posadas\/","title":{"rendered":"Propusieron un telef\u00e9rico que una Encarnaci\u00f3n-Posadas"},"content":{"rendered":"<p>Al respecto el intendente de la ciudad capitalina explic\u00f3 que las buenas ideas siempre son bienvenidas. Adem\u00e1s remarc\u00f3 que ser\u00eda bueno producir en paralelo con la ciudad encarnacena<\/p>\n<p>&nbsp;<\/p>\n<p>Luego del proyecto que se present\u00f3 en Encarnaci\u00f3n (Paraguay), para construir un telef\u00e9rico que una a la ciudad vecina con Posadas, el intendente de Posadas Joaqu\u00edn Losada explic\u00f3 en\u00a0Noticiero 12 que\u00a0las buenas ideas siempre ser\u00e1n bienvenidas<\/p>\n<p>Adem\u00e1s manifest\u00f3 que es importante analizar la complejidad de un tr\u00e1mite de esta caracter\u00edstica; ya que se trata de un emprendimiento binacional.<\/p>\n<p>\u201cLos posade\u00f1os debemos seguir d\u00e1ndonos este tipo de debates que nos haga complementarios con los hermanos encarnacenos\u201d, dijo el jefe comunal.<\/p>\n<p>Asimismo Losada remarc\u00f3 que la idea del telef\u00e9rico es compleja debido a las asimetr\u00edas econ\u00f3micas que existe entre ambas ciudades.<\/p>\n<p>Para finalizar el intendente dijo: \u201cHay proyectos muy interesantes para trabajar con la ciudad encarnacena y ser\u00eda muy bueno poder juntarnos y producir en paralelo\u201d.<\/p>\n<p>La propuesta se present\u00f3 d\u00edas atr\u00e1s en Encarnaci\u00f3n y mediante im\u00e1genes descriptivas mostr\u00f3 la serie de equipamientos que fabrican en materia de cable, sistemas ferroviarios, instalaciones de parques de atracci\u00f3n y trenes de carretera.<\/p>\n<h6>Fuente: territorio Digital<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Al respecto el intendente de la ciudad capitalina explic\u00f3 que las buenas ideas siempre son bienvenidas. Adem\u00e1s remarc\u00f3 que ser\u00eda bueno producir en paralelo con la ciudad encarnacena<\/p>\n","protected":false},"author":2,"featured_media":47308,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[27],"class_list":["post-47307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-misiones"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/47307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=47307"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/47307\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/47308"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=47307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=47307"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=47307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}