{"id":47827,"date":"2016-05-06T08:08:56","date_gmt":"2016-05-06T11:08:56","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=47827"},"modified":"2016-05-06T08:08:56","modified_gmt":"2016-05-06T11:08:56","slug":"tras-la-polemica-avaluo-fiscal-mendoza-pierde-millones-falta-actualizacion","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/tras-la-polemica-avaluo-fiscal-mendoza-pierde-millones-falta-actualizacion\/","title":{"rendered":"Tras la pol\u00e9mica por el aval\u00fao fiscal: Mendoza pierde millones por falta de actualizaci\u00f3n"},"content":{"rendered":"<p>La pol\u00e9mica generada por las declaraciones juradas de los funcionarios de Cornejo permiti\u00f3 revelar una inexplicable falta de actualizaci\u00f3n de los valores de las propiedades. Se habla de $7.000 millones al a\u00f1o.<\/p>\n<p>La publicaci\u00f3n de las declaraciones juradas de los funcionarios de la gesti\u00f3n de Alfredo Cornejo desat\u00f3 un tsunami de cr\u00edticas por los irrisorios valores de algunas de las propiedades y bienes registrados.<\/p>\n<p>Quiz\u00e1s el que m\u00e1s enojo caus\u00f3 por lo incre\u00edble del dato fue una casa de la vicegobernadora Laura Montero, declarada por 70 centavos.<\/p>\n<p>M\u00e1s all\u00e1 de las explicaciones del caso, el tema puso de nuevo en agenda una vieja discusi\u00f3n: c\u00f3mo se realiza el aval\u00fao fiscal de las propiedades y desde cu\u00e1ndo no se realiza una actualizaci\u00f3n del registro catastral para que no ocurran situaciones irregulares y para mejorar la recaudaci\u00f3n impositiva de Mendoza.<\/p>\n<p>El arquitecto y ex legislador justicialista Roberto Blanco es autor de un proyecto para que Mendoza tenga una normativa espec\u00edfica en esta \u00e1rea. Esta obligar\u00eda a los gobiernos a realizar un censo catastral cada cuatro a\u00f1os para tener los datos actualizados.<\/p>\n<p>Adem\u00e1s, Blanco elabor\u00f3 un informe que da cuenta de lo que Mendoza pierde a\u00f1o a a\u00f1o por cobrar mal el Impuesto Inmobiliario. Seg\u00fan sus c\u00e1lculos \u2013basados en datos de la recaudaci\u00f3n oficial que se encuentran en la p\u00e1gina del Ministerio de Hacienda de Mendoza\u2013, se pierden $5.000 millones por c\u00e1lculos mal realizados de los impuestos Inmobiliario y de Sellos. En tanto, el Estado tambi\u00e9n deja de percibir aproximadamente $2.000 millones por construcciones clandestinas, decir, s\u00f3lo en esos rubros: Mendoza no recauda $7.000 millones.<\/p>\n<p>Seg\u00fan datos del ex legislador, en 10 a\u00f1os, Mendoza ha perdido $70.000 millones por estos errores o por falta de registro de los datos catastrales.<\/p>\n<p><strong>La p\u00e9rdida en la recaudaci\u00f3n<\/strong><\/p>\n<p>Con los datos proporcionados por el Estado en mano, Blanco explic\u00f3 c\u00f3mo fue decayendo la recaudaci\u00f3n impositiva mendocina, desde fines de los &#8217;80 hasta ahora.<\/p>\n<p>A fines de la d\u00e9cada de 1980, el Estado recaudaba un equivalente al 42% del presupuesto en impuestos provinciales (Ingresos Brutos, Inmobiliario, Automotor, Sellos).<\/p>\n<p>Entre el 2007 y el 2013, ese porcentaje cay\u00f3 al 24%. Mientras, entre el 2014 y el 2015, el total de la recaudaci\u00f3n signific\u00f3 26% de la pauta presupuestaria anual de Mendoza.<\/p>\n<p>Blanco destac\u00f3 que uno de los principales motivos de que ocurra esto es la total desactualizaci\u00f3n del aval\u00fao fiscal de las propiedades.<\/p>\n<p>Para explicarlo mejor utiliz\u00f3 algunas comparaciones. En 1990, se tomaba el valor del m2 a $210. En aquel momento, este valor representaba el 70% del real, que se estimaba en $300. Este es, seg\u00fan el arquitecto, el porcentaje recomendado por el catastro internacional. En cambio, en la actualidad, el valor estimado del m2 equivale al 17% del valor real: Mendoza lo toma a $1.750, mientras que el valor del mercado es de $10.000 por m2.<\/p>\n<p>\u00abSi aument\u00e1ramos el aval\u00fao fiscal de las propiedades, recaudar\u00edamos m\u00e1s por el Impuesto Inmobiliario y por el sellado en las transferencias de compra y venta\u00bb, asever\u00f3 el ex legislador.<\/p>\n<p><strong>54 a\u00f1os sin datos catastrales<\/strong><\/p>\n<p>Otro de los elementos que no ayudan a recaudar correctamente es la desactualizaci\u00f3n de los datos catastrales de Mendoza. Seg\u00fan el informe de Blanco, las \u00faltimas actualizaciones catastrales urbanas de Mendoza fueron hechas en base a tecnolog\u00eda aero-fotogram\u00e9trica y satelital, y datan de 1999, es decir, de hace 17 a\u00f1os.<\/p>\n<p>Tambi\u00e9n alarma el dato de la de-sactualizaci\u00f3n de los registros catastrales rurales: no se hacen desde 1962, es decir, Mendoza lleva 54 a\u00f1os sin renovarlos.<\/p>\n<p>\u00abEl catastro es un elemento crucial para el desarrollo de la econom\u00eda provincial y municipal, e incide sobre la planificaci\u00f3n urbana, los servicios, la regulaci\u00f3n de la tenencia de la tierra, el uso del suelo y la recaudaci\u00f3n impositiva\u00bb, manifest\u00f3 Blanco.<\/p>\n<p>El ex diputado explic\u00f3, adem\u00e1s, que existen empresas nacionales e internacionales capaces de brindar este servicio y que, incluso, cobran un porcentaje de la mayor recaudaci\u00f3n que el Estado obtenga por el relevamiento y la modificaci\u00f3n de los datos que a trav\u00e9s de \u00e9l se realicen.<\/p>\n<p>\u00abEs cuesti\u00f3n de eficiencia y decisi\u00f3n pol\u00edtica\u00bb, recalc\u00f3.<\/p>\n<p>Para concluir, Roberto Blanco destac\u00f3 que desde hace 17 a\u00f1os, las sucesivas gestiones de gobierno de Mendoza han intentado licitar el relevamiento de im\u00e1genes satelitales para la actualizaci\u00f3n catastral, sin conseguirlo.<\/p>\n<p>La \u00faltima vez que se intent\u00f3 fue en el 2011, a\u00f1o en el que se hab\u00eda conseguido financiamiento del BIRF y la licitaci\u00f3n lleg\u00f3 hasta la preadjudicaci\u00f3n, pero no se concret\u00f3.<\/p>\n<p>\u00abEn los \u00faltimos 20 a\u00f1os, casi todas las provincias argentinas invirtieron dinero en tecnolog\u00eda en esta \u00e1rea, Mendoza es una de las que no lo hizo\u00bb, remat\u00f3 el ex diputado.<\/p>\n<p><strong>Qu\u00e9 dice la Fiscal\u00eda de Estado<\/strong><\/p>\n<p>El responsable del \u00e1rea de declaraciones juradas de la Fiscal\u00eda de Estado de Mendoza, Mariano Made, explic\u00f3 que el registro del patrimonio de los funcionarios es una herramienta de seguimiento de los bienes de estos. Por eso, lo que se pide es que se coloque el valor registrado de las propiedades.<\/p>\n<p>\u00abEl valor que el funcionario declare queda a su criterio, si coloca un precio de siete australes o de un peso, no es nuestra funci\u00f3n opinar al respecto\u00bb. Lo que s\u00ed es responsabilidad de la Fiscal\u00eda es controlar que puedan justificar los bienes que adquieren mientras sean funcionarios p\u00fablicos.<\/p>\n<p><strong>La visi\u00f3n de Cornejo y del jefe de la ATM<\/strong><\/p>\n<p>El gobernador Alfredo Cornejo asegur\u00f3 que desde que el tema del contenido de las declaraciones juradas salt\u00f3 a los medios, ha recibido innumerables pedidos de los funcionarios de su gesti\u00f3n para que el decreto firmado por Francisco P\u00e9rez se modifique. Esto, para que se incluya a todos los poderes del Estado y para definir exactamente el criterio con el que se registra el valor de los bienes.<\/p>\n<p>El director de la Agencia Tributaria Mendoza (ATM), Alejandro Donatti, explic\u00f3 que lo que sucedi\u00f3 con los registros de las declaraciones juradas en las que aparecen inmuebles valuados a precios irrisorios, tuvo que ver con la falta de claridad de la norma dictada por el ex gobernador Francisco P\u00e9rez, para que los funcionarios tuvieran la obligaci\u00f3n de realizar la declaraci\u00f3n jurada de sus bienes.<\/p>\n<p>\u00abEl decreto que dict\u00f3 el ex gobernador Francisco P\u00e9rez no ha determinado la metodolog\u00eda para valuar los bienes que declaran los funcionarios. Como s\u00ed parece estar claro en los apartados que piden el registro de los bienes personales. Como no est\u00e1 claramente especificado ha quedado a criterio de los funcionarios\u00bb.<\/p>\n<p><strong>Irregularidades<\/strong><\/p>\n<p>Por otra parte, asumi\u00f3 que los registros catastrales de Mendoza estaban desactualizados.<\/p>\n<p>\u00abLo que hacemos es cruzar los datos que tenemos con los de los municipios para actualizar el catastro. Pero lamentablemente en nuestro pa\u00eds estas irregularidades son habituales, hay muchas construcciones clandestinas, sin habilitaci\u00f3n municipal. No es com\u00fan que la gente denuncie que le est\u00e1n cobrando de menos. Para eso el Estado tiene que investigar\u00bb, expres\u00f3 Donatti.<\/p>\n<h6>Fuente: Uno Mendoza<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La pol\u00e9mica generada por las declaraciones juradas de los funcionarios de Cornejo permiti\u00f3 revelar una inexplicable falta de actualizaci\u00f3n de los valores de las propiedades. Se habla de $7.000 millones al a\u00f1o.<\/p>\n","protected":false},"author":2,"featured_media":47828,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[31],"class_list":["post-47827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincias","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/47827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=47827"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/47827\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/47828"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=47827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=47827"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=47827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}