{"id":48380,"date":"2016-05-16T06:00:34","date_gmt":"2016-05-16T09:00:34","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=48380"},"modified":"2016-05-16T08:34:31","modified_gmt":"2016-05-16T11:34:31","slug":"urbanizaran-asentamiento-mas-antiguo-mendoza","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/urbanizaran-asentamiento-mas-antiguo-mendoza\/","title":{"rendered":"Urbanizar\u00e1n el asentamiento m\u00e1s antiguo de Mendoza"},"content":{"rendered":"<p>El Olivares, con m\u00e1s de 100 a\u00f1os, ser\u00e1 remodelado para lograr el car\u00e1cter de barrio y as\u00ed recibir los servicios b\u00e1sicos, al igual que el Flores Oeste, que est\u00e1 ubicado al lado<\/p>\n<p>Si les hubiesen preguntado a los primeros vecinos del barrio Olivares c\u00f3mo deb\u00eda llamarse el grupo de WhatsApp en el que se iban a difundir las noticias de la urbanizaci\u00f3n, el desconcierto hubiese sido total. Ni siquiera exist\u00eda la radio. Y para qu\u00e9 quer\u00edan asfaltar las calles si se mov\u00edan a caballo. Hace m\u00e1s de 100 a\u00f1os naci\u00f3 este asentamiento que se ubica frente a la UNCuyo. Y, desde hace d\u00e9cadas, sus vecinos, al igual que los del Flores Oeste, esperan la urbanizaci\u00f3n del lugar.<\/p>\n<p>Luego del paso de gestiones de todos los signos pol\u00edticos, la Municipalidad de Capital tom\u00f3 la decisi\u00f3n de urbanizar ambos asentamientos, que no al no poseer el car\u00e1cter de barrio no pueden recibir los servicios b\u00e1sicos como cloacas, agua, energ\u00eda el\u00e9ctrica ni gas.<\/p>\n<p>De esta forma, el Olivares y el Flores Oeste ser\u00e1n remodelados al punto de alcanzar la entidad de barrio. Con esto llegar\u00e1n los servicios. Y con los servicios podr\u00e1n empadronar los domicilios en la Direcci\u00f3n de Catastro. Un c\u00edrculo virtuoso e indispensable para que sus habitantes puedan vivir en condiciones dignas.<\/p>\n<p>La construcci\u00f3n de casas, para evitar que familias vivan entre paredes de chapa y nylon, ser\u00eda una segunda etapa, sobre la que vecinos y funcionarios prefieren ser precavidos.<\/p>\n<p>Parte 1<br \/>\n\u00abSe est\u00e1 buscando el acuerdo con el Estado provincial y la UNCuyo (due\u00f1a de los terrenos del Flores)para poder avanzar con la urbanizaci\u00f3n de ambos asentamientos, que si bien tienen nombres distintos son una misma masa humana espont\u00e1nea\u00bb, explic\u00f3 Mario Isgr\u00f3, secretario de Planificaci\u00f3n, Infraestructura y Ambiente, de Ciudad.<\/p>\n<p>Sobre la pol\u00edtica de trabajo, el arquitecto Isgr\u00f3 agreg\u00f3: \u00abHay una l\u00ednea de trabajo de diferentes ciudades del mundo, avalada por organismos como el BID o el Banco Mundial, que tiene como principio urbanizar los asentamientos espont\u00e1neos en los sitios donde nacieron por el apego de los vecinos al lugar\u00bb.<\/p>\n<p>Este proceso de urbanizaci\u00f3n, que le permitir\u00e1 formalizar las propiedades a los vecinos, alcanza a quienes viven all\u00ed desde hace m\u00e1s de 20 a\u00f1os. No para personas que se mudaron hace poco tiempo.<br \/>\nHasta ahora las obras las asumi\u00f3 la comuna. Y algunas m\u00e1quinas de trabajo las cedi\u00f3 Vialidad provincial.<\/p>\n<p>\u00abPara que el lote tenga n\u00famero de padr\u00f3n \u2013dijo Isgr\u00f3\u2013 tiene que tener los servicios. Ese el problema que tenemos que entender. Los que viven son los que m\u00e1s lo sufren. Hay que ensanchar las calles para que entren las cloacas, por ejemplo\u00bb.<\/p>\n<p>Gladys Mercado, 57 a\u00f1os, es una de las integrantes de la Cooperativa Victoria, del Olivares. Tiene 10 hijos. Desde hace d\u00e9cadas pelea porque el Estado d\u00e9 una soluci\u00f3n a los vecinos del sitio adonde vive. Los vecinos la adoran, siempre los ayud\u00f3. \u00abMe van a sacar de ac\u00e1 con las patitas para arriba\u00bb, repite con voz pausada.<\/p>\n<p>Hace 37 a\u00f1os que lleg\u00f3 de San Juan y su vida est\u00e1 entre esas calles estrechas con m\u00fasica propia. No quiere que relocalicen a los vecinos en otro barrio a kil\u00f3metros de all\u00ed, como ya hicieron muchas veces. Por eso da pelea. Y parece que la Municipalidad de Ciudad entendi\u00f3 los reclamos.<\/p>\n<p>\u00abHay unas pocas familias que hacen l\u00edo \u2013agrega Gladys\u2013. Las dem\u00e1s no. De ac\u00e1 sali\u00f3 Gonzalo D\u00edaz, el que jug\u00f3 en Godoy Cruz; tambi\u00e9n tenemos una forense. Hay gente muy estudiosa\u00bb.<\/p>\n<p>Teresa Castro, 64 a\u00f1os, lleg\u00f3 a los 10 al Flores Oeste, desde Catamarca. Enarbola la misma bandera que Gladys: \u00abQueremos que se dividan los lotes en terrenos de 200 metros cuadrados para cada uno\u00bb.<br \/>\nNo quieren que una familia disponga de un espacio amplio mientras otra convive hacinada en un \u00abrancho\u00bb, como suelen decirle ellos mismos a sus viviendas.<\/p>\n<p>\u00abTampoco queremos ir m\u00e1s a buscar el agua a Vialidad, como hac\u00edamos antes. Estamos dispuestos a pagar los servicios y los impuestos\u00bb, dice Teresa, que sabe que para eso es imprescindible que se concluyan las obras.<\/p>\n<p>\u00abLa Municipalidad est\u00e1 trabajando desde marzo. Avanzaron mucho. Cuando se acumula mucha basura les llamamos para que vengan a sacarla y ellos vienen inmediatamente\u00bb, concluye Gladys, con la mirada cansada.<\/p>\n<p>\u00bfQu\u00e9 dice la UNCuyo?<br \/>\n\u00abLos terrenos del barrio Flores son de la UNCuyo. El proceso judicial est\u00e1 vigente. Somos propietarios del inmueble y como tales mantenemos conversaciones y participamos en las mesas para encontrar una soluci\u00f3n\u00bb, aclar\u00f3 el abogado de la casa de altos estudios, V\u00edctor Ib\u00e1\u00f1ez.<\/p>\n<p>\u00abSabemos \u2013agreg\u00f3 el letrado\u2013 que el Municipio tiene la voluntad de urbanizar la zona. El martes se firmar\u00e1 un convenio entre la comuna, Edemsa, el EPRE y nosotros\u00bb.<\/p>\n<p>El convenio permitir\u00e1, con una modalidad particular, que se puedan hacer conexiones de luz en el Flores.<\/p>\n<p>\u00abNo hemos hecho nada m\u00e1s que mostrar nuestra voluntad para buscar una soluci\u00f3n\u00bb, finaliz\u00f3 Ib\u00e1\u00f1ez.<\/p>\n<h6>Fuente: Uno Mendoza<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El Olivares, con m\u00e1s de 100 a\u00f1os, ser\u00e1 remodelado para lograr el car\u00e1cter de barrio y as\u00ed recibir los servicios b\u00e1sicos, al igual que el Flores Oeste, que est\u00e1 ubicado al lado<\/p>\n","protected":false},"author":2,"featured_media":48381,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[31],"class_list":["post-48380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/48380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=48380"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/48380\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/48381"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=48380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=48380"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=48380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}