{"id":54262,"date":"2016-10-03T06:35:48","date_gmt":"2016-10-03T09:35:48","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=54262"},"modified":"2016-10-03T08:37:48","modified_gmt":"2016-10-03T11:37:48","slug":"se-perdieron-1-613-puestos-trabajo-catamarca-primer-semestre","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/se-perdieron-1-613-puestos-trabajo-catamarca-primer-semestre\/","title":{"rendered":"Se perdieron 1.613 puestos de trabajo en Catamarca en el primer semestre"},"content":{"rendered":"<p>El n\u00famero representa un decrecimiento del 3,6 por ciento en el periodo de diciembre a junio del 2016.<\/p>\n<p>La cantidad de empleos registrados en cuatro de las seis provincias del NOA tuvo entre diciembre de 2015 y junio de este a\u00f1o una ca\u00edda superior a los 22 mil trabajadores registrados, en su gran mayor\u00eda del sector privado, seg\u00fan la informaci\u00f3n que ofrece un medio period\u00edstico de Santiago del Estero y en base a datos que maneja la Superintendencia de Riesgos de Trabajo (SRT).<\/p>\n<p>En este orden y de acuerdo a lo que public\u00f3 El Liberal, Catamarca se encuentra entre las provincias que registraron p\u00e9rdidas, por un total de 1.613, de los empleos registrados entre diciembre y junio de este a\u00f1o. Esta cifra arroja un porcentual negativo del 3,6 por ciento.<\/p>\n<p>Sin perjuicio de ello, entre las provincias que tuvieron las mayores bajas en sus empleos registrados est\u00e1n Salta y Jujuy.<\/p>\n<p>En la primera subjurisdicci\u00f3n nacional mencionada se perdi\u00f3, en el periodo citado, 10.593 trabajos registrados.<\/p>\n<p>En este orden, El Liberal expone que \u00ablas bajas m\u00e1s fuertes estuvieron en sectores como el de Agricultura, que pas\u00f3 de 25.729 puestos registrados a 19.894, y la Construcci\u00f3n, que disminuy\u00f3 el empleo registrado de 12.343 a 9.960 trabajadores\u201d.<\/p>\n<p>Por su parte, en Jujuy la p\u00e9rdida de empleos alcanz\u00f3 a 7.095 personas. El medio explica que \u00abla mayor destrucci\u00f3n de empleos registrados fue en la Agricultura, que disminuy\u00f3 de 11.294 a 5.738 con una ca\u00edda de 5.556 puestos laborales registrados\u201d.<\/p>\n<p>En tanto, se remarca el crecimiento en La Rioja, donde hubo un aumento del empleo registrado de 1.159 trabajadores y en Tucum\u00e1n, un incremento de otros 12.409.<\/p>\n<p><strong>Empleadores<\/strong><\/p>\n<p>Por otro lado, el peri\u00f3dico mencionado indic\u00f3 la cantidad de empleadores registrados para igual periodo.<\/p>\n<p>En esta l\u00ednea y seg\u00fan los datos oficiales de la SRT, Catamarca ten\u00eda registrado a diciembre del a\u00f1o pasado 5.236 empleadores, mientras que a junio la cifra baj\u00f3 a los 4.778.<\/p>\n<p>Estos n\u00fameros arrojan la merma de 458 y representa un decrecimiento del 9 por ciento.<\/p>\n<p>Las provincias que mayor cantidad de empleadores perdieron fueron Tucum\u00e1n (con 3.671), Salta (2.349) y Jujuy (847).<\/p>\n<h6>Fuente: El Esquiu<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El n\u00famero representa un decrecimiento del 3,6 por ciento en el periodo de diciembre a junio del 2016.<\/p>\n","protected":false},"author":2,"featured_media":54263,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[16],"class_list":["post-54262","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincias","tag-catamarca"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/54262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=54262"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/54262\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/54263"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=54262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=54262"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=54262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}