{"id":54813,"date":"2016-10-19T07:56:13","date_gmt":"2016-10-19T10:56:13","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=54813"},"modified":"2016-10-19T07:56:13","modified_gmt":"2016-10-19T10:56:13","slug":"guaymallen-pide-la-reforma-constitucional","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/guaymallen-pide-la-reforma-constitucional\/","title":{"rendered":"Guaymall\u00e9n pide por la reforma constitucional"},"content":{"rendered":"<p>El Concejo Deliberante aprobar\u00e1 hoy una ordenanza que impulsa la UCR y que limita las reelecciones de intendentes y concejales; pero tambi\u00e9n una resoluci\u00f3n del PJ para invitar a los legisladores a modificar la Carta Magna.<\/p>\n<p>El nivel de consenso para reformar la Constituci\u00f3n provincial va en ascenso. A tal punto es as\u00ed, que es casi seguro que hoy el Concejo Deliberante de Guaymall\u00e9n apruebe una resoluci\u00f3n para pedir a la Legislatura que avance en una reforma \u201cintegral\u201d de la Carta Magna.<\/p>\n<p>La iniciativa tambi\u00e9n llega con un fuerte consenso entre los ediles, ya que complementar\u00e1 a otro proyecto trascendental. El que busca, por medio de una ordenanza, limitar las reelecciones de los intendentes y de los concejales guaymallinos.<\/p>\n<p>El primero es una iniciativa del representante del Frente para la Victoria (FpV), Rafael Moyano, quien pide que \u201ctodos los legisladores, especialmente los guaymallinos\u201d, avancen sobre el texto constitucional.<\/p>\n<p>El segundo, y m\u00e1s conocido hasta ahora, es el que impulsa el radical Ignacio Conte, aunque avalado por todo su bloque.<\/p>\n<p>La intenci\u00f3n es modificar el sistema electoral del muncipio que hoy conduce Marcelino Iglesias (UCR), quien ha dicho no estar a favor \u201cde ninguna reelecci\u00f3n\u201d. Para ello se basa precisamente en un art\u00edculo de la Constituci\u00f3n, el 198.<\/p>\n<p>All\u00ed dice con claridad que los intendentes deben ser elegidos por el voto de su pueblo, \u201cpudiendo ser reelectos\u201d, sin m\u00e1s detalle que eso.<\/p>\n<p>\u201cVimos que se pod\u00eda hacer sin problemas y por eso avanzamos\u201d, resalt\u00f3 Conte, quien a\u00f1adi\u00f3 que \u201clos constitucionalistas avalan la iniciativa\u201d.<\/p>\n<p>Efectivamente, la reconocida abogada constitucionalista Mar\u00eda Gabriela \u00c1balos, coincidi\u00f3. \u201cEs un tema absolutamente constitucional\u201d, indic\u00f3. \u201cEl municipio puede limitar las reelecciones si as\u00ed lo quiere\u201d.<\/p>\n<p>Sin embargo los ediles quieren ir m\u00e1s all\u00e1 y por eso Moyano plante\u00f3 su proyecto. \u201cEst\u00e1 bien la limitaci\u00f3n, pero eso quedar\u00e1 en Guaymall\u00e9n. Nosotros queremos que esto se ampl\u00ede\u201d, dijo el peronista.<\/p>\n<p>\u201cEstamos de acuerdo, eso demuestra el consenso de estos temas\u201d, resalt\u00f3 por su lado Conte, que intent\u00f3 dar a ambos proyectos \u201cla idea de una bola de nieve que vaya creciendo en toda la provincia\u201d.<\/p>\n<p>Moyano explic\u00f3 que su partido \u201csiempre ha sido reformista\u201d y en ese sentido consider\u00f3 que \u201c\u00e9ste es el momento para pensar en una reforma integral de la Constituci\u00f3n\u201d.<\/p>\n<p>Por eso, si bien es cierto que no ha conversado el proyecto con las autoridades electas de su partido, \u201cseguramente habr\u00e1 consenso\u201d, consider\u00f3.<\/p>\n<p>Pues bien, en un art\u00edculo publicado ayer por Los Andes, que da cuenta del debate que las universidades dieron en torno a las posibles reformas a la Constituci\u00f3n, el nuevo jefe del justicialismo, Omar F\u00e9lix, se mostr\u00f3 a favor de esos cambios. E incluso avanz\u00f3 en lo que es la reelecci\u00f3n del gobernador, el cual ha sido considerado \u201cun fantasma\u201d que ha frustrado iniciativas anteriores.<\/p>\n<p>Para Moyano incluso, esta es una oportunidad no s\u00f3lo para hablar de reelecciones o reformas pol\u00edticas. \u201cEs la oportunidad de hablar, por ejemplo, de autonom\u00eda municipal\u201d.<\/p>\n<p><strong>Godoy Cruz lo eval\u00faa<\/strong><\/p>\n<p>El proyecto de limitar las reelecciones ya tiene una repercusi\u00f3n directa. El concejal radical Sergio Biscupovich presentar\u00e1 \u201cesta semana\u201d un proyecto basado en el de Conte.<\/p>\n<p>\u201cSe trata de una buena iniciativa. Vamos a adecuar el texto a lo que es Godoy Cruz y le daremos ingreso\u201d, expres\u00f3.<\/p>\n<p>El edil godoicruce\u00f1o dijo que su intenci\u00f3n es avanzar en este tema \u201cm\u00e1s all\u00e1 de que culturalmente es un departamento en el que lo de una reelecci\u00f3n ya se cumple de hecho\u201d.<\/p>\n<p>En efecto es as\u00ed. Desde el regreso a la Democracia, en 1983, ning\u00fan intendente ha superado los dos mandatos, es decir, una elecci\u00f3n y una reelecci\u00f3n.<\/p>\n<p>Biscupovich adem\u00e1s consider\u00f3 que \u201cser\u00eda bueno que esto se trasladara a todos los departamentos\u201d. Y en igual sentido, aval\u00f3 la idea de que se pida una reforma de la Constituci\u00f3n. \u201cProbablemente incorporemos en el mismo texto, el pedido que en Guaymall\u00e9n hace Moyano\u201d, se\u00f1al\u00f3 el radical.<\/p>\n<p><strong>Alcances de una medida \u201cdeclarativa\u201d<\/strong><\/p>\n<p>Mar\u00eda Gabriela \u00c1balos explic\u00f3 que \u201ctoda norma puede ser derogada o modificada por otra de igual jerarqu\u00eda\u201d. En tal sentido, s\u00f3lo una ordenanza municipal puede modificar una norma similar en los departamentos. As\u00ed tambi\u00e9n, una ley se cambia con otra. \u201cY jur\u00eddicamente hablando, s\u00f3lo en la Legislatura se puede variar la Constituci\u00f3n\u201d, explic\u00f3.<\/p>\n<p>Eso significa que un proyecto como el de Moyano en Guaymall\u00e9n, de buscar un cambio en la Constituci\u00f3n provincial, no tiene mucho m\u00e1s sentido que \u201cdeclarativo\u201d. Precisamente por eso es que se trata de una resoluci\u00f3n. Sin embargo la constitucionalista vio con buenos ojos la iniciativa. \u201cSe trata de un hecho positivo. Ojal\u00e1 los 18 departamentos se pusieran de acuerdo en hacer este tipo de declaraciones\u201d. se\u00f1al\u00f3.<\/p>\n<p>\u00c1balos es una de las expertas m\u00e1s citada por la vicegobernadora Laura Montero, quien desde febrero pasado ha organizado distintos debates en torno a una posible reforma de la Constituci\u00f3n de Mendoza.<\/p>\n<h6>Fuente: Los ANdes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El Concejo Deliberante aprobar\u00e1 hoy una ordenanza que impulsa la UCR y que limita las reelecciones de intendentes y concejales; pero tambi\u00e9n una resoluci\u00f3n del PJ para invitar a los legisladores a modificar la Carta Magna.<\/p>\n","protected":false},"author":2,"featured_media":54814,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[31],"class_list":["post-54813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-politico","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/54813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=54813"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/54813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/54814"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=54813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=54813"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=54813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}