{"id":55568,"date":"2016-11-07T07:45:57","date_gmt":"2016-11-07T10:45:57","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=55568"},"modified":"2016-11-07T07:45:57","modified_gmt":"2016-11-07T10:45:57","slug":"mendoza-recaudacion-coparticipacion-preocupante-caida-libre","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/mendoza-recaudacion-coparticipacion-preocupante-caida-libre\/","title":{"rendered":"Mendoza: Recaudaci\u00f3n y coparticipaci\u00f3n, en preocupante ca\u00edda libre"},"content":{"rendered":"<p>Octubre ha sido el peor mes del a\u00f1o, con una baja que lleg\u00f3 por lo menos a 11 puntos. Lo sufrir\u00e1n las comunas. El estancamiento, la inflaci\u00f3n y la retracci\u00f3n del consumo figuran entre los principales motivos del fen\u00f3meno<\/p>\n<p>Octubre no s\u00f3lo ha sido el mes de mayor ca\u00edda en la recaudaci\u00f3n provincial, seg\u00fan explic\u00f3 el director general de Rentas, Ignacio Barbeira, sino en el que m\u00e1s han disminuido los ingresos por coparticipaci\u00f3n, tal como lo indic\u00f3 el tesorero general de la provincia, Mauro Luchetti.<\/p>\n<p>As\u00ed, mientras en setiembre la recaudaci\u00f3n de impuestos provinciales se hab\u00eda mantenido en un orden superior al 30%, en octubre se desplom\u00f3: lleg\u00f3 al 19%.<\/p>\n<p>En tanto, una situaci\u00f3n similar ocurri\u00f3 con las tasas que generan ingresos coparticipables provenientes de la Naci\u00f3n. Las cifras pueden homologarse: ingresos alrededor del 30% y en el 9\u00ba mes del a\u00f1o la ca\u00edda fue de alrededor de 11%.<\/p>\n<p>Tanto el tesorero como el director de Rentas coincidieron en que la respuesta est\u00e1 en el fen\u00f3meno conocido como estanflaci\u00f3n (estancamiento con inflaci\u00f3n). Ca\u00edda de la actividad productiva, precios altos que no ceden y el consumo detenido provocan un combo mortal para el crecimiento econ\u00f3mico.<br \/>\nLo cierto es que el impacto lo van a sufrir directamente las comunas, ya que la masa coparticipable, obviamente, disminuir\u00e1.<\/p>\n<p><strong>Los n\u00fameros provinciales<\/strong><br \/>\nSeg\u00fan Barbeira, la recaudaci\u00f3n se ven\u00eda manteniendo hasta setiembre en forma m\u00e1s o menos pareja.<br \/>\nEl funcionario explic\u00f3 que, de alguna manera, se estaba sosteniendo el recurso presupuestado, entre el 29% y el 30%.<\/p>\n<p>Barbeira manifest\u00f3 que en octubre se puede observar una ca\u00edda en el IVA impositivo que est\u00e1 en 20,4%. \u00abNosotros en Ingresos Brutos vimos una situaci\u00f3n similar con un aumento del 21% interanual\u00bb, y agreg\u00f3: \u00abEsto lo atribuimos a una ca\u00edda pronunciada de la actividad, si comparamos el IVA con los Ingresos Brutos, que son los impuestos que est\u00e1n de alguna manera relacionados directamente al crecimiento de la actividad productiva. No sabemos si en el tercer trimestre va a mantenerse, o va a crecer. Pero s\u00ed aseguramos que hay un estancamiento con inflaci\u00f3n\u00bb.<\/p>\n<p><strong>De la Naci\u00f3n<\/strong><br \/>\nAdem\u00e1s de disminuir los ingresos provinciales, a nivel nacional la situaci\u00f3n es preocupante. As\u00ed, mientras hasta setiembre la masa de impuestos coparticipables se mantuvo en el orden del 28%, en octubre cay\u00f3 al 19%.<\/p>\n<p>Luchetti explic\u00f3 que la recaudaci\u00f3n de todos los impuestos que se coparticipan disminuy\u00f3.<br \/>\nAs\u00ed, el IVA pas\u00f3 del 35% en promedio al 24% en octubre, el impuesto al cheque del 32% al 28% y el monotributo del 18% al 20%,<\/p>\n<p>En cuanto al Impuesto a los Bienes Personales, s\u00f3lo creci\u00f3 en promedio 4,5% , registr\u00e1ndose meses en los que se recaud\u00f3 menos que el a\u00f1o pasado. En este contexto, los peores meses fueron marzo, donde hubo una recaudaci\u00f3n negativa del orden del 22% y octubre donde fue del 12%.<\/p>\n<p>El caso m\u00e1s emblem\u00e1tico fue el del Impuesto a las Ganancias, que luego de la modificaci\u00f3n del m\u00ednimo no imponible, en marzo pasado, la recaudaci\u00f3n comenz\u00f3 a caer en forma estrepitosa y pas\u00f3 del 62% en enero, al 6% en octubre, registr\u00e1ndose meses de recaudaci\u00f3n negativa con respecto al a\u00f1o anterior.<\/p>\n<p>El tesorero explic\u00f3 los motivos de esta p\u00e9rdida de ingresos por los embates de la inflaci\u00f3n y la retracci\u00f3n del consumo, por falta de liquidez. \u00abLa mayor\u00eda del dinero que se emite se utiliza para comprar Lebac. Por lo tanto queda poco dinero en la calle. Esto explica la disminuci\u00f3n en las compras\u00bb.<\/p>\n<p><strong>Sin moratoria<\/strong><br \/>\nEl director de Rentas de la provincia, Ignacio Barbeira, asegur\u00f3 que no va a haber moratoria en Mendoza.<\/p>\n<p>\u00abLa Provincia ya tuvo 6 moratorias entre el 2007 y el 2015. Fuero 6 en 8 a\u00f1os. Cuando son as\u00ed de seguidas, lo \u00fanico que generan es un relajamiento en la conducta de los que pagan\u00bb, asever\u00f3 el funcionario.<\/p>\n<p>Por otra parte, explic\u00f3 que siguen sosteniendo el plan de pagos de 36 cuotas con intereses del 2% mensual sobre saldos. Pero no moratorias con condonaci\u00f3n de intereses y multas. \u00abNuestra pol\u00edtica es de antimoratorias\u00bb, subray\u00f3.<\/p>\n<h6>Fuente: Uno Mendoza<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Octubre ha sido el peor mes del a\u00f1o, con una baja que lleg\u00f3 por lo menos a 11 puntos. Lo sufrir\u00e1n las comunas. El estancamiento, la inflaci\u00f3n y la retracci\u00f3n del consumo figuran entre los principales motivos del fen\u00f3meno<\/p>\n","protected":false},"author":2,"featured_media":55569,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[31],"class_list":["post-55568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincias","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/55568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=55568"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/55568\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/55569"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=55568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=55568"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=55568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}