{"id":56488,"date":"2016-11-24T06:03:11","date_gmt":"2016-11-24T09:03:11","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=56488"},"modified":"2016-11-24T08:10:58","modified_gmt":"2016-11-24T11:10:58","slug":"mendoza-comercio-10-meses-se-perdieron-mas-370-empleos","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/mendoza-comercio-10-meses-se-perdieron-mas-370-empleos\/","title":{"rendered":"Mendoza: Comercio, en 10 meses se perdieron m\u00e1s de 370 empleos"},"content":{"rendered":"<p>La cifra se refiere s\u00f3lo a empleados registrados. Una dura consecuencia de la retracci\u00f3n del consumo.<\/p>\n<p>Seg\u00fan el Centro de Empleados de Comercio (CEC), en lo que va del a\u00f1o, 372 personas perdieron su fuente laboral en ese sector. Este n\u00famero s\u00f3lo tiene en cuenta a los empleados registrados que fueron despedidos, por lo que calculan desde el sindicato que el n\u00famero es m\u00e1s grande si se incluye a los trabajadores en negro y los que se fueron por retiros voluntarios.<\/p>\n<p>El titular del CEC, Guillermo Pereyra, explic\u00f3 que \u201centre comercio y servicio calculamos que hay 35% de empleo informal y cuando estas personas se quedan en la calle, no van al sindicato\u201d.<\/p>\n<p>Seg\u00fan los datos del gremio, en el Gran Mendoza fueron despedidas 33 personas por mes, de los cuales los m\u00e1s complicados fueron mayo y julio. Otro de los datos que se desprenden del informe del sindicato, es que de las personas que se quedaron sin empleo, casi el 50%, hab\u00edan sido contratadas entre 2015 y 2016.<\/p>\n<p>El titular del CEC, quien tambi\u00e9n se desempe\u00f1a como diputado provincial por el Frente Renovador, destac\u00f3 que, se da una situaci\u00f3n a la que menciona como \u201cdespidos encubiertos\u201d. Se trata de los retiros voluntarios.<\/p>\n<p>\u201cHay muchas de estas situaciones, de la que nos enteramos s\u00f3lo si en la empresa en la que se dio tenemos delegados que nos informen. Para nosotros estos son despidos, porque de hecho a las personas que aceptan se les paga todo como si la hubieran echado\u201d, sentenci\u00f3 el presidente del CEC.<\/p>\n<p>Otra de las situaciones que advirtieron desde el CEC, es que hay muchos micro-emprendedores que atend\u00edan sus propios negocios y que cerraron y que obviamente no estaban enmarcados en el sindicato, sino que se trataba de monotributistas, pero que tambi\u00e9n se dedicaban al sector del comercio y los servicios.<\/p>\n<p>En lo que tiene que ver con los rubros m\u00e1s afectados se menciona el de indumentaria y \u00faltimamente lo que tiene que ver con electrodom\u00e9sticos. En cuanto a los supermercados, de los 372 despidos, 13% correspond\u00eda a este tipo de comercio, aunque tambi\u00e9n este rubro es el que m\u00e1s utiliza la figura del retiro voluntario, seg\u00fan explicaron desde el CEC.<\/p>\n<p>Una de las situaciones que se vieron modificadas, seg\u00fan explic\u00f3 Pereyra, es que desde el D\u00eda de la Madre y hasta enero, por las fiestas, el sector de comercio y servicio tomaba personal part-time para hacer frente a la alta demanda, situaci\u00f3n que este a\u00f1o no s\u00f3lo no se dio sino que \u201choy cada comercio est\u00e1 atendiendo con el m\u00ednimo personal necesario para abrir sus puertas, con la esperanza de que las ventas repunten en las Fiestas de Fin de A\u00f1o\u201d.<\/p>\n<p>En cuanto al futuro, desde el sindicato se mostraron con reservas y manifestaron que la clave ser\u00e1 febrero y marzo de 2017. \u201cEl tema es: si no se reactiva el comercio entre febrero y marzo con las ventas escolares, vamos a estar en serios problemas\u201d, remarc\u00f3 el diputado massista.<\/p>\n<p>Agreg\u00f3 que \u201csi los mendocinos optan por comprar la indumentaria y \u00fatiles escolares en Chile, afectar\u00e1 mucho el comercio local y por ende el empleo. A partir de ese momento sabremos qu\u00e9 situaci\u00f3n podremos tener en 2017\u201d.<\/p>\n<p><strong>Son pocos<\/strong><\/p>\n<p>El presidente de la Federaci\u00f3n Econ\u00f3mica de Mendoza (FEM), Adolfo Tr\u00edpodi, se mostr\u00f3 en desacuerdo con los n\u00fameros entregados por el CEC y manifest\u00f3 que desde que empez\u00f3 el a\u00f1o hasta ahora en el sector de comercio y servicios no se perdieron menos de 1.300 empleos.<\/p>\n<p>Igualmente, Tr\u00edpodi aclar\u00f3 que los n\u00fameros del sindicato tienen en cuenta s\u00f3lo los empleos registrados, no as\u00ed los trabajadores que son despedidos y est\u00e9n en negro. \u201cIgualmente 372 despidos para el gran Mendoza en esos rubros creo que son pocos. En la realidad han sido muchos m\u00e1s\u201d.<\/p>\n<p>Por su parte el presidente de la C\u00e1mara Empresaria de Comercio, Industria, Turismo y Servicios de Mendoza (Cecitys), Marcelo Marra, manifest\u00f3 que \u201cse est\u00e1n dando los despidos, aunque nosotros vemos que se dan m\u00e1s en los grandes comercios y cadenas de supermercados y no tanto en el peque\u00f1o comercio\u201d.<\/p>\n<p>Agreg\u00f3 que \u201clo que vemos es que no hay nueva generaci\u00f3n de empleo. Antes exist\u00edan las figuras del franquero, los temporarios o los que se llamaban para las fechas fuertes. Pero resulta que las fechas fuertes ya no son fuertes y se termina trabajando con lo m\u00ednimo\u201d.<\/p>\n<p>A su vez el presidente de la Cecitys manifest\u00f3 que si se tiene en cuenta el empleo informal y los retiros voluntarios, podr\u00edan ser m\u00e1s los despidos.<br \/>\nPor su parte, el presidente de la Uni\u00f3n Comercial e Industrial de Mendoza (UCIM), Daniel Ariosto, sostuvo que el desempleo est\u00e1 en aumento, provocado sobre todo por una merma en el consumo, pero advirti\u00f3 que esto es una situaci\u00f3n de arrastre que viene de la gesti\u00f3n anterior.<\/p>\n<p><strong>Acuerdo para evitar despidos<\/strong><\/p>\n<p>El gobierno nacional anunci\u00f3 que se acord\u00f3 con el sector empresarial y el sindical \u201cmantener los puestos de trabajo hasta marzo de 2017\u201d, en tanto no se pronunci\u00f3 respecto al pago de un bono de fin de a\u00f1o en el sector privado.<\/p>\n<p>\u201cAcordamos mantener los puestos de trabajo hasta marzo de 2017, poniendo especial \u00e9nfasis en la creaci\u00f3n de empleo\u201d, se\u00f1al\u00f3 Triaca al participar junto al vicejefe de Gabinete, Mario Quintana, de una conferencia de prensa en Casa Rosada, sin presencia del sector empresarial ni el sindical.<\/p>\n<p>En tanto, Quintana destac\u00f3 la \u201cnecesidad de tener un debate entre todos\u201d, al referirse al proyecto de reforma de la ley del impuesto a las Ganancias.<\/p>\n<h6>Fuente: Los Andes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La cifra se refiere s\u00f3lo a empleados registrados. Una dura consecuencia de la retracci\u00f3n del consumo.<\/p>\n","protected":false},"author":2,"featured_media":56489,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[31],"class_list":["post-56488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-economico","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/56488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=56488"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/56488\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/56489"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=56488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=56488"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=56488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}