{"id":62068,"date":"2017-04-25T07:44:08","date_gmt":"2017-04-25T10:44:08","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=62068"},"modified":"2017-04-25T07:44:08","modified_gmt":"2017-04-25T10:44:08","slug":"remodelan-parque-general-san-martin-los-cortes-calles-duraran-3-4-meses","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/remodelan-parque-general-san-martin-los-cortes-calles-duraran-3-4-meses\/","title":{"rendered":"Remodelan el Parque General San Mart\u00edn y los cortes de calles durar\u00e1n entre 3 y 4 meses"},"content":{"rendered":"<p>Se har\u00e1n refacciones en todo el n\u00facleo hist\u00f3rico, con trabajos en la calzada, acequias, veredas y sendas peatonales.<\/p>\n<p>Miles de personas se re\u00fanen diariamente en el n\u00facleo hist\u00f3rico del parque General San Mart\u00edn para hacer deportes, pasear o conocer. Como su estado actual, producto de varios a\u00f1os sin refacciones, no es el mejor, empezaba este lounes una serie de obras con las que buscan dejarlo en perfectas condiciones.<\/p>\n<p>Entre tres y cuatro meses demorar\u00e1n los trabajos en calzada, veredas, sendas peatonales y acequias, y un gran recambio de luminarias, que se har\u00e1n en tres etapas para tratar de minimizar el impacto para los mendocinos y turistas que circulan por all\u00ed.<\/p>\n<p>Todos los que habitualmente visiten el sector que rodea al lago ver\u00e1n que desde este lunes el camino estar\u00e1 cerrado y habr\u00e1 m\u00e1quinas trabajando adentro. Durante aproximadamente 35 d\u00edas la situaci\u00f3n ser\u00e1 similar, por lo que tratar\u00e1n de habilitar un circuito alternativo en la zona cercana al estadio Malvinas Argentinas, sobre todo teniendo en cuenta que el pr\u00f3ximo fin de semana se jugar\u00e1 el cl\u00e1sico cuyano entre Godoy Cruz y San Mart\u00edn de San Juan en ese escenario.<\/p>\n<p>Seg\u00fan explic\u00f3 el subsecretario de Obras P\u00fablicas, Daniel Chicahuala: \u00abSe recuperar\u00e1 todo el asfalto, pero no solamente eso, lo que encontrar\u00e1 el usuario es una divisi\u00f3n de dos zonas bien marcadas: una para los que hacen deportes, para que puedan circular por ah\u00ed, y en otro color, la zona para que los automovilistas circulen\u00bb.<\/p>\n<p>Adem\u00e1s, se trabajar\u00e1 en la recuperaci\u00f3n de todas las veredas y acequias, manteniendo el concepto del empedrado y demarcando los \u00e1rboles. En las zonas donde faltan acequias, se construir\u00e1n nuevas.<\/p>\n<p>La recomendaci\u00f3n del funcionario para los deportistas y dem\u00e1s visitantes habituales del parque es: \u00abTraten de evitar las zonas donde se est\u00e1 trabajando porque habr\u00e1 mucho movimiento de maquinarias y eso siempre supone un riesgo de accidentes\u00bb.<\/p>\n<p>En cuanto al movimiento vehicular, Chicahuala dijo que se tomaron los recaudos para realizar los desv\u00edos, incluido el del transporte p\u00fablico, que se ver\u00e1 afectado algunos meses.<\/p>\n<p>Luego de terminar la primera etapa \u2013para la que se calculan unos 30 o 35 d\u00edas\u2013 se avanzar\u00e1 con las otras zonas, con la idea es atacar primero lo que m\u00e1s se usa y despu\u00e9s pasar a las grandes avenidas (ver aparte). Al final, se trabajar\u00e1 en las calles internas del parque, que tienen menor circulaci\u00f3n.<\/p>\n<p><strong>M\u00e1s y mejor iluminaci\u00f3n<\/strong><br \/>\nEn estos d\u00edas est\u00e1 finalizando el trabajo de recambio de luminarias, obra que comenz\u00f3 hace unos 45 d\u00edas y que tiene como detalle importante un contrato de mantenimiento para los pr\u00f3ximos tres a\u00f1os.<\/p>\n<p>De esta manera, se buscar\u00e1 evitar los problemas que habitualmente causan las luces cuando se van deteriorando, rompiendo o quemando.<\/p>\n<p>\u00abLo hicimos con contrato de mantenimiento de tres a\u00f1os para evitar todos esos problemas y que el parque est\u00e9 siempre iluminado. Habr\u00e1 plazos de entre 24 y 48 horas para que se pueda reparar y los mismos usuarios podr\u00e1n hacer la denuncia de las luminarias que no funcionen\u00bb, explic\u00f3 Chicahuala.<\/p>\n<p><strong>Las c\u00e1maras, en tres meses<\/strong><br \/>\nEn alrededor de un mes y medio el Ministerio de Infraestructura sacar\u00e1, en conjunto con el de Seguridad, una licitaci\u00f3n para la compra de c\u00e1maras de seguridad, que tendr\u00e1n como destino el parque General San Mart\u00edn.<\/p>\n<p>El n\u00famero de c\u00e1maras todav\u00eda no est\u00e1 definido, pero seguramente rondar\u00e1 entre las 60 o 70, dependiendo de las caracter\u00edsticas del modelo que finalmente se elija.<\/p>\n<p>\u00abHay c\u00e1maras que con una menor cantidad, ten\u00e9s una mayor cobertura, mientras que otras tienen menos rango de acci\u00f3n y requieren una mayor cantidad. Estamos terminando de evaluar la mejor alternativa\u00bb, cerr\u00f3 el funcionario.<\/p>\n<p>El objetivo es que en cuatro meses los usuarios puedan realizar sus actividades con mejores condiciones de infraestructura y seguridad.ses<\/p>\n<h6>Fuente: Uno Mendoza<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Se har\u00e1n refacciones en todo el n\u00facleo hist\u00f3rico, con trabajos en la calzada, acequias, veredas y sendas peatonales.<\/p>\n","protected":false},"author":2,"featured_media":62069,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31],"class_list":["post-62068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/62068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=62068"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/62068\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/62069"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=62068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=62068"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=62068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}