{"id":63596,"date":"2017-06-01T07:55:53","date_gmt":"2017-06-01T10:55:53","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=63596"},"modified":"2017-06-01T07:55:53","modified_gmt":"2017-06-01T10:55:53","slug":"municipalizacion-la-seguridad-vial-intendentes-mendocinos-pusieron-grito-cielo","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/municipalizacion-la-seguridad-vial-intendentes-mendocinos-pusieron-grito-cielo\/","title":{"rendered":"Municipalizaci\u00f3n de la Seguridad Vial: intendentes mendocinos pusieron el grito en el cielo"},"content":{"rendered":"<p>La iniciativa del Gobierno provincial de traspasar la Seguridad Vial a la \u00f3rbita municipal activ\u00f3 la alarma en comunas opositoras: \u00abNo nos han consultado nada. Sin recursos, no ser\u00e1 posible\u00bb, apuntaron.<\/p>\n<p>El Gobierno provincial busca descentralizar la Seguridad Vial, obligando a cada municipio a hacerse cargo de los controles y las sanciones. Ni lerdos ni perezosos, m\u00e1s de un intendente opositor sali\u00f3 al cruce de Alfredo Cornejo se\u00f1alando que, en primer lugar, no fueron consultados sobre dicha iniciativa y advirtiendo fundamentalmente que, sin los recursos correspondientes, no podr\u00e1n hacerse cargo.<\/p>\n<p>Como inform\u00f3 MDZ, el lunes ingres\u00f3 al Senado el proyecto para la derogaci\u00f3n parcial y reforma de la ley 6.082. El esp\u00edritu de la misma es municipalizar definitivamente los controles y las sanciones viales (actualmente es optativo que cada comuna se haga cargo de esto). Bajo este panorama, la nueva ley establece un plazo m\u00e1ximo de 9 meses para que todos los departamentos pongan en funcionamiento su polic\u00eda vial y los juzgados de tr\u00e1nsito correspondientes. Bajo los argumentos de ofrecer una respuesta efectiva y r\u00e1pida y de desafectar al personal policial que, en la actualidad, debe intervenir en cada siniestro vial; el Gobierno pretende tambi\u00e9n que las comunas se encarguen de los peritajes de todos los accidentes de tr\u00e1nsito, excepto aquellos en los que se registren muertos.<\/p>\n<p>Si bien el proyecto a\u00fan debe pasar el filtro de la Legislatura -ser\u00e1 analizado en la comisi\u00f3n de Legislaci\u00f3n y Asuntos Constitucionales y podr\u00eda tratarse la semana pr\u00f3xima-, m\u00e1s de un intendente sali\u00f3 a poner sus reparos a la iniciativa de Cornejo. El principal contra-argumento es que sin la reasignaci\u00f3n presupuestaria correspondiente no podr\u00e1n hacerse cargo de la Seguridad Vial.<\/p>\n<p>\u00abTodo va a depender de la asignaci\u00f3n presupuestaria. Si yo no tengo presupuesto para aplicarlo, podr\u00e1 ser muy obligatorio pero&#8230; hay que ver c\u00f3mo va a hacer la provincia para transferir los recursos correspondientes. Si la provincia reasigna parte de su presupuesto a los municipios, nosotros veremos la aplicaci\u00f3n porque dentro de nuestro presupuesto no est\u00e1 sometido esto, lo que tenemos que tener es una partida extrapresupuestaria para ejecutar eso. Si el Gobierno provincial no la manda por supuesto que no lo vamos a ejecutar\u00bb, apunt\u00f3 el intendente de San Rafael, Emir F\u00e9lix (PJ), en donde actualmente la Seguridad Vial depende exclusivamente de la provincia. \u00abTransferir las responsabilidades a los municipios sin los recursos es una falta&#8230; la decisi\u00f3n pol\u00edtica est\u00e1 cuando se transfieren las partidas&#8230; sino, no hay nada\u00bb, remat\u00f3.<\/p>\n<p>En el mismo sentido se expres\u00f3 el intendente de Lavalle, Roberto Righi (PJ), que adem\u00e1s asegur\u00f3 que el proyecto no ha sido consensuado con las comunas. \u00abNo nos han consultado ni nada, me he enterado por el diario. Los municipios, como los nuestros, no tenemos la estructura ni los fondos necesarios para poder crear la polic\u00eda vial. Por eso, hay que ver en qu\u00e9 condiciones se da esta idea para poder recibir una responsabilidad de tal magnitud. No es lo mismo Guaymall\u00e9n o Capital que Lavalle en donde no ten\u00e9s los recursos\u00bb, dispar\u00f3.<\/p>\n<p>El intendente de San Mart\u00edn, Jorge Omar Gim\u00e9nez (PJ), tambi\u00e9n hizo hincapi\u00e9 en la necesidad de recursos para hacer efectiva la municipalizaci\u00f3n de la Seguridad Vial: \u00abTodo lo que signifique dar un mejor servicio y m\u00e1s r\u00e1pido a la gente est\u00e1 bueno pero eso tiene que estar acompa\u00f1ado de recursos que se necesitan\u00bb, subray\u00f3, al tiempo que coment\u00f3 que, actualmente, cuentan con una estructura peque\u00f1a de agentes viales y juzgados que se sostiene con el \u00abesfuerzo municipal\u00bb. \u00abSi no hay recursos pasa como en la fiesta de la Vendimia, que la pagamos todos los municipios y los r\u00e9ditos quedan en Capital y en la provincia\u00bb, asever\u00f3 Gim\u00e9nez.<\/p>\n<p>Por el lado del oficialismo, el intendente de Capital, Rodolfo Su\u00e1rez (UCR), defendi\u00f3 y celebr\u00f3 el proyecto de Cornejo y asegur\u00f3 que no s\u00f3lo permitir\u00e1 actuar con celeridad y efectividad frente a los siniestros viales sino que tambi\u00e9n se podr\u00e1 tener un mayor control sobre la escena del accidente sin tener que afectar personal de la polic\u00eda provincial. \u00abEn el caso nuestro, tenemos un promedio de 17 a 18 accidentes por d\u00eda, de los cuales 7 a 8 son con lesionados. Con la Ley vigente no podemos intervenir, con lo cual tenemos que llamar a la polic\u00eda y esperar para poder mover los veh\u00edculos lo que termina dificultando el tr\u00e1nsito, entre otros problemas. Con la reforma actual, podremos intervenir, salvo que haya un muerto, lo que nos permitir\u00e1 responder m\u00e1s r\u00e1pido. Asimismo, no se afectar\u00e1 personal policial de la provincia en controles de tr\u00e1nsito. No pod\u00e9s tener una polic\u00eda afectada a tareas de tr\u00e1nsito\u00bb, adujo.<\/p>\n<p>Argument\u00f3 adem\u00e1s que favorecer\u00e1 a los controles y al pago de multas correspondientes. \u00abCon la norma vigente, al no poder intervenir cuando hay lesionados, el que hab\u00eda cometido una infracci\u00f3n en un siniestro determinado, como haber pasado un sem\u00e1foro en rojo por ejemplo, presentaba un certificado por lesiones y as\u00ed pretend\u00eda evitar la multa. Esto se terminar\u00eda con el nuevo proyecto de Ley\u00bb, fundament\u00f3 y cerr\u00f3 en que los municipios no tendr\u00e1n inconvenientes al momento de contar con recursos para hacerse cargo de la Seguridad Vial porque \u00ablo que, hasta este momento, recaudaba la Polic\u00eda, lo pasar\u00e1 a recaudar cada municipio\u00bb.<\/p>\n<h6>Fuente: MDZ Online<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La iniciativa del Gobierno provincial de traspasar la Seguridad Vial a la \u00f3rbita municipal activ\u00f3 la alarma en comunas opositoras: \u00abNo nos han consultado nada. Sin recursos, no ser\u00e1 posible\u00bb, apuntaron.<\/p>\n","protected":false},"author":2,"featured_media":63597,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[31],"class_list":["post-63596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-politico","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/63596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=63596"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/63596\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/63597"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=63596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=63596"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=63596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}