{"id":65774,"date":"2017-07-25T05:43:51","date_gmt":"2017-07-25T08:43:51","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=65774"},"modified":"2017-07-25T07:55:55","modified_gmt":"2017-07-25T10:55:55","slug":"mendoza-informalidad-los-centros-esqui-la-lupa","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/mendoza-informalidad-los-centros-esqui-la-lupa\/","title":{"rendered":"Mendoza: Informalidad en los centros de esqu\u00ed, bajo la lupa"},"content":{"rendered":"<p>Un operativo en bares y otros locales detect\u00f3 120 trabajadores en negro, 15% del total. Falta de aportes y registro horario. M\u00e1s controles.<\/p>\n<p>A contramano de lo que muestra la actualidad del mercado laboral, los centros tur\u00edsticos est\u00e1n a pleno y por ende con m\u00e1s empleados. A\u00fan as\u00ed, en Mendoza la informalidad persiste y muchas empresas, entre hoteles y gastronom\u00eda, deben aportes patronales.<\/p>\n<p>Es lo que se desprende de un operativo conjunto realizado por la Subsecretar\u00eda de Trabajo y Uthgra (Uni\u00f3n de Trabajadores Hoteleros y Gastron\u00f3micos) Seccional Mendoza a uno de los principales complejos invernales de esqu\u00ed como es Las Le\u00f1as.<\/p>\n<p>De 26 firmas (hoteles, bares, restaurantes y operadores tur\u00edsticos) y 818 trabajadores relevados surgi\u00f3 un dato: 15% de ellos est\u00e1 en negro. Dentro de 50 actas de infracci\u00f3n labradas, resulta la principal infracci\u00f3n.<\/p>\n<p>De acuerdo al director de Inspecciones de Trabajo, Rodrigo Herrera, las hubo por faltas de seguridad e higiene, \u00a0por \u201cno acreditarse el uso del sistema de control horario\u201d acorde a resoluci\u00f3n del 2006, y \u201cobstruir la labor de la repartici\u00f3n\u201d.<\/p>\n<p>Respecto a la falta de control de carga laboral, el porcentaje irregular es a\u00fan mayor: el operativo marc\u00f3 que \u00a0la mitad de las firmas fiscalizadas no tienen planilla ni reloj par marcar entrada y\/o salida.<\/p>\n<p>\u201cHay un n\u00facleo duro que cree que evadi\u00e9ndo la ley evitan costo de despidos y licencias, y se controla con m\u00e1s inspecciones. Si bien es cierto que bajar\u00e1 en la medida que crezcan \u00a0oportunidades de trabajo, la situaci\u00f3n econ\u00f3mica no es causa excluyente\u201d, analiz\u00f3 el subsecretario, Alejandro Jofr\u00e9.<\/p>\n<p>Aunque las empresas tienen 15 d\u00edas para presentar documentaci\u00f3n en su descargo, se enfrentan a un sumario administrativo y en definitiva multas. La cuenta es multiplicar el n\u00famero de trabajadores afectados por el salario promedio, que va de $12.179 a $19.133 de acuerdo a la escala de 7 categor\u00edas de convenio para personal gastron\u00f3mico y de hoteles.<\/p>\n<p>Jofr\u00e9 anticip\u00f3 que la avanzada fiscalizadora en los centros tur\u00edsticos seguir\u00e1. \u201cSe trata de medidas disuasivas seg\u00fan una agenda estacional. Con bares, restaurantes y hoteles lo hacemos todo el a\u00f1o\u201d.<\/p>\n<p>El r\u00e1nking de irregularidades muestra que las condiciones irregulares de contrataci\u00f3n,\u00a0seguida por atrasos en transferencia de retenciones son las m\u00e1s detectadas.<\/p>\n<p>Seg\u00fan Dante D&#8217;Ambola, responsable de Recaudaci\u00f3n de Uthgra, \u201cla mora en el dep\u00f3sito de retenciones, las jornadas laborales y el pago a la obra social son las m\u00e1s frecuentes, en una temporada en donde hay mucha m\u00e1s gente trabajando que la anterior\u201d.<\/p>\n<p>En tal sentido, entre las pr\u00e1cticas en la mira de los inspectores est\u00e1n las liquidaciones inferiores a la carga laboral. \u201cAl parecer, los contadores se \u201colvidan\u201d que los empleados trabajan muchas m\u00e1s horas y liquidan s\u00f3lo por media jornada, y eso impacta en la cobertura social\u201d, \u00a0ironiza por su parte Carolina Montivero, del \u00e1rea de Asuntos Gremiales.<\/p>\n<p>Desde Uthgra reafirman que los atrasos en la liquidaci\u00f3n de retenciones (el mentado Formulario 931 de Afip, que implica entre 2 y 2,5% del salario) y aportes por ley a obras sociales (11%) es lo m\u00e1s com\u00fan, con matices. Al respecto, D&#8217;Ambola, que tambi\u00e9n particip\u00f3 de 19 inspecciones en Uspallata, sobre todo \u00a0locales de comidas, precis\u00f3 que \u201cas\u00ed como \u00a0en el caso de la retenci\u00f3n de contribuciones es m\u00e1s notable la cantidad de empleados afectados, la mora resulta mayor en fondos para la obra social\u201d. Aunque supo llegar a 6 a\u00f1os, actualmente la mora promedio en hoteler\u00eda y gastronom\u00eda promedia 2 a\u00f1os. El objetivo es llegar a 6 meses como lo \u201cnormal\u201d.<\/p>\n<p>Con hoteles 5 estrellas y hostels como polos opuestos de cumplimiento, el resto del universo es dispar conforme crece la dispersi\u00f3n. \u201cEl del hostel es el rubro m\u00e1s irregular\u201d, asevera Jofr\u00e9, \u201cporque contratan a estudiantes de intercambio alojados que as\u00ed se costean la estad\u00eda en la provincia\u201d. En Mendoza, Uthgra maneja un amplio universo de convenios que exceden a la hoteler\u00eda, restaurantes tradicionales y bares, e incluye tambi\u00e9n a sandwicher\u00edas, hoteles alojamiento y comedores. Estos \u00faltimos \u201centre los que funcionan en las universidades y hospitales, los que funcionan de manera m\u00e1s informal\u201d, puntualiz\u00f3 D&#8217;Ambola.<\/p>\n<h6>Fuente: Los Andes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Un operativo en bares y otros locales detect\u00f3 120 trabajadores en negro, 15% del total. Falta de aportes y registro horario. M\u00e1s controles.<\/p>\n","protected":false},"author":2,"featured_media":65775,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[31],"class_list":["post-65774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-economico","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/65774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=65774"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/65774\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/65775"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=65774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=65774"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=65774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}