{"id":66521,"date":"2017-08-10T08:43:41","date_gmt":"2017-08-10T11:43:41","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=66521"},"modified":"2017-08-10T08:43:41","modified_gmt":"2017-08-10T11:43:41","slug":"malargue-impactante-donde-se-lo-mire","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/malargue-impactante-donde-se-lo-mire\/","title":{"rendered":"Malarg\u00fce: Impactante por donde se lo mire."},"content":{"rendered":"<p>\u00bfBusc\u00e1s un destino con variedad de actividades? En Malarg\u00fce encontrar\u00e1s aventura, naturaleza, pesca, termalismo, turismo cient\u00edfico y cultura.<\/p>\n<p>&nbsp;<\/p>\n<p>Uno de los lugares m\u00e1s limpios para observaci\u00f3n de cielo, una joya paleontol\u00f3gica, un libro abierto para quien le gusta la geograf\u00eda y la geolog\u00eda. Ubicado a 420 kil\u00f3metros al sur de la Ciudad de Mendoza se encuentra Malarg\u00fce, un destino que no podes dejar de visitar. Su nombre proviene del\u00a0mapudungun\u00a0\u00abMalal Hue\u00bb, que significa\u00a0corral de piedra\u00a0o\u00a0zona de corrales\u00a0haciendo referencia a las formaciones monta\u00f1osas. Sobre la marcha en la ruta 40, vemos a nuestro alrededor una vasta extensi\u00f3n de tierra que sorprendentemente una vez fue oc\u00e9ano.<\/p>\n<p>AVENTURA: TURCAR\u00c1<\/p>\n<p>Turcar\u00e1 es una empresa familiar con un proyecto tur\u00edstico integral. Para su desarrollo cuenta con un predio de casi treinta hect\u00e1reas ubicado a 35 km. de la ciudad de Malarg\u00fce sobre la ruta 40 en direcci\u00f3n sur. Con un acceso inmejorable en el coraz\u00f3n de la Cuesta del Chiuhido, Turcar\u00e1 se convierte en una parada obligatoria entre los atractivos m\u00e1s reconocidos del departamento mendocino. El predio cuenta con una gran oferta de actividades diferentes para pasar un d\u00eda inolvidable rodeado de un paisaje excepcional.<\/p>\n<p>El parque est\u00e1 separado en dos partes. La primera consta de un circuito donde hay un sendero bien demarcado para que la gente recorra la quebrada sin alterar la flora y fauna del lugar. La idea es que los turistas recorran el lugar de manera libre gui\u00e1ndose por carteles que acompa\u00f1an el camino. En medio de la caminata se encontrar\u00e1n con cascadas, vertientes y flora aut\u00f3ctona. Un hermoso paseo que culmina en un ca\u00f1ad\u00f3n donde nace la quebrada.<\/p>\n<p>La segunda parte se desarrolla en un circuito de aventura donde hay variados juegos de altura, como el puente tibetano, un puente comando, un puente del abismo y dos tirolesas extremadamente vertiginosas. Siempre acompa\u00f1ados por un gu\u00eda, el juego comienza con una charla de seguridad personal e informaci\u00f3n necesaria sobre la flora y paleontolog\u00eda del lugar.<\/p>\n<p>Info.\u00a0Turcar\u00e1:\u00a0ruta 40 km.2911 &#8211; Cuesta del Chihuido- Malarg\u00fce. Valor al camping: Mayores $90. Menores de 12 a\u00f1os $ 50. Ingreso gratuito para personas con discapacidad y h\u00e9roes de Malvinas. Valor circuito de aventuras completo m\u00e1s servicios de la entrada general. Precio p\/persona: $ 400. (+054) 0260 15-453-5908 &#8211; (+054) 011 49145237www.turcara.com\u00a0Facebook: Turcara Aventuras<\/p>\n<p>NATURALEZA: MANQUI MALAL<\/p>\n<p>En lengua mapuche Manqui (c\u00f3ndor) y Malal (barda). Manqui Malal es un \u00e1rea natural protegida que cuenta con dos peque\u00f1as cascadas de 30 metro de altura. Se puede acceder a ellas realizando un recorrido paleontol\u00f3gico por un antiguo lecho marino, donde se han encontrado f\u00f3siles de millones de a\u00f1os de antig\u00fcedad y que son visibles hoy por efecto de la orogenia andina. \u00abEs como caminar por el fondo del mar\u00bb dice Rosario, propietaria y una de las gu\u00edas del lugar. \u00danicamente se permite el ingreso con la compa\u00f1\u00eda de un gu\u00eda que brinda toda la informaci\u00f3n sobre este maravilloso lugar y responder\u00e1 las inquietudes.<\/p>\n<p>El lugar cuenta con un comedor para aquellos que deseen deleitarse con exquisitos platos de monta\u00f1a. Antes de la caminata, los visitantes pueden elegir el men\u00fa y una vez que llegan del recorrido, la mesa estar\u00e1 lista. Todo lo que se ofrece se elabora de forma casera, con productos cuidadosamente seleccionados y preparados en el momento, con agua pura de vertiente y horno a le\u00f1a. Algunos de los platos estrella son trucha al roquefort, chivo al malbec, chivo al disco, locro y pizzas caseras.<\/p>\n<p>Info:\u00a0Valor trekking guiado: $120 mayores, $80 menores. Contacto: 0260 405-1538. Facebook: Manqui Malal<\/p>\n<p>VALLE DE LOS MOLLES<\/p>\n<p>Tranquilidad y comodidad son palabras que definen a este sitio ubicado a tan solo 15km de Las Le\u00f1as. El Valle de Los Molles es una excelente opci\u00f3n para aquellos que quieren aminorar gastos y no alojarse en el Valle de Las Le\u00f1as, pudiendo disfrutar de la serenidad del lugar y eliminar el estr\u00e9s que a veces provocan las actividades de monta\u00f1a. Aqu\u00ed pod\u00e9s disfrutar del cielo limpio y la falta de comunicaci\u00f3n debido a que no hay se\u00f1al de ning\u00fan tipo, una caracter\u00edstica necesaria que buscan algunos turistas para desconectarse y conocer los placeres del valle como las aguas termales de cualidades terap\u00e9uticas del Hotel Lahuen-c\u00f3, que significa \u00abaguas milagrosas\u00bb en mapuche. Un sitio verdaderamente acogedor con capacidad para s\u00f3lo 60 personas.<\/p>\n<p>Su gran atractivo es que cuenta con piletas termales que rondan de los 37\u00b0C a 43\u00b0C. Dichas piscinas son naturales y altamente terap\u00e9uticas gracias a los minerales presentes en el agua como hierro, azufre y potasio. Receso ideal para aquellos que tienen afecciones de tipo, \u00f3sea, d\u00e9rmica o problemas respiratorios. Un lugar que es un mimo al cuerpo aportando nutrientes que descontracturan y relajan. Si te hosped\u00e1s en el hotel, la tarifa incluye dos ba\u00f1os termales, uno en la ma\u00f1ana y otro en la tarde.<\/p>\n<p>El valor para una persona que desea visitarlo es de $75 con toall\u00f3n disponible. El tiempo inmersi\u00f3n en las piletas no puede superar los diez minutos. Luego pod\u00e9s disfrutar de otros diez minutos de relax en unas camillas con frazadas para terminar la visita de la manera m\u00e1s reconfortante.<\/p>\n<h6>Fuente: MDZ Online<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfBusc\u00e1s un destino con variedad de actividades? En Malarg\u00fce encontrar\u00e1s aventura, naturaleza, pesca, termalismo, turismo cient\u00edfico y cultura.<\/p>\n","protected":false},"author":2,"featured_media":66522,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87],"tags":[31],"class_list":["post-66521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turismo","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/66521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=66521"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/66521\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/66522"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=66521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=66521"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=66521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}