{"id":66596,"date":"2017-08-15T08:13:02","date_gmt":"2017-08-15T11:13:02","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=66596"},"modified":"2017-08-15T08:13:02","modified_gmt":"2017-08-15T11:13:02","slug":"buscan-integrar-las-ciclovias-los-departamentos-del-gran-mendoza","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/buscan-integrar-las-ciclovias-los-departamentos-del-gran-mendoza\/","title":{"rendered":"Buscan integrar las ciclov\u00edas de los departamentos del Gran Mendoza"},"content":{"rendered":"<p>Se trata de una iniciativa de las secretar\u00edas de Ambiente y Ordenamiento Territorial, a trav\u00e9s de Unicipio y de la Secretar\u00eda de Servicios P\u00fablicos, con financiaci\u00f3n del Banco Interamericano de Desarrollo.<\/p>\n<p>Con el fin de delinear una Red de Ciclov\u00edas Metropolitana, la Secretar\u00eda de Ambiente y Ordenamiento Territorial (SAyOT) de\u00a0Mendoza\u00a0\u2013a trav\u00e9s de Unicipio\u2013 junto a la Secretar\u00eda de Servicios P\u00fablicos, trabajan en un proyecto que ser\u00e1 financiado por el Banco Interamericano de Desarrollo (BID), en el marco del Programa de Desarrollo de \u00c1reas Metropolitanas del Interior (DAMI II).<\/p>\n<p>El proyecto de la Red Cicloviaria ser\u00e1 coordinado por un consultor experto en planificaci\u00f3n y movilidad \u2013con trabajos similares en otras provincias\u2013 de forma transversal con los secretarios de obras p\u00fablicas y los referentes de movilidad de cada municipio, en articulaci\u00f3n con la SAyOT y la Secretar\u00eda de Servicios P\u00fablicos.<\/p>\n<p>\u00abEste es uno de los varios proyectos que tenemos previstos en la Secretar\u00eda de Ambiente para Unicipio. Con este en particular, buscamos superar el uso recreativo de las bicisendas y que apunte a generar un opci\u00f3n efectiva para mejorar la movilidad de la poblaci\u00f3n en toda el \u00c1rea Metropolitana\u00bb, explic\u00f3 el secretario de Ambiente y Ordenamiento Territorial, Humberto Mingorance.<\/p>\n<p>El proyecto partir\u00e1 de un diagn\u00f3stico del desarrollo de bicisendas en cada departamento miembro de Unicipio, para luego delinear de forma conjunta una Red de Ciclov\u00edas Metropolitana.<\/p>\n<h6>Fuente: Uno Mendoza<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de una iniciativa de las secretar\u00edas de Ambiente y Ordenamiento Territorial, a trav\u00e9s de Unicipio y de la Secretar\u00eda de Servicios P\u00fablicos, con financiaci\u00f3n del Banco Interamericano de Desarrollo.<\/p>\n","protected":false},"author":2,"featured_media":66597,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31],"class_list":["post-66596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/66596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=66596"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/66596\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/66597"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=66596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=66596"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=66596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}