{"id":67670,"date":"2017-09-18T08:06:55","date_gmt":"2017-09-18T11:06:55","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=67670"},"modified":"2017-09-18T08:06:55","modified_gmt":"2017-09-18T11:06:55","slug":"espana-secuestra-material-electoral-cataluna","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/espana-secuestra-material-electoral-cataluna\/","title":{"rendered":"Espa\u00f1a secuestra material electoral en Catalu\u00f1a"},"content":{"rendered":"<p>La Guardia civil incaut\u00f3 ayer cerca de Barcelona 1,3 millones de volantes, folletos y afiches para el refer\u00e9ndum sobre la independencia de Catalu\u00f1a prohibido por la Justicia espa\u00f1ola, anunci\u00f3 el Ministerio del Interior.<\/p>\n<p>La Guardia civil incaut\u00f3 ayer cerca de Barcelona 1,3 millones de volantes, folletos y afiches para el refer\u00e9ndum sobre la independencia de Catalu\u00f1a prohibido por la Justicia espa\u00f1ola, anunci\u00f3 el Ministerio del Interior.<\/p>\n<p>Los documentos fueron decomisados en una empresa de distribuci\u00f3n publicitaria de una comuna de la provincia de Barcelona. \u00abLos materiales estaban empaquetados en pal\u00e9s, listos para su distribuci\u00f3n\u00bb, seg\u00fan el comunicado del ministerio.<\/p>\n<p>El descubrimiento ocurri\u00f3 en Montcada i Reixac, a diez kil\u00f3metros de Barcelona. Entre los documentos hab\u00eda unos 700.000 volantes que promueven el \u00abs\u00ed\u00bb en el refer\u00e9ndum, y unos 370.000 folletos con el logo del gobierno catal\u00e1n para promover el ref\u00e9r\u00e9ndum.<\/p>\n<p>Tambi\u00e9n fueron decomisados unos 138.000 afiches de la CUP, partido separatista de extrema izquierda que apoya la consulta.<\/p>\n<p>Seg\u00fan el Ministerio del Interior, el decomiso de material para promocionar el \u00abs\u00ed\u00bb al mismo tiempo que documentos oficiales del gobierno catal\u00e1n, prueban la \u00abunidad de acci\u00f3n\u00bb entre el gobierno regional y la campa\u00f1a por la afirmativa.<\/p>\n<p>El gobierno separatista de Catalu\u00f1a de Carles Puigdemont est\u00e1 determinado a organizar el 1\u00ba de octubre el refer\u00e9ndum para la autodeterminaci\u00f3n, que implica de facto su separaci\u00f3n de Espa\u00f1a. Por esto fue prohibido por el Tribunal Constitucional espa\u00f1ol y recibe la negativa absoluta del gobierno.<\/p>\n<p>Las instituciones espa\u00f1olas han aumentado las acciones para impedir la realizaci\u00f3n del refer\u00e9ndum: allanamiento de imprentas y lugares que puedan suministrar material electoral y amenazas de la fiscal\u00eda contra alcaldes dispuestos a permitir la celebraci\u00f3n de la votaci\u00f3n, entre otras medidas.<\/p>\n<p>Catalu\u00f1a est\u00e1 dividida sobre la independencia: en las elecciones de septiembre de 2015, los separatistas tuvieron 47,8 por ciento de votos y los no independentistas, 51,7 por ciento.<\/p>\n<h6>Fuente: La Capital Rosario<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La Guardia civil incaut\u00f3 ayer cerca de Barcelona 1,3 millones de volantes, folletos y afiches para el refer\u00e9ndum sobre la independencia de Catalu\u00f1a prohibido por la Justicia espa\u00f1ola, anunci\u00f3 el Ministerio del Interior.<\/p>\n","protected":false},"author":2,"featured_media":67671,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[57],"class_list":["post-67670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-mundo","tag-el-mundo"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/67670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=67670"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/67670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/67671"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=67670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=67670"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=67670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}