{"id":67759,"date":"2017-09-19T05:37:18","date_gmt":"2017-09-19T08:37:18","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=67759"},"modified":"2017-09-19T08:42:23","modified_gmt":"2017-09-19T11:42:23","slug":"partido-lopez-obrador-lidera-sondeo-eleccion-presidencial-mexico-2018","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/partido-lopez-obrador-lidera-sondeo-eleccion-presidencial-mexico-2018\/","title":{"rendered":"Partido de L\u00f3pez Obrador lidera sondeo para elecci\u00f3n presidencial M\u00e9xico 2018"},"content":{"rendered":"<p>El partido del veterano l\u00edder progresista Andr\u00e9s Manuel L\u00f3pez Obrador encabeza la intenci\u00f3n de voto rumbo a las elecciones presidenciales del pr\u00f3ximo a\u00f1o en M\u00e9xico, seg\u00fan una encuesta publicada ayer.<\/p>\n<p>MORENA, fundado en 2014 por el combativo pol\u00edtico de 63 a\u00f1os que buscar\u00e1 la presidencia por tercera vez, obtuvo un 23.3 por ciento de la intenci\u00f3n de voto, seguido por el derechista Partido Acci\u00f3n Nacional (PAN) con un 20 por ciento, seg\u00fan el sondeo del diario El Universal.<\/p>\n<p>El gobernante centrista Partido Revolucionario Institucional (PRI) tuvo un 16.5 por ciento de las menciones. Un 16.4 por ciento de los consultados no declar\u00f3 preferencias y un 9.8 por ciento dijo que no votar\u00eda en los comicios de julio de 2018.<\/p>\n<p>En varios escenarios simulados con potenciales contendientes, L\u00f3pez Obrador lider\u00f3 las preferencias de los encuestados.<\/p>\n<p>Un 31.6 por ciento de los encuestados dijo conocer la reci\u00e9n formada alianza del PAN y los izquierdistas Partido de la Revoluci\u00f3n Democr\u00e1tica (PRD) y Movimiento Ciudadano, a trav\u00e9s de la cual competir\u00e1n en las presidenciales. De ellos, un 46 por ciento consider\u00f3 que dicho frente derrotar\u00eda a MORENA.<\/p>\n<p>El sondeo fue realizado a nivel nacional del 18 de agosto al 3 de septiembre a 6,400 personas en viviendas, con un margen de error del +\/- 3.3 por ciento.<\/p>\n<h6>Fuente: Tucum\u00e1n Hoy<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El partido del veterano l\u00edder progresista Andr\u00e9s Manuel L\u00f3pez Obrador encabeza la intenci\u00f3n de voto rumbo a las elecciones presidenciales del pr\u00f3ximo a\u00f1o en M\u00e9xico, seg\u00fan una encuesta publicada ayer.<\/p>\n","protected":false},"author":2,"featured_media":67760,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[57],"class_list":["post-67759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-mundo","tag-el-mundo"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/67759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=67759"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/67759\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/67760"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=67759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=67759"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=67759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}