{"id":67923,"date":"2017-09-25T06:46:19","date_gmt":"2017-09-25T09:46:19","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=67923"},"modified":"2017-09-25T06:46:19","modified_gmt":"2017-09-25T09:46:19","slug":"merkel-gano-la-sorpresa-la-dio-la-ultraderecha","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/merkel-gano-la-sorpresa-la-dio-la-ultraderecha\/","title":{"rendered":"Merkel gan\u00f3, pero la sorpresa la dio la ultraderecha"},"content":{"rendered":"<p>La canciller alemana se impuso con menos votos, los socialdem\u00f3cratas quedaron en segundo lugar y los ultras como tercera fuerza.<\/p>\n<p>Mientras miles de atletas corr\u00edan la 43\u00aa edici\u00f3n de la Marat\u00f3n de Berl\u00edn a pesar de la llovizna y el fr\u00edo que marcan el fin del verano berlin\u00e9s, otros tantos millones de alemanes que viven en la capital germana no se olvidaron de su compromiso democr\u00e1tico y fueron a votar definiendo as\u00ed el parlamento que regir\u00e1 durante el pr\u00f3ximo per\u00edodo de 2017 a 2021. Los n\u00fameros, aunque provisorios, sorprendieron a todos: por primera vez desde la derrota del nazismo la ultraderecha ingresa al parlamento con un sorprendente 13%, rest\u00e1ndole votos al partido de \u00c1ngela Merkel (CDU) que lleg\u00f3 a una victoria eclipsada del 32,9. Los socialdem\u00f3cratas tambi\u00e9n bajaron quedando en un segundo lugar con el 20% y los liberales (FDP) en el cuarto con el 10,6. El \u00fanico porcentaje que se mantuvo similar desde las \u00faltimas elecciones parlamentarias en el 2013 fue el de abstenci\u00f3n al voto (un 30% de la poblaci\u00f3n no se acerc\u00f3 a votar).<\/p>\n<p>Pasadas las medianoche, con casi el 50% de los votos escrutados, el partido cristianodem\u00f3crata (CDU) logr\u00f3 un resultado menor al que anticipaban las encuestadoras y casi diez puntos por debajo del porcentaje obtenido en las \u00faltimas elecciones de 2013. Con el 20% el partido socialdem\u00f3crata (SPD), al mando de Martin Schulz, consistentemente con los pron\u00f3sticos qued\u00f3 en segundo lugar pero tambi\u00e9n con menos puntajes que la elecci\u00f3n anterior. El tercer puesto, codiciado por todo el resto, lo obtuvo el partido populista de ultraderecha Alternativa para Alemania (AfD) con un hist\u00f3rico 13%. Los liberales entraron cuartos con un poco m\u00e1s del 10%, la izquierda y el partido Verde se ubicaron en el quinto y sexto lugar con un 9% y 9,1% respectivamente. El parlamento alem\u00e1n tendr\u00e1 que enfrentarse a un colorido panorama, pues ninguna fuerza se qued\u00f3 afuera y la CDU tendr\u00e1 que lograr, en los pr\u00f3ximos 30 d\u00edas, una coalici\u00f3n que represente m\u00e1s del 50% de los votos para formar un gobierno.<\/p>\n<p>Luego de 12 a\u00f1os en el poder, \u00c1ngela Merkel seguir\u00e1 siendo la canciller y cabeza pol\u00edtica de Alemania, pero sabe que los a\u00f1os que vienen no ser\u00e1n iguales a los pasados. En la sede de su partido federal (Bundesparteizentrale), la reelecta canciller recalc\u00f3 enfrente de los integrantes de su partido la responsabilidad de haber estado en el gobierno ininterrumpidamente durante tantos a\u00f1os y reconoci\u00f3 la actual situaci\u00f3n: \u201ctenemos por delante un gran desaf\u00edo: la AfD ha entrado en el parlamento alem\u00e1n y debemos recuperar a quienes votaron esa fuerza para continuar siendo un pa\u00eds justo y social. Esta tarea nos pide que mantengamos la uni\u00f3n y trabajemos para tener una Europa fuerte. Para lograrlo, debemos combatir la inmigraci\u00f3n ilegal, pero tambi\u00e9n las razones por las cuales est\u00e1 inmigraci\u00f3n es creada en los pa\u00edses de donde provienen los inmigrantes. Debemos encontrar formas legales de ayudar y acoger a los refugiados para garantizar la seguridad y vivir en un pa\u00eds pr\u00f3spero y libre\u201d.<\/p>\n<p>A pesar de la victoria, nadie celebraba y la mandataria alemana sabe que el desaf\u00edo de formar una coalici\u00f3n que eclipse el triunfo de la ultraderecha es fundamental. La estrategia favorita es la llamada \u201ccoalici\u00f3n Jamaica\u201d, debido a los colores representativos de los partidos: negro (CDU), amarillo (FDP) y verde (Alianza 90\/Los Verdes). Si se logran poner de acuerdo y formar un gobierno entre ellos, el SPD quedar\u00e1 como primera fuerza opositora dentro del parlamento.<\/p>\n<p>Sin embargo, si se mantuviese la coalici\u00f3n actual de los dos partidos con mayor porcentaje \u201cNegro (CDU)\/Rojo (SPD)\u201d, significar\u00e1 darle a la extrema derecha el privilegio de ser la primera fuerza opositora. Christian Lindner, cabeza del partido liberal sabe que esto no es bueno: \u201c\u00bfUn porcentaje m\u00e1s o menos para la Uni\u00f3n (CDU)? Eso no hace ninguna diferencia. Pero un punto porcentual m\u00e1s en la lucha por el tercer lugar entre el AfD y el FDP, \u00a1lo cambia todo!\u201d A pesar de los desconcertantes resultados electorales todav\u00eda queda un mes de negociaciones que ser\u00e1n fundamentales.<\/p>\n<h6>Fuetne: P\u00e1gina 12<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La canciller alemana se impuso con menos votos, los socialdem\u00f3cratas quedaron en segundo lugar y los ultras como tercera fuerza.<\/p>\n","protected":false},"author":2,"featured_media":67924,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[57],"class_list":["post-67923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-mundo","tag-el-mundo"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/67923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=67923"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/67923\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/67924"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=67923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=67923"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=67923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}