{"id":71086,"date":"2017-12-20T06:09:41","date_gmt":"2017-12-20T09:09:41","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=71086"},"modified":"2017-12-20T08:11:24","modified_gmt":"2017-12-20T11:11:24","slug":"guaymallen-prohibio-las-domas-jineteadas-sancionara-las-carreras-galgos","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/guaymallen-prohibio-las-domas-jineteadas-sancionara-las-carreras-galgos\/","title":{"rendered":"Guaymall\u00e9n prohibi\u00f3 las domas y jineteadas y sancionar\u00e1 las carreras de galgos"},"content":{"rendered":"<p>La comuna aprob\u00f3 una ordenanza que protege la integridad de los animales y la aplicaci\u00f3n de multas que llegan hasta los $18.000.<\/p>\n<p>A trav\u00e9s de una ordenanza municipal,\u00a0el Concejo Deliberante de\u00a0Guaymall\u00e9n prohibi\u00f3 la realizaci\u00f3n de domas y jineteadas, debido a los maltratos que reciben los animales en este tipo de actividades. Las multas llegar\u00e1n hasta los\u00a018.000 pesos.<\/p>\n<p>El concejal\u00a0Ignacio Conte\u00a0(UCR) cont\u00f3 a\u00a0Los Andes\u00a0que Guaymall\u00e9n se convierte en el\u00a0primer departamento\u00a0de Mendoza en\u00a0aprobar\u00a0una iniciativa que proh\u00edbe esta pr\u00e1ctica y sanciona la explotaci\u00f3n de animales, as\u00ed como tambi\u00e9n que establece multas para las\u00a0carreras de galgos\u00a0y\u00a0ri\u00f1as de gallos,que ya estaban prohibidas a nivel nacional.<\/p>\n<p>En ese sentido, el impulsor de la ordenanza cont\u00f3 que en las localidades deLos Corralitos, Colonia Molina\u00a0y\u00a0Rodeo de la Cruz\u00a0suelen concretarse este tipo de encuentros, en los que las personas llevan a sus animales y los someten a maltrato. \u201cAntes s\u00f3lo se pod\u00eda secuestrar a los animales, pero ahora se puede sancionar a quienes los explotan\u201d, explic\u00f3.<\/p>\n<p>La normativa se fundamenta en la\u00a0Declaraci\u00f3n Universal de los Derechos de los Animales, que establece que \u201ctodo animal tiene derecho al respeto\u201d, que \u201cel hombre, como especie animal, no puede atribuirse el derecho de exterminar a los otros animales o de explotarlos, y que los animales \u201ctienen derecho a la atenci\u00f3n, a los cuidados y a la protecci\u00f3n del hombre\u201d.<\/p>\n<p>Tambi\u00e9n toma en cuenta el\u00a0sufrimiento\u00a0al que se le\u00a0somete a los animales que, por motivo de la exigencia competitiva, tienen baja expectativa de vida, ya que cerca de los tres a\u00f1os son abandonados y hasta eliminados.<\/p>\n<p>Incluso, la ordenanza intenta resguardar la salud de las especies. Es com\u00fan que en este tipo de pr\u00e1cticas sufran da\u00f1os f\u00edsicos como\u00a0fracturas, quemaduras, golpes y deformaciones, debido al uso de drogas y hasta de \u00e1cido contra los animales.<\/p>\n<p>Ahora, las carreras de perros ser\u00e1n sancionadas por\u00a0multas\u00a0de\u00a0$11.000(5.000 unidades tributarias) los que realicen y promuevan ri\u00f1as o pelea de gallos, perros o cualquier otro animal, al igual que a sus due\u00f1os.<\/p>\n<p>En tanto, ser\u00e1n multados con\u00a0$18.700\u00a0(8500 UT) los que ejerzan actos de crueldad, maltratos y\/o administren drogas o sustancias similares a los animales.<\/p>\n<p>Vale aclarar que las sanciones se duplicar\u00e1n\u00a0si algunas de las acciones\u00a0fueran realizadas por dinero o con \u00e1nimo de lucro.<\/p>\n<h6>Fuente: Los Andes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La comuna aprob\u00f3 una ordenanza que protege la integridad de los animales y la aplicaci\u00f3n de multas que llegan hasta los $18.000.<\/p>\n","protected":false},"author":2,"featured_media":71087,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31],"class_list":["post-71086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/71086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=71086"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/71086\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/71087"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=71086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=71086"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=71086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}