{"id":72713,"date":"2018-02-01T06:56:30","date_gmt":"2018-02-01T09:56:30","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=72713"},"modified":"2018-02-01T06:56:30","modified_gmt":"2018-02-01T09:56:30","slug":"mar-del-plata-recibira-110-millones-pesos-tras-la-promulgacion-la-adhesion-al-pacto-fiscal","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/mar-del-plata-recibira-110-millones-pesos-tras-la-promulgacion-la-adhesion-al-pacto-fiscal\/","title":{"rendered":"Mar del Plata recibir\u00e1 110 millones de pesos tras la promulgaci\u00f3n de la adhesi\u00f3n al pacto fiscal"},"content":{"rendered":"<p>El intendente de General Pueyrred\u00f3n, a trav\u00e9s del decreto N\u00ba 105, proclam\u00f3 la ordenanza que establece que el municipio se sume al R\u00e9gimen de Responsabilidad Fiscal de la Provincia de Buenos Aires.<\/p>\n<p>Finalmente el\u00a0intendente de General Pueyrred\u00f3n, Carlos Arroyo,\u00a0promulg\u00f3 la\u00a0ordenanza para que el municipio adhiera al pacto fiscal impulsado por la gobernadora de la provincia de Buenos Aires, Mar\u00eda Eugenia Vidal. La misma fue aprobada por mayor\u00eda en la sesi\u00f3n extraordinaria del Concejo Deliberante.<\/p>\n<p>Al respecto, el\u00a0concejal oficialista Guillermo Volponi, destac\u00f3 la aprobaci\u00f3n del proyecto y dijo que \u201cgenera un importante beneficio para la ciudad de Mar del Plata\u201d.<\/p>\n<p>Asimismo indic\u00f3 que \u201csomos conscientes y valoramos el esfuerzo que realiza por la ciudad la Gobernadora Mar\u00eda Eugenia Vidal, contribuyendo para que Mar del Plata pueda salir de la crisis en la se encuentra como resultado de las malas administraciones de los a\u00f1os anteriores\u201d.<\/p>\n<p>\u201cConsideramos que es vital para todos los marplatenses contar con los instrumentos necesarios para poder dar respuesta a las demandas m\u00e1s urgentes de la gente, y esta es una v\u00eda m\u00e1s que v\u00e1lida para lograrlo\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Seg\u00fan public\u00f3 0223, Volponi afirm\u00f3 que \u201cser\u00e1 por la aprobaci\u00f3n de esta ordenanza a nivel local, en este ejercicio Mar del Plata recibir\u00e1 unos 110 millones de pesos, fundamentales para el desarrollo de la gesti\u00f3n actual\u201d.<\/p>\n<p>Mientras tanto,\u00a0los ediles de Unidad Ciudadana\u00a0rechazaron la iniciativas y se\u00f1alaron que \u201cesta medida atenta directamente contra la autonom\u00eda municipal. El pacto fiscal de Cambiemos es extorsivo, ya que si los municipios no adhieren la Provincia los castiga: no les permite contraer deuda o asistencia financiera, y si adhieren, pero no cumplen las metas tambi\u00e9n son castigados\u201d.<\/p>\n<p>\u201cEs lamentable que los intendentes se conviertan en gerentes de Cambiemos y tengan la obligaci\u00f3n de cumplir metas para satisfacer a la gobernadora, aunque esas metas est\u00e9n lejos de los intereses de los ciudadanos\u201d, sostuvieron.<\/p>\n<h6>Fuente: InfoCielo<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El intendente de General Pueyrred\u00f3n, a trav\u00e9s del decreto N\u00ba 105, proclam\u00f3 la ordenanza que establece que el municipio se sume al R\u00e9gimen de Responsabilidad Fiscal de la Provincia de Buenos Aires.<\/p>\n","protected":false},"author":2,"featured_media":72714,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[12],"class_list":["post-72713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-economico","tag-buenos-aires"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=72713"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72713\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/72714"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=72713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=72713"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=72713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}