{"id":72746,"date":"2018-02-01T08:02:42","date_gmt":"2018-02-01T11:02:42","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=72746"},"modified":"2018-02-01T08:02:42","modified_gmt":"2018-02-01T11:02:42","slug":"fiesta-nacional-del-asado-cholila-2-3-4-febrero","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/fiesta-nacional-del-asado-cholila-2-3-4-febrero\/","title":{"rendered":"Fiesta Nacional del Asado, Cholila, 2, 3, y 4 de febrero"},"content":{"rendered":"<p>La localidad de Cholila, en Chubut, celebrar\u00e1 este fin de semana una nueva edici\u00f3n del tradicional evento.<\/p>\n<p>Con unos 15 mil kilos de carne y 80 parrilleros, la localidad de Cholila, ubicada al pie de la Cordillera de los Andes, en el noroeste de Chubut, celebrar\u00e1 este fin de semana la novena edici\u00f3n de la fiesta nacional del asado.<\/p>\n<p>Este a\u00f1o, la fiesta se realizar\u00e1 los d\u00edas 2, 3, y 4 de febrero y m\u00e1s de ochenta personas trabajar\u00e1n en el fog\u00f3n para colaborar en la cocci\u00f3n y atenci\u00f3n de los comensales, en este mega asado que se desarrollar\u00e1 en \u00abEl Morro\u00bb, el predio oficial de la fiesta, en el que se cocinar\u00e1n aproximadamente 55 novillos y 500 corderos.<\/p>\n<p>\u00abLa gente de Cholila espera con gran entusiasmo esta celebraci\u00f3n que congrega a familias, amigos, turistas de todas partes y pobladores de localidades aleda\u00f1as\u00bb, dijo el intendente local, Silvio Boudargham, en di\u00e1logo con T\u00e9lam.<\/p>\n<p>\u00abEl desarrollo de esta fiesta es muy positivo econ\u00f3micamente para los comerciantes locales ya que es mucha la gente que se acerca a nuestra localidad en esas fechas y aprovecha tambi\u00e9n para quedarse unos d\u00edas m\u00e1s\u00bb, a\u00f1adi\u00f3.<\/p>\n<p>La porci\u00f3n de asado rondar\u00e1 los $250 y se podr\u00e1 optar por asado de ternero, cordero, costeletas, bifes de cordero y chorizos caseros.<\/p>\n<h6>Fuente: MDZ Online<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La localidad de Cholila, en Chubut, celebrar\u00e1 este fin de semana una nueva edici\u00f3n del tradicional evento.<\/p>\n","protected":false},"author":2,"featured_media":72747,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[14],"class_list":["post-72746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiestas","tag-chubut"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=72746"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72746\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/72747"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=72746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=72746"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=72746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}