{"id":72755,"date":"2018-02-01T06:20:40","date_gmt":"2018-02-01T09:20:40","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=72755"},"modified":"2018-02-01T08:25:02","modified_gmt":"2018-02-01T11:25:02","slug":"soem-rio-gallegos-exige-inmediato-pago-las-litis","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/soem-rio-gallegos-exige-inmediato-pago-las-litis\/","title":{"rendered":"El SOEM R\u00edo Gallegos exige el inmediato pago de las Litis"},"content":{"rendered":"<p>A trav\u00e9s de una nota, dirigida al intendente, la Comisi\u00f3n Directiva del SOEM reclama que de manera inmediata se realice el pago de las Litis y cuotas alimentarias, advirtiendo que las mismas fueron descontadas de los haberes a los trabajadores pero que hasta el momento \u201cno se constata la acreditaci\u00f3n correspondiente en los sistemas bancarios de los beneficiarios\u201d.<\/p>\n<p>Ariel D\u00edaz, secretario de Prensa del SOEM, indic\u00f3 que se est\u00e1 trabajando y se recurrir\u00e1 a la Justicia, y critic\u00f3 duramente la falta de gesti\u00f3n: \u201cHay una muy mala gesti\u00f3n y una falta de previsibilidad financiera que nos est\u00e1 perjudicando\u201d.<\/p>\n<p>El dirigente se dirigi\u00f3 a Giubetich: \u201cqueremos decirle al se\u00f1or intendente que es necesario que se ponga a la altura de las circunstancias, est\u00e1 claramente incumpliendo sus obligaciones y est\u00e1n sobrepasando los l\u00edmites, y esto no lo vamos a permitir, lo vivimos en el 2015 y debemos poner un freno, porque parece incre\u00edble que sucedan estas cosas\u201d.<\/p>\n<p>Adem\u00e1s, D\u00edaz, record\u00f3 que el reclamo por parte de trabajadores es permanente y remarc\u00f3 que las tratativas y el di\u00e1logo es constante por parte de la organizaci\u00f3n sindical.<\/p>\n<p>\u201cEstamos trabajando junto con nuestros asesores letrados para tomar los recaudos necesarios, y aprovechamos la oportunidad para convocar a los compa\u00f1eros que se encuentran afectados a acercarse al sindicato para realizar el correspondiente diligenciamiento y reclamo en forma colectiva, ya que este retraso de la Litis expensas perjudica a nuestros hijos y va a llegar a la Justicia\u201d, advirti\u00f3.<\/p>\n<p>Se\u00f1al\u00f3 que \u201chay compa\u00f1eras y compa\u00f1eros movilizados porque es un tema complejo que pasa por descuentos que se le hacen al trabajador y no llegan donde deben llegar\u201d.<\/p>\n<p>Ratificando que ir\u00e1n a la Justicia por este tema, tambi\u00e9n pidi\u00f3 que esperan que dicho Poder, \u201cact\u00fae de igual manera como lo hace con el gremio a la hora de aplicar la ley\u201d.<\/p>\n<p>En la nota, presentada al jefe comunal, el gremio recuerda que el retraso en el pago de las Litis y Alimentos, \u201cdilata la naturaleza jur\u00eddica de la obligaci\u00f3n del Alimento\u201d y repercute en el hogar, \u201cpero m\u00e1s a\u00fan en la persona beneficiaria por qui\u00e9n se reclama\u201d, ya que dichos montos est\u00e1n destinados a cubrir los gastos de la canasta b\u00e1sica, vestimenta y \u201csobre todo, la sustentabilidad\u201d de dicho hogar.<\/p>\n<h6>Fuente: La Opini\u00f3n Austral<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de una nota, dirigida al intendente, la Comisi\u00f3n Directiva del SOEM reclama que de manera inmediata se realice el pago de las Litis y cuotas alimentarias, advirtiendo que las mismas fueron descontadas de los haberes<\/p>\n","protected":false},"author":2,"featured_media":72756,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[29],"class_list":["post-72755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-sindical","tag-santa-cruz"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=72755"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72755\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/72756"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=72755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=72755"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=72755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}