{"id":72844,"date":"2018-02-05T07:58:10","date_gmt":"2018-02-05T10:58:10","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=72844"},"modified":"2018-02-05T07:58:10","modified_gmt":"2018-02-05T10:58:10","slug":"ecuador-vota-referendum-favor-limitar-dos-periodos-mandato-presidencial","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/ecuador-vota-referendum-favor-limitar-dos-periodos-mandato-presidencial\/","title":{"rendered":"Ecuador vota en refer\u00e9ndum a favor de limitar a dos periodos el mandato presidencial"},"content":{"rendered":"<p>Seg\u00fan datos del CNE, el \u00abs\u00ed\u00bb en la pregunta que busca derogar la reelecci\u00f3n indefinida de autoridades alcanz\u00f3 la aprobaci\u00f3n del 64,66% de los votantes.<\/p>\n<p>&nbsp;<\/p>\n<p>Los ecuatorianos votaron este domingo por limitar a dos t\u00e9rminos el mandato presidencial, lo que impedir\u00e1 al expresidente Rafael Correa presentarse nuevamente al gobierno, seg\u00fan datos preliminares del Consejo Nacional Electoral (CNE).<\/p>\n<p>Cuando se llevaba escrutado alrededor del 68% de las actas, el \u00abs\u00ed\u00bb ganaba en las siete preguntas de la consulta convocada por el presidente, Len\u00edn Moreno con un promedio de 69,07%.<\/p>\n<p>Seg\u00fan datos del CNE, el \u00abs\u00ed\u00bb en la pregunta que busca derogar la reelecci\u00f3n indefinida de autoridades alcanz\u00f3 la aprobaci\u00f3n del\u00a064,66%\u00a0de los votantes.<\/p>\n<p>El refer\u00e9ndum constaba de siete preguntas sobre corrupci\u00f3n, la reelecci\u00f3n presidencial, plusval\u00eda, naturaleza, miner\u00eda y delitos sexuales contra menores.<\/p>\n<p>La participaci\u00f3n se situ\u00f3 un 74,80% de los m\u00e1s de 13 millones de ecuatorianos que estaba llamados a votar, incluidos 400.000 en el extranjero.<\/p>\n<p>Los datos indican que la pregunta que m\u00e1s apoyo obtuvo, con un 74%, es la que pide que quienes hayan sido sentenciados por corrupci\u00f3n queden inhabilitados para participar en la vida pol\u00edtica y pierdan sus bienes.<\/p>\n<p>Los resultados tienen un margen de error menor al 1%, seg\u00fan el CNE.<\/p>\n<p>Enfrentamiento<br \/>\nEl refer\u00e9ndum fue visto como un enfrentamiento entre Moreno y Rafael Correa. Especialmente por dos de las preguntas del mismo, seg\u00fan dijo el polit\u00f3logo Sim\u00f3n Pachano, profesor de la sede de Ecuador de la Facultad Latinoamericana de Ciencias Sociales (Flacso Ecuador), a BBC Mundo.<\/p>\n<p>Una de las consultas a las que se refiere Pachano es la que buscaba terminar con la reelecci\u00f3n indefinida de autoridades.<\/p>\n<p>El exmandatario Rafael Correa regres\u00f3 desde B\u00e9lgica al pa\u00eds para hacer campa\u00f1a por el \u00abno\u00bb, opci\u00f3n que le hubiera permitido volver a postular a un nuevo mandato.<\/p>\n<p>Pero cuando el CNE hab\u00eda contado el 78% de las actas, el \u00abs\u00ed\u00bb acumulaba el 64% de los votos y el \u00abno\u00bb, solo el 35%.<\/p>\n<p>De acuerdo a estos resultados, Correa ya no podr\u00e1 ser reelegido. El expresidente cuestion\u00f3 el proceso en su cuenta de Twitter.<\/p>\n<p>Correa hab\u00eda impulsado la reelecci\u00f3n indefinida a trav\u00e9s de una enmienda constitucional en 2015 y fue acusado de querer perpetuarse en el poder.<\/p>\n<p>Ante ello, no se present\u00f3 a los comicios de 2017 y result\u00f3 ganador el candidato de su partido, Len\u00edn Moreno, el mismo que ahora le impide volver al poder.<\/p>\n<p>La otra pregunta con la que Moreno desaf\u00eda a Correa es la que busca reestructurar el Consejo de Participaci\u00f3n Ciudadana y Control Social, organismo encargado de las designaciones del contralor general del Estado, del procurador y del defensor p\u00fablico.<\/p>\n<p>Cuando se hab\u00eda escrutado el 76% de las actas, el \u00abs\u00ed\u00bb a la reestructuraci\u00f3n iba ganando con el 63% y la opci\u00f3n \u00abno\u00bb ten\u00eda el 36% de los votos.<\/p>\n<p>En consecuencia, el gobierno podr\u00e1 dar por finalizar el per\u00edodo de los miembros del Consejo y evaluar el desempe\u00f1o de las autoridades que ha designado, a quienes los cr\u00edticos de Correa acusan de responder al expresidente.<\/p>\n<p>\u00abEso implicar\u00eda la p\u00e9rdida de poder de Correa y sus aliados y la transferencia al grupo de Moreno\u00bb, explic\u00f3 Pedro Romero, director de la Maestr\u00eda de Econom\u00eda de la Universidad San Francisco de Quito, a BBC Mundo.<\/p>\n<p>Legitimaci\u00f3n<br \/>\nEl profesor Pachano, de Flacso Ecuador, dijo a BBC Mundo que Moreno ten\u00eda dos razones para querer legitimar su mandato con este refer\u00e9ndum.<\/p>\n<p>Una es superar el hecho de que alcanz\u00f3 la presidencia con muy poca diferencia con respecto al otro candidato (Guillermo Lasso) y en medio de sospechas de fraude.<\/p>\n<p>La otra, distanciarse de Correa tanto dentro de su partido como en la conducci\u00f3n del pa\u00eds.<\/p>\n<h6>Fuente: MDZ Online<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan datos del CNE, el \u00abs\u00ed\u00bb en la pregunta que busca derogar la reelecci\u00f3n indefinida de autoridades alcanz\u00f3 la aprobaci\u00f3n del 64,66% de los votantes.<\/p>\n","protected":false},"author":2,"featured_media":72845,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[57],"class_list":["post-72844","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-mundo","tag-el-mundo"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=72844"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72844\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/72845"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=72844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=72844"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=72844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}