{"id":72877,"date":"2018-02-06T06:07:44","date_gmt":"2018-02-06T09:07:44","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=72877"},"modified":"2018-02-06T07:09:25","modified_gmt":"2018-02-06T10:09:25","slug":"la-politica-ahogar-los-gremios","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/la-politica-ahogar-los-gremios\/","title":{"rendered":"La pol\u00edtica de ahogar a los gremios"},"content":{"rendered":"<p>En medio del conflicto por 122 despidos en el Hospital Posadas, el Gobierno intenta ahogar financieramente a los gremios. La Asociaci\u00f3n de Profesionales de la Salud denunci\u00f3 que las autoridades no ejecutaron el descuento de la cuota sindical de sus afiliados en los sueldos de enero. La medida est\u00e1 en l\u00ednea con otras recientes acciones antisindicales de Cambiemos, como la campa\u00f1a de desafiliaci\u00f3n que la gobernadora Mar\u00eda Eugenia Vidal impulsa entre los docentes y la anulaci\u00f3n de la cuota solidaria a La Bancaria.<\/p>\n<p>\u201cLo que est\u00e1n haciendo es totalmente ilegal\u201d, advirti\u00f3 Guillermo Pacagnini, titular del gremio. El dirigente se\u00f1al\u00f3 que su organizaci\u00f3n tiene personer\u00eda gremial, por lo que las autoridades del hospital est\u00e1n obligadas a hacer de agente de retenci\u00f3n de la cuota de los afiliados, para transferir luego los fondos al gremio. En este caso, omitieron aplicar el c\u00f3digo de descuento en las liquidaciones.<\/p>\n<p>Los trabajadores del hospital est\u00e1n en plan de lucha por la reincorporaci\u00f3n de los despedidos. Hicieron ya dos paros de 24 horas y anunciaron una tercera huelga para este jueves, d\u00eda en que realizar\u00e1n un abrazo al hospital y saldr\u00e1n al Acceso Oeste.<\/p>\n<p>Los 122 despidos de enero hab\u00edan puesto en evidencia la intenci\u00f3n oficial de desarmar la organizaci\u00f3n gremial dentro del hospital. \u00a0Entre los cesantes, hay 17 de los 23 delegados de la Cicop, como as\u00ed tambi\u00e9n afiliados a una lista de ATE opositora a la conducci\u00f3n local.<\/p>\n<p>Adem\u00e1s de la Cicop, un segundo gremio del hospital fue tambi\u00e9n tomado como blanco \u2013el Sindicato de Trabajadores de la Salud\u2013 con la no aplicaci\u00f3n del c\u00f3digo de descuento para la cuota sindical. En este caso, la represalia no constituye en rigor una ilegalidad, ya que se trata de un sindicato simplemente inscripto, es decir que no tiene la personer\u00eda gremial. Con todo, lo que queda a la vista es la decisi\u00f3n de las autoridades de debilitar como sea la organizaci\u00f3n de los trabajadores.<\/p>\n<h6>Fuente: P\u00e1gina 12<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>En medio del conflicto por 122 despidos en el Hospital Posadas, el Gobierno intenta ahogar financieramente a los gremios. <\/p>\n","protected":false},"author":2,"featured_media":72878,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[21],"class_list":["post-72877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-nacional","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=72877"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72877\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/72878"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=72877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=72877"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=72877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}