{"id":72905,"date":"2018-02-06T07:47:43","date_gmt":"2018-02-06T10:47:43","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=72905"},"modified":"2018-02-06T07:47:43","modified_gmt":"2018-02-06T10:47:43","slug":"buscan-chacras-familiares-exporten-alfalfa-rio-negro-los-emiratos-arabes","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/buscan-chacras-familiares-exporten-alfalfa-rio-negro-los-emiratos-arabes\/","title":{"rendered":"Buscan que chacras familiares exporten alfalfa de R\u00edo Negro a los Emiratos \u00c1rabes"},"content":{"rendered":"<p>Desde el a\u00f1o pasado, se vende agua mineral a Medio Oriente. Ahora buscan que peque\u00f1os emprendimientos se asocien e introduzcan la alfalfa all\u00ed, lo cual les permitir\u00e1 crecer y planificar. Tambi\u00e9n hay l\u00edneas de trabajo de la C\u00e1mara Argentina Emirat\u00ed para que capones y ovinos rionegrinos lleguen al puerto de Dub\u00e1i.<\/p>\n<p>En di\u00e1logo con El Cordillerano, el ingeniero Ra\u00fal Benzo se\u00f1al\u00f3 que est\u00e1 trabajando para que peque\u00f1as chacras de nuestra provincia puedan tener un proyecto de exportaci\u00f3n a largo plazo y de esa manera, exista un sustento que les permita planificar, por lo menos a cinco a\u00f1os.<\/p>\n<p>\u201cLa idea en la que se est\u00e1 trabajando y que est\u00e1 muy avanzada, es en asociar a peque\u00f1as chacras familiares que hoy no llegan a ser ni siquiera PyME, para que se conviertan en productores importantes de alfalfa. As\u00ed potenciamos adem\u00e1s, las zonas de riego ociosas y se genera un mercado importante\u201d, precis\u00f3.<\/p>\n<p>El proyecto contempla a unos 15 productores ubicados en la zona de Choele Choel y Luis Beltr\u00e1n y se apunta a poder vender unas 5.000 toneladas de alfalfa de alta densidad. Todo lo que generen es f\u00e1cil de comercializar en el mercado \u00e1rabe por la alta demanda que tiene el producto, una enorme carencia que hay en esa regi\u00f3n para la cr\u00eda de animales.<\/p>\n<p>Por otro lado, en territorio rionegrino se potenciar\u00eda a peque\u00f1os productores, quienes estar\u00e1n creando un producto de alta calidad, con valores competitivos en el mercado, donde se pugna directamente con los Estados Unidos, principal productor de alfalfa del mundo.<\/p>\n<p>Para fomentar y entablar los v\u00ednculos, va creciendo la importancia de la C\u00e1mara Argentino Emirat\u00ed de Comercio, Industria, Servicios y Transferencia de Tecnolog\u00eda (CARAE), puerta de acceso a un mercado asi\u00e1tico de 2.000 millones de habitantes, regi\u00f3n del principal producto bruto del mundo.<\/p>\n<p>\u201cEs una iniciativa que adem\u00e1s de entablar una venta a largo plazo, tiene su corte social, porque queremos que estos peque\u00f1os productores tengan trabajo todo el a\u00f1o y por mucho tiempo. Eso va a generar que se conviertan en PyME, porque estamos hablando de chacras que no tienen m\u00e1s de 20 hect\u00e1reas y que si no se las asocia entre s\u00ed y se les brinda un respaldo como este, nunca estar\u00edan en condiciones de exportar\u201d, detall\u00f3 el ingeniero.<\/p>\n<p>Presidida por Gabriel Osatinsky, la C\u00e1mara Argentina Emirat\u00ed trabaja en la regi\u00f3n y en los pr\u00f3ximos d\u00edas se emprender\u00e1 una misi\u00f3n comercial a Dub\u00e1i, con participaci\u00f3n del gobierno nacional y provincial.<\/p>\n<p>En ese formato de gesti\u00f3n, ya se est\u00e1 exportando agua mineral de manantial de Bariloche y ahora, desde la entidad quieren sellar el convenio para vender carnes rionegrinas, alfalfa y generar un v\u00ednculo con centros de esqu\u00ed de la regi\u00f3n, donde el cerro Bayo se ha mostrado interesado.<\/p>\n<p>En lo que hace a la exportaci\u00f3n de alfalfa, lo m\u00e1s dif\u00edcil de solucionar es c\u00f3mo bajar el costo de traslado desde nuestra provincia hasta el puerto de Buenos Aires. Desde all\u00ed, hasta Dub\u00e1i la C\u00e1mara se encarga de las gestiones.<\/p>\n<p>Por el lado de las carnes, el responsable de la C\u00e1mara Argentina Emirat\u00ed en la regi\u00f3n, Claudio Thieck, explic\u00f3 que est\u00e1 avanzada la firma de una carta de intenci\u00f3n para que el frigor\u00edfico R\u00edo Negro exporte capones y ovinos a Medio Oriente, a precios muy competitivos.<\/p>\n<p>La exportaci\u00f3n de productos comestibles, tanto como el turismo, requieren de certificaciones de calidad \u201cHalal\u201d, por lo que all\u00ed hay un punto m\u00e1s de exigencia para el comercio.<\/p>\n<p>En el rubro tur\u00edstico, por ahora una sola agencia de viajes ha sido certificada en la Argentina para venderles paquetes y productos tur\u00edsticos de este pa\u00eds.<\/p>\n<p>La potencialidad de este mercado es especialmente importante en el Sureste asi\u00e1tico y el Golfo P\u00e9rsico, donde hay pa\u00edses de mayor\u00eda musulmana en los que est\u00e1n creciendo mucho las clases medias y \u00e9stas est\u00e1n empezando a viajar por todo el mundo.<\/p>\n<p>La C\u00e1mara desarrolla un plan que define como hub to hub, con Argentina en un extremo y el puerto de Dub\u00e1i en el otro. La premisa es facilitar la presentaci\u00f3n de proyectos de inversi\u00f3n para la provincia, permitiendo que productores y exportadores de la regi\u00f3n puedan ir acerc\u00e1ndose a este mundo comercial.<\/p>\n<p>El visitante \u00e1rabe es muy particular por varias razones. Suele tener un alto poder adquisitivo y su modo de vida depende mucho de sus h\u00e1bitos, ligados a la religi\u00f3n. Por ejemplo: no beben alcohol, no comen cerdo, ni tampoco pueden verlos.<\/p>\n<p>El servicio es diferenciado porque se manejan \u00e1reas exclusivas, tanto para hombres como para mujeres. Ba\u00f1os, saunas, piscinas y salas de oraci\u00f3n, todas van separadas por g\u00e9nero, ya que no permiten mezclarse. En las habitaciones hay ejemplares del Cor\u00e1n y alfombras para orar.<\/p>\n<p>En Bariloche hay hoteles que ya est\u00e1n trabajando con este segmento y cada vez que llegan contingentes musulmanes, el alojamiento se completa y se cierra \u00edntegramente para ellos.<\/p>\n<h6>Fuente: El Cordillerano<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Desde el a\u00f1o pasado, se vende agua mineral a Medio Oriente. Ahora buscan que peque\u00f1os emprendimientos se asocien e introduzcan la alfalfa all\u00ed, lo cual les permitir\u00e1 crecer y planificar.<\/p>\n","protected":false},"author":2,"featured_media":72906,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[11],"class_list":["post-72905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincias","tag-rio-negro"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=72905"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72905\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/72906"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=72905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=72905"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=72905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}