{"id":72920,"date":"2018-02-06T06:21:26","date_gmt":"2018-02-06T09:21:26","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=72920"},"modified":"2018-02-06T08:23:15","modified_gmt":"2018-02-06T11:23:15","slug":"soem-catamarca-eligio-junta-electoral","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/soem-catamarca-eligio-junta-electoral\/","title":{"rendered":"El SOEM Catamarca eligi\u00f3 Junta Electoral"},"content":{"rendered":"<p>Anoche se realiz\u00f3 la asamblea del Sindicato de Obreros y Empleados Municipales (SOEM) de la Capital para elegir la Junta Electoral que regir\u00e1 el proceso de renovaci\u00f3n de autoridades que se celebrar\u00e1 pr\u00f3ximamente.<br \/>\nWalter Ar\u00e9valo, titular del sindicato, se\u00f1al\u00f3 que \u201cel 26 de marzo se estar\u00eda llamando a elecciones y se invitar\u00e1 a todo el que est\u00e9 en condiciones de formar parte de la Comisi\u00f3n Directiva, para que forme una lista y se involucre en el gremio\u201d.<br \/>\nEl gremialista dijo: \u201cNo nos tenemos que volver a equivocar, porque hoy tenemos miembros de la excomisi\u00f3n que dejaron una deuda de 11 millones de pesos, queriendo chicanear\u201d.<br \/>\n\u201cLos muchachos son ya historia dentro del sindicato y vamos a seguir avanzando\u201d, agreg\u00f3.<br \/>\nAr\u00e9valo dijo que a\u00fan no decidi\u00f3 si se presentar\u00e1 para un nuevo mandato, y se mostr\u00f3 a la expectativa de que haya buena participaci\u00f3n en las elecciones.<br \/>\n\u201cPor ahora estamos abocados a la negociaci\u00f3n paritaria\u201d, dijo.<\/p>\n<h6>Fuente: El Esquiu<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Anoche se realiz\u00f3 la asamblea del Sindicato de Obreros y Empleados Municipales (SOEM) de la Capital para elegir la Junta Electoral que regir\u00e1 el proceso de renovaci\u00f3n de autoridades que se celebrar\u00e1 pr\u00f3ximamente.<\/p>\n","protected":false},"author":2,"featured_media":72921,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[16],"class_list":["post-72920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-sindical","tag-catamarca"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=72920"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72920\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/72921"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=72920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=72920"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=72920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}