{"id":72927,"date":"2018-02-07T07:32:53","date_gmt":"2018-02-07T10:32:53","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=72927"},"modified":"2018-02-07T07:32:53","modified_gmt":"2018-02-07T10:32:53","slug":"olavarria-adhirio-al-decreto-antinepotismo-los-primos-del-intendente-seguiran-funciones","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/olavarria-adhirio-al-decreto-antinepotismo-los-primos-del-intendente-seguiran-funciones\/","title":{"rendered":"Olavarr\u00eda adhiri\u00f3 al decreto antinepotismo pero los primos del intendente seguir\u00e1n en funciones"},"content":{"rendered":"<p>El jefe comunal de ese distrito bonaerense, Ezequiel Galli, dio a conocer que no habr\u00e1 designaciones de parientes que desarrollen funciones en el gabinete municipal. Sin embargo, no la medida no alcanza a sus tres parientes.<\/p>\n<p>Ezequiel Galli, intendente de Olavarr\u00eda, tambi\u00e9n confirm\u00f3 su adhesi\u00f3n al decreto antinepotismo y de ese modo va en la misma l\u00ednea que el presidente Mauricio Macri y la gobernadora Mar\u00eda Eugenia Vidal en la Provincia. De todos modos, la resoluci\u00f3n no repercute en los primos del mandatario que prestan funciones en el Municipio.<\/p>\n<p>El jefe comunal asegur\u00f3 que no podr\u00e1n efectuarse designaciones de personal en la administraci\u00f3n p\u00fablica municipal que tengan vinculaci\u00f3n directa en l\u00ednea recta o hasta el segundo grado de consaguinidad con el intendente o rango jer\u00e1rquico. \u00a0Tambi\u00e9n son incluidos los c\u00f3nyuges y las uniones convivenciales.<\/p>\n<p>Galli dijo que quedan exceptuadas \u00ablas personas designadas mediante proceso de selecci\u00f3n por concurso o cuenten con estabilidad en el cargo alcanzada por el art\u00edculo primero, los cuales deber\u00e1n desvincularse antes del 31 de marzo\u00bb.<\/p>\n<p>Sobre su esposa, Florencia Barbieri, el intendente aclar\u00f3 que \u00abmi mujer nunca fue directora de PAMI, fue m\u00e9dica auditora de PAMI. Estudi\u00f3 para ser m\u00e9dica y el cargo era una auditor\u00eda y ya renunci\u00f3 hace quince d\u00edas\u00bb.<\/p>\n<p>En conferencia de prensa, explic\u00f3 que decreto \u00abtoca al matrimonio de Luciano Blanco y Mariana Diamanti\u00bb. El actual titular de la subsecretar\u00eda de Legales municipal \u00abtiene un cargo electo en el Concejo Deliberante por lo cual va a tomar cargo a partir del 1\u00ba de abril\u00bb. En el caso de la m\u00e9dica, es la actual secretaria del \u00e1rea de Salud comunal y seguir\u00e1 en funciones.<\/p>\n<p>Seg\u00fan public\u00f3 El Popular, el mandatario comunal manifest\u00f3 que la con la medida se busca \u00abir hacia la transparencia del Estado y limitar el acceso irrestricto de padres, hijos y familiares directos. Es una decisi\u00f3n que ha tomado el Presidente y que como Intendente y parte integrante de este espacio pol\u00edtico estoy convencido de que estamos yendo hacia una mejora del Estado\u00bb.<\/p>\n<p>Sobre sus primos que cumplen funciones dijo que \u00aba ninguno los toca el decreto\u00bb al tiempo que hizo hincapi\u00e9 en la \u00abidoneidad en cada uno de ellos para estar en el cargo. Ninguno es \u00f1oqui. Cada uno tuvo un proceso en la facultad. Mariana (Galli) es psic\u00f3loga y hace un trabajo inmenso en el sector de salud mental. Juan Agust\u00edn (Galli) es profesor de Educaci\u00f3n F\u00edsica y se form\u00f3 en deporte social en las villas del conurbano y la Ciudad de Buenos Aires. Hilario (Galli) es subsecretario y licenciado en econom\u00eda en la Universidad de Buenos Aires. Tampoco es un improvisado para estar haciendo lo que hace\u00bb.<\/p>\n<h6>Fuente: InfoCielo<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El jefe comunal de ese distrito bonaerense, Ezequiel Galli, dio a conocer que no habr\u00e1 designaciones de parientes que desarrollen funciones en el gabinete municipal. Sin embargo, no la medida no alcanza a sus tres parientes.<\/p>\n","protected":false},"author":2,"featured_media":72928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[12],"class_list":["post-72927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-politico","tag-buenos-aires"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=72927"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72927\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/72928"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=72927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=72927"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=72927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}