{"id":72967,"date":"2018-02-08T07:08:59","date_gmt":"2018-02-08T10:08:59","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=72967"},"modified":"2018-02-08T07:08:59","modified_gmt":"2018-02-08T10:08:59","slug":"luchar-ajuste-del-gobierno","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/luchar-ajuste-del-gobierno\/","title":{"rendered":"\u201cHay que luchar contra el ajuste del Gobierno\u201d"},"content":{"rendered":"<p>En un plenario de corrientes sindicales del que particip\u00f3 buena parte de la CGT, las dos CTA y la Corriente Federal se coincidi\u00f3 en armar un frente sindical y social para confrontar al Gobierno. La CTEP anuncia hoy su adhesi\u00f3n.<\/p>\n<p>El plenario de distintas corrientes sindicales realizado ayer al mediod\u00eda en la sede de Camioneros ratific\u00f3 la movilizaci\u00f3n \u2013que imaginan \u201cmultitudinaria y multisectorial\u201d\u2013 \u201ccontra el ajuste del gobierno de Mauricio Macri\u201d, que finalmente se realizar\u00e1 el mi\u00e9rcoles 21 de febrero para no coincidir con el sexto aniversario de la tragedia de Once. En la reuni\u00f3n de la que participaron los anfitriones Hugo y Pablo Moyano, una representaci\u00f3n importante de la CGT (que incluye a los triunviros de la conducci\u00f3n Juan Carlos Schmid y Carlos Acu\u00f1a) y varias de sus regionales, las dos CTA que conducen el docente Hugo Yasky y el estatal Pablo Micheli, la Corriente Federal que encabeza el bancario Sergio Palazzo y sindicatos clasistas, se coincidi\u00f3 en la voluntad de construir en la acci\u00f3n un frente sindical y social de quienes est\u00e1n dispuestos \u201ca confrontar contra el ajuste del Gobierno, la lucha contra los despidos y en defensa de las conquistas del movimiento sindical y social\u201d.<\/p>\n<p>Hoy, la Confederaci\u00f3n de Trabajadores de la Econom\u00eda Popular (Cetep) definir\u00e1 en un plenario \u2013del que tambi\u00e9n participar\u00e1n Pablo Moyano, Yasky y Micheli\u2013 la adhesi\u00f3n a la marcha, como ya lo hicieron otros movimientos sociales como Barrios de Pie, asociaciones que nuclean a las pymes, sectores agrarios, cooperativas fabriles en manos de los trabajadores y representaciones pol\u00edticas como Unidad Ciudadana y Partido Obrero, entre otras organizaciones.<\/p>\n<p>El encuentro, del que tambi\u00e9n participaron los dirigentes sindicales Roberto Baradel (Suteba), Ricardo Cirielli (aeron\u00e1uticos), An\u00edbal Torreta (municipales porte\u00f1os), Facundo Moyano (peajes), V\u00edctor Gonz\u00e1lez (municipales nacionales), Daniel Yofra (aceiteros), los diputados nacionales de Unidad Ciudadana con representaci\u00f3n sindical como Walter Correa (curtidores) y Vanesa Siley (judiciales) y el legislador porte\u00f1o Gustavo Vera arranc\u00f3 el debate sobre la fecha de la movilizaci\u00f3n.<\/p>\n<p>Fue entonces que Rub\u00e9n \u201cPollo\u201d Sobrero, dirigente de la Uni\u00f3n Ferroviaria del Sarmiento, que acompa\u00f1a la lucha de los familiares de las 52 v\u00edctimas de la tragedia de Once, propuso la modificaci\u00f3n en nombre de los trabajadores ferroviarios que se sumar\u00e1n a la marcha. La propuesta fue aprobada por aclamaci\u00f3n y movilizaci\u00f3n se pas\u00f3 para un d\u00eda antes: el 21F.<\/p>\n<p>All\u00ed tambi\u00e9n se definieron las proclamas de la convocatoria: por paritarias libres, contra los despidos en el Estado y la actividad privada, contra la reforma provisional y la modificaci\u00f3n del c\u00e1lculo de la movilidad jubilatoria. Tambi\u00e9n sumaron las demandas de los movimientos sociales como la declaraci\u00f3n de la emergencia alimentaria.<\/p>\n<p>\u201cEl plenario expres\u00f3 la voluntad de construir un frente sindical y social para confrontar contra el ajuste del gobierno de Macri y en defensa de las conquistas sindicales, un sujeto que hasta ahora solo tomaba forma con intermitencias, y con una proyecci\u00f3n multisectorial que se va a expresar en la movilizaci\u00f3n que va a ser multitudinaria\u201d, dijo Yasky a P\u00e1ginaI12.<\/p>\n<p>Micheli se refiri\u00f3 al d\u00eda despu\u00e9s de la movilizaci\u00f3n. \u201cTenemos que plantear la posibilidad de que si no tenemos respuestas luego de la marcha del 21, vamos a convocar a un paro nacional para el mes de marzo.\u201d<\/p>\n<p>\u201cSi no reaccionamos a tiempo, estos se\u00f1ores nos llevan puestos, porque no tienen escr\u00fapulos en seguir adelante a pesar de saber claramente que el pa\u00eds no anda nada bien\u201d, dijo Hugo Moyano tras arribar al encuentro y agradecer a los dirigentes el apoyo a la convocatoria que surgi\u00f3 desde su gremio tras un encuentro informal de sindicatos cegetistas en Mar del Plata, durante enero, que produjo un duro documentos contra las pol\u00edticas econ\u00f3micas y sociales del gobierno de Cambiemos. De esa l\u00ednea luego se despegaron el triunviro H\u00e9ctor Daer y los denominados sectores cegetistas conocidos como \u201cgordos\u201d e \u201cindependientes\u201d.<\/p>\n<p>El l\u00edder camionero tambi\u00e9n se refiri\u00f3 a quienes se autoexcluyeron de la marcha. \u201cMiren hasta que punto llega ese compromiso y sumisi\u00f3n que tienen algunos con el gobierno que les mandan a decir que no van a participar. No hace falta decirlo: no vienen y punto\u201d, se\u00f1al\u00f3. \u201cLo que pasa \u2013agreg\u00f3 Moyano\u2013 es que les exigen que digan que no van a venir, pensando que con eso van a debilitar la movilizaci\u00f3n, pero en vez de debilitarla la fortalecen porque no vendr\u00e1n los dirigentes pero s\u00ed los trabajadores y eso es lo que nos interesa.\u201d<\/p>\n<p>Aunque aun falta definir algunos detalles, la concentraci\u00f3n est\u00e1 prevista a partir de las 15 del mi\u00e9rcoles 21 de febrero frente al palco que se montar\u00e1 sobre las avenidas 9 de Julio y Belgrano, mirando al sur. All\u00ed ser\u00e1n oradores los dirigentes de las principales organizaciones convocantes: CGT, las dos CTA, la Corriente Federal y tambi\u00e9n habr\u00e1 un lugar para los movimiento sociales, con la idea de discursos cortos para dejar el cierre del acto a Hugo Moyano.<\/p>\n<h6>Fuente: P\u00e1gina 12<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>En un plenario de corrientes sindicales del que particip\u00f3 buena parte de la CGT, las dos CTA y la Corriente Federal se coincidi\u00f3 en armar un frente sindical y social para confrontar al Gobierno. La CTEP anuncia hoy su adhesi\u00f3n.<\/p>\n","protected":false},"author":2,"featured_media":72968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[21],"class_list":["post-72967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-nacional","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=72967"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/72968"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=72967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=72967"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=72967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}