{"id":72982,"date":"2018-02-08T07:27:42","date_gmt":"2018-02-08T10:27:42","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=72982"},"modified":"2018-02-08T07:27:42","modified_gmt":"2018-02-08T10:27:42","slug":"la-ciudad-santa-fe-recibira-us-300-000-consolidar-polo-cerveza-artesanal","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/la-ciudad-santa-fe-recibira-us-300-000-consolidar-polo-cerveza-artesanal\/","title":{"rendered":"La ciudad de Santa Fe recibir\u00e1 U$S 300.000 para consolidar el polo de cerveza artesanal"},"content":{"rendered":"<p>Con estos fondos, que aporta el gobierno nacional, se instalar\u00e1 una planta piloto de levadura en la Facultad de Bioqu\u00edmica de la UNL, que ya viene trabajando junto a las pymes cerveceras.<\/p>\n<p>La cerveza artesanal es una actividad en pleno auge y crecimiento en la ciudad de Santa Fe. Este martes se realiz\u00f3 una reuni\u00f3n de trabajo en el Mercado Norte, en la que se conocieron importantes novedades para potenciar el sector. La secretaria municipal de Desarrollo Estrat\u00e9gico y Resiliencia, Andrea Valsagna, encabez\u00f3 el encuentro que cont\u00f3 con la presencia de representantes de entidades que impulsan el sector de la cerveza artesanal santafesina.<\/p>\n<p>\u201cNos reunimos con dos actores importantes de la ciudad: el presidente de la Asociaci\u00f3n de Cerveceros Santafesinos, V\u00edctor Bertani; y el presidente de la C\u00e1mara de la Industria de Cerveza Artesanal, Federico Zwiener\u201d, cont\u00f3 Andrea Valsagna.<\/p>\n<p>La funcionaria municipal les comunic\u00f3 que el Ministerio de Producci\u00f3n de la Naci\u00f3n acaba de aprobar la financiaci\u00f3n -a trav\u00e9s del Banco Interamericano de Desarrollo (BID)- de 300.000 d\u00f3lares para el sector de cerveza artesanal. Se trata de un proyecto que se present\u00f3 el a\u00f1o pasado, con el apoyo de la Faculta de Bioqu\u00edmica de la Universidad Nacional del Litoral, que permitir\u00e1 instalar una planta piloto de desarrollo de levadura que ser\u00e1 un impulso muy grande para las Pymes cerveceras de la regi\u00f3n.<\/p>\n<p>El monto solicitado para realizar el proyecto contempla: adquisici\u00f3n de equipamiento para un laboratorio y planta piloto en la Facultad de Bioqu\u00edmica, equipamiento para compra de barriles de acero inoxidable, y la elaboraci\u00f3n de un plan de marketing.<\/p>\n<p>La novedad del financiamiento fue una gran noticia para los cerveceros: \u201cEstamos muy contentos con este anuncio. Es una excelente noticia para nosotros. Venimos trabajando con la Facultad de Bioqu\u00edmica hace ya m\u00e1s de 3 a\u00f1os. Nos viene acompa\u00f1ando con cuestiones de formaci\u00f3n, microbiol\u00f3gica y apoyo t\u00e9cnico. Poder tener esta planta es un paso muy grande, algo in\u00e9dito en la Argentina y viene acompa\u00f1ado de todo un proceso de formaci\u00f3n y capacitaci\u00f3n para todas las microempresas locales\u201d, destac\u00f3 Zwiener.<\/p>\n<p>Con respecto a quienes podr\u00e1n utilizar esta nueva tecnolog\u00eda, Zwiener indic\u00f3: \u201cActualmente en la c\u00e1mara somos 13, pero todo esto es para nosotros y para todos los que vengan despu\u00e9s, est\u00e1 pensado para todos los cerveceros que quieran usarlo\u201d.<\/p>\n<p>Bertani record\u00f3 que Santa Fe es una ciudad netamente cervecera. \u201cLo que traemos nosotros son gustos distintos, sabores distintos. Por eso, noticias como \u00e9stas son cosas que nos demuestran que el trabajo que venimos haciendo hace m\u00e1s de 2 a\u00f1os est\u00e1 dando sus frutos. Eso nos lleva a seguir apostando a trabajar todos juntos y tratar de posicionar la cerveza santafesina como referente de la provincia\u201d, propuso.<\/p>\n<p>La potencialidad tur\u00edstica de la industria fue otro de los ejes del encuentro. \u201cDesde el gobierno de la ciudad queremos avanzar para que se incorporen al desarrollo tur\u00edstico, porque la cerveza hoy tiene una potencialidad enorme para transformarse en un producto, ya sea con el tour cervecero, como con la posibilidad de armar circuitos y visitas de uno de los productos que caracterizan a Santa Fe, y por otra parte estamos avanzando en el calendario cervecero del a\u00f1o\u201d, concluy\u00f3 Andrea Valsagna.<\/p>\n<p>\u201cDesde el gobierno de la ciudad queremos avanzar para que se incorporen al desarrollo tur\u00edstico, porque la cerveza hoy tiene una potencialidad enorme para transformarse en un producto, ya sea con el tour cervecero, como con la posibilidad de armar circuitos\u201d.<br \/>\nAndrea Valsagna, Secretaria de Desarrollo Estrat\u00e9gico y Resiliencia<\/p>\n<h6>Fuente: El Litoral<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Con estos fondos, que aporta el gobierno nacional, se instalar\u00e1 una planta piloto de levadura en la Facultad de Bioqu\u00edmica de la UNL, que ya viene trabajando junto a las pymes cerveceras.<\/p>\n","protected":false},"author":2,"featured_media":72983,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[10],"class_list":["post-72982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-santa-fe"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=72982"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72982\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/72983"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=72982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=72982"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=72982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}