{"id":72985,"date":"2018-02-08T06:28:53","date_gmt":"2018-02-08T09:28:53","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=72985"},"modified":"2018-02-08T07:40:35","modified_gmt":"2018-02-08T10:40:35","slug":"inflacion-sigue-la-suba-precios-los-super","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/inflacion-sigue-la-suba-precios-los-super\/","title":{"rendered":"Inflaci\u00f3n: sigue la suba de precios en los s\u00faper"},"content":{"rendered":"<p>Teniendo en cuenta los rubros generales, el que m\u00e1s aumento registr\u00f3 fue el correspondiente a \u00abhogar\u00bb, con un incremento del 4,56 por ciento.<\/p>\n<p>El \u00edndice de precios de supermercados elaborado por el Centro de Estudios Econ\u00f3micos y Sociales Scalabrini Ortiz (IPS-Ceso) para la primera semana del mes de febrero fue del 0,5 por ciento en relaci\u00f3n a la semana anterior, y del 2 por ciento en relaci\u00f3n a la misma semana del mes pasado.<\/p>\n<p>Seg\u00fan el \u00edndice que elabora Ceso y realiza el seguimiento de m\u00e1s de 20 mil precios de productos on line, a cargo de equipos de programaci\u00f3n de la consultora, los incrementos mensuales m\u00e1s destacados se registraron en los rubros iluminaci\u00f3n (20 por ciento), textil hogar (10 por ciento), TV y video (8,3 por ciento), muebles (7,8 por ciento), celulares y telefon\u00eda (7,6 por ciento), producto del efecto de la devaluaci\u00f3n sobre los precios de los productos importados.<\/p>\n<p>Las bajas m\u00e1s importantes se registraron en los rubros climatizaci\u00f3n (-1,4 por ciento), cereales (-1,2 por ciento) y piletas (-1 por ciento).<\/p>\n<p>Teniendo en cuenta los rubros generales, el que m\u00e1s aumento registr\u00f3 fue el correspondiente a \u00abhogar\u00bb, con un incremento del 4,56 por ciento, seguido por el rubro \u00abtextil\u00bb, con una evoluci\u00f3n del 4,17 por ciento, y \u00abbebidas\u00bb, que aument\u00f3 el 3,17 por ciento.<\/p>\n<h6>Fuente: La capital<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Teniendo en cuenta los rubros generales, el que m\u00e1s aumento registr\u00f3 fue el correspondiente a \u00abhogar\u00bb, con un incremento del 4,56 por ciento.<\/p>\n","protected":false},"author":2,"featured_media":72987,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[21],"class_list":["post-72985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-nacional","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=72985"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/72985\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/72987"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=72985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=72985"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=72985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}