{"id":73047,"date":"2018-02-09T07:15:34","date_gmt":"2018-02-09T10:15:34","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=73047"},"modified":"2018-02-09T07:15:34","modified_gmt":"2018-02-09T10:15:34","slug":"mos-rechaza-la-aprobacion-del-ajuste-la-provincia-santa-fe","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/mos-rechaza-la-aprobacion-del-ajuste-la-provincia-santa-fe\/","title":{"rendered":"El MOS rechaza la aprobaci\u00f3n del Ajuste en la Provincia de Santa Fe"},"content":{"rendered":"<p>ANTE LA POSIBILIDAD DE QUE SEA TRATADO EN LA LEGISLATURA PROVINCIAL EL PACTO FISCAL IMPULSADO POR EL EJECUTIVO NACIONAL, EL MOVIMIENTO OBRERO SANTAFESINO REITERA SU RECHAZO ABSOLUTO A ESTE PROYECTO QUE CERCENA DERECHOS E INSISTE EN AJUSTAR A LOS Y LAS TRABAJADORAS SANTAFESINAS.<\/p>\n<p>En este contexto, este jueves 8 de febrero el MOS fue recibido por legisladores santafesinos quienes se comprometieron a mantener informados a los representantes de lxs trabajadorxs ante cualquier novedad que surja sobre el tratamiento de esta iniciativa.<\/p>\n<p>Recordamos que, como la gran mayor\u00eda de las pol\u00edticas impulsadas desde el Gobierno Nacional, este Pacto significar\u00e1 m\u00e1s ajuste y retrocesos en los derechos y conquistas del Movimiento Obrero Santafesino, ya que implica el congelamiento de la planta del Estado, la armonizaci\u00f3n de la Caja de Jubilaciones, la sesi\u00f3n de recursos santafesinos en favor de la Provincia de Buenos Aires y un dudoso compromiso de pago de las deudas que nuestra Provincia ha ganado en diferentes litigios.<\/p>\n<p>Tambi\u00e9n, se pone en riesgo el sistema de recaudaci\u00f3n provincial al resignar progresivamente la recaudaci\u00f3n por Ingresos Brutos, la m\u00e1s importante fuente de recursos propia. Implicar\u00e1 adem\u00e1s, una menor presi\u00f3n fiscal sobre los sectores de m\u00e1s alto ingresos y m\u00e1s concentrados de la econom\u00eda con las modificaciones que se proponen en Ganancias y Bienes Personales, a la par de un fuerte aumento del impuesto inmobiliario que recaer\u00e1 sobre los trabajadores.<\/p>\n<p>Por todo lo expuesto desde el Movimiento Obrero Santafesino SE MANTIENE EL ESTADO DE ALERTA Y MOVILIZACI\u00d3N a los efectos de garantizar instancias metodol\u00f3gicas en defensa de los intereses de la clase trabajadora, de los sectores sociales m\u00e1s vulnerables y de nuestros compa\u00f1eros jubilados y pensionados.<\/p>\n<p>CGT REGIONAL SANTA FE<br \/>\nCGT REGIONAL SAN LORENZO<br \/>\nCGT REGIONAL VENADO TUERTO<br \/>\nCGT REGIONAL RAFAELA<br \/>\nCGT REGIONAL RECONQUISTA<br \/>\nCGT REGIONAL ESPERANZA<br \/>\nCTA PROVINCIA DE SANTA FE<br \/>\nMOVIMIENTO SINDICAL ROSARINO<br \/>\nUOM VILLA CONSTITUCI\u00d3N<br \/>\nFESTRAM<br \/>\nAMSAFE PROVINCIAL<br \/>\nATE CONSEJO DIRECTIVO PROVINCIAL<\/p>\n<h6>Fuente: Prensa FESTRAM<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>ANTE LA POSIBILIDAD DE QUE SEA TRATADO EN LA LEGISLATURA PROVINCIAL EL PACTO FISCAL IMPULSADO POR EL EJECUTIVO NACIONAL, EL MOVIMIENTO OBRERO SANTAFESINO REITERA SU RECHAZO ABSOLUTO A ESTE PROYECTO<\/p>\n","protected":false},"author":2,"featured_media":73048,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[10],"class_list":["post-73047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-sindical","tag-santa-fe"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/73047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=73047"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/73047\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/73048"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=73047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=73047"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=73047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}