{"id":73077,"date":"2018-02-09T07:47:33","date_gmt":"2018-02-09T10:47:33","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=73077"},"modified":"2018-02-09T07:47:33","modified_gmt":"2018-02-09T10:47:33","slug":"amaicha-se-agitan-las-cajas-recibir-la-nueva-pachamama","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/amaicha-se-agitan-las-cajas-recibir-la-nueva-pachamama\/","title":{"rendered":"En Amaicha se agitan las cajas para recibir a la nueva Pachamama"},"content":{"rendered":"<p>La Fiesta Nacional de la Pachamama, coincidente con los carnavales, arranca este jueves. M\u00fasica en vivo, bailes y mucha tradici\u00f3n<\/p>\n<p>En la plaza de Amaicha del Valle ya se perciben los preparativos para el gran fin de semana de la temporada. Entre cantos de copleras, el retumbar de los bombos y las cajas, el baile de los diablos, los sikus y los ritos ancestrales se celebrar\u00e1 la 71\u00b0 edici\u00f3n de la Fiesta Nacional de la Pachamama en coincidencia con el carnaval, del jueves 8 hasta el martes 13. Para los actos centrales del domingo se espera que participen unas 20.000 personas, seg\u00fan los c\u00e1lculos del director de Turismo de la comuna,\u00a0Sebasti\u00e1n Pastrana.<\/p>\n<p>Las expectativas son las mejores en Amaicha. La plaza del pueblo ser\u00e1 uno de los escenarios al aire libre para el festejo del carnaval; mientras que el domingo se elegir\u00e1 a la nueva Pachamama, que representa la fertilidad. \u201cEn agosto vivimos el momento rogativo, de pedido por un buen a\u00f1o agr\u00edcola; mientras que en febrero estamos en \u00e9poca de cosecha y agradecemos a la Madre Tierra con carnavales y fiestas\u201d, explic\u00f3 Pastrana.<\/p>\n<p>El festejo se abre con el tradicional Jueves de comadres, una colorida fiesta que empieza a palpitar el ritmo del Carnaval. Este a\u00f1o actuar\u00e1n grandes artistas en shows para todos los que quieran compartir la celebraci\u00f3n ancestral en el Hogar de la Pachamama. Pastrana explic\u00f3 que habr\u00e1 un bono contribuci\u00f3n de $60 para ayudar a cubrir algunos gastos de la festividad. Pero tambi\u00e9n habr\u00e1 fiesta al aire libre y gratuita en la plaza del pueblo.<\/p>\n<p>La Pachamama es tan convocante que las autoridades esperan cubrir la capacidad hotelera de Amaicha y derivar gente, incluso, a localidades cercanas. La concurrencia de los turistas se hace patente, sobre todo, a la noche, cuando invaden la plaza principal y los bares, para disfrutar del aire puro y de la m\u00fasica que arrastra el viento por todo el valle. La mayor\u00eda son mochileros que, en su paso por los Valles, se enamoran de la tierra de la Pachamama.<\/p>\n<p>Esta vez la comuna y el Gobierno provincial ejecutaron diferentes obras para asegurar a los turistas servicios p\u00fablicos y atenci\u00f3n adecuada durante los festejos. \u201cEn el sector comercial -dijo Pastrana-, se nota el optimismo que impone esta temporada por el crecimiento notable de la oferta de albergues y de las propuestas recreativas y musicales, entre otras, que organiza la comuna\u201d.<\/p>\n<p>Conocido como el sitio con el mejor clima del mundo, Amaicha comenz\u00f3 a contar las horas para iniciar los festejos que tanto han marcado su sello de identidad. \u201cSe avecina un fin de semana a pleno\u201d, pronostic\u00f3 Pastrana. Por esa raz\u00f3n, se especula con la posibilidad de habilitar casas de familia para recibir a los visitantes que, una vez m\u00e1s, participar\u00e1n del baile bajo la enramada, una postal tradicional de Amaicha del Valle.<\/p>\n<h6>Fuente: La Gaceta<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La Fiesta Nacional de la Pachamama, coincidente con los carnavales, arranca este jueves. M\u00fasica en vivo, bailes y mucha tradici\u00f3n<\/p>\n","protected":false},"author":2,"featured_media":73078,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[33],"class_list":["post-73077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiestas","tag-tucuman"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/73077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=73077"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/73077\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/73078"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=73077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=73077"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=73077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}