{"id":73108,"date":"2018-02-19T06:47:24","date_gmt":"2018-02-19T09:47:24","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=73108"},"modified":"2018-02-19T06:47:24","modified_gmt":"2018-02-19T09:47:24","slug":"la-marcha-los-paises","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/la-marcha-los-paises\/","title":{"rendered":"La marcha y los pa\u00edses"},"content":{"rendered":"<p>Ante la marcha de pasado ma\u00f1ana, he aqu\u00ed una conjetural mirada panor\u00e1mica:<\/p>\n<p>1\u00a0El pa\u00eds popular, el pa\u00eds trabajador, est\u00e1 casi en ruinas, en shock y en duelo. Son muchos millones de compatriotas desconcertados, deprimidos, sin rumbo, algunos en p\u00e1nico. Igual los precarizados, los monotributistas, los no sindicalizados. No parece que reconozcan liderazgos, m\u00e1s bien \u201cno creen en nada\u201d. Y muchos marchar\u00e1n, es claro, pero tambi\u00e9n muchos no, porque las dudas son infinitas. En El Manifiesto Argentino pensamos que, por todo eso mismo, hay que marchar el 21F.<\/p>\n<p>2\u00a0El pa\u00eds de los ricos y sus offshores contin\u00faa exultante. Chochos de la vida en su irresponsabilidad custodiada por expertos, su marchita nismaniana de este s\u00e1bado 17 junt\u00f3 apenas un centenar de personas. Flacura que acaso indique que tambi\u00e9n est\u00e1n disconformes, aunque en voz baja, con los extrav\u00edos del gobierno. Entonces no marchan, pero siguen creyendo, como ni\u00f1os, en la infalibilidad del gato. Mirar\u00e1n el 21F por la tele y no entender\u00e1n nada, como siempre.<\/p>\n<p>3\u00a0El pa\u00eds autoritario y fascista es el m\u00e1s contento. Encantados con la mano dura que garantizan un presidente offshore de pocas luces y una ex montonera devenida favorita del imperio, son el verdadero poder, hoy, en este pa\u00eds at\u00f3nito. Armados y feroces, seguramente van a provocar para ejercer su violencia. Salvo algunos imb\u00e9ciles residuales, toda violencia en la marcha estar\u00e1 a cargo de polic\u00edas, gendarmes y otros represores. Ellos s\u00ed van a estar, brutales.<\/p>\n<p>4\u00a0El pa\u00eds sindical cl\u00e1sico est\u00e1 en descomposici\u00f3n y no va a ir. La CGT ya no representa al sector obrero porque, la verdad, hay cada vez menos obreros. Y los dirigentes de los grandes gremios, de producci\u00f3n y de servicios, engordaron tanto que ahora son obesos. Sumisos y obedientes del poder de turno, ni un tri\u00e1ngulo equil\u00e1tero han sabido mantener. Tambi\u00e9n mirar\u00e1n la tele, acaso desde sus retretes.<\/p>\n<p>5\u00a0El pa\u00eds de las bases sindicales es el que va a constituir el grueso de la marcha. El pueblo trabajador que forma el verdadero movimiento obrero argentino, hoy con millones de desocupados y codo a codo con lo mejor del sindicalismo: \u00e9se que se nuclea en unas 3 mil organizaciones con m\u00e1s de 70 mil delegados, la inmensa mayor\u00eda de ellos abnegados y decentes. Van a ser el grueso de esta marcha de protesta y hartazgo, y a sabiendas de que el camionero convocante no es confiable. Porque siempre entremezcl\u00f3 fichas personales, y s\u00f3lo patale\u00f3 fuerte cada vez que el Poder insinu\u00f3 investigar su patrimonio y alguna presunta estancia entrerriana. Y porque fue instrumento clave para que este gobierno miserable est\u00e9 donde est\u00e1. A conciencia de todo ello, este pa\u00eds de laburantes va a marchar el 21.<\/p>\n<p>6\u00a0El pa\u00eds empresarial nacional est\u00e1 tambi\u00e9n en llamas, pero es poquito lo que se va a movilizar porque es poquito lo que queda de la industria nacional. S\u00f3lo algunas pymes que sobreviven como pueden, algunas heroicamente, van a marchar junto a sus trabajadores. Mientras que el pa\u00eds del empresariado cipayo, ya sabemos.<\/p>\n<p>7\u00a0El pa\u00eds de la educaci\u00f3n, la cultura y la salud, y el de los jubilados a quienes les tocan la cola todos los d\u00edas, tambi\u00e9n van a marchar. Salvo los necios y los muchos mentalmente formateados por la telebasura y los mentimedios, claro est\u00e1.<\/p>\n<p>8\u00a0El pa\u00eds pol\u00edtico opositor, que est\u00e1 hecho cruvica \u2013como decimos en el Nordeste cuando algo est\u00e1 todo roto\u2013 va a ir en su inmensa mayor\u00eda. Con banderas y consignas diversas, all\u00ed estar\u00e1n y eso es bueno. Hiperfragmentados, no terminan de digerir derrotas, autocr\u00edticas y carpetazos pero ahora en saludable efervescencia para resurgir. Los peronistas, al menos. Porque el radicalismo hist\u00f3rico, nacional y popular, hoy es dirigencialmente minoritario y quien debiera liderar el resurgimiento, Ricardo Alfons\u00edn, no se decide o no se atreve.<\/p>\n<p>9\u00a0El pa\u00eds peronista, por cierto, bien har\u00eda en reflexionar sobre la eterna y reiterada inutilidad de las unidades forzadas. El viejo estilo de roscas dirigenciales del PJ trajo desilusiones de alto costo una y otra vez. Por eso el conqui\u00e9n y el paraqu\u00e9, hoy, imponen extremos cuidados. Pero para ello las autocr\u00edticas deben practicarse en voz alta de una buena vez, y que la sepa el pueblo, que es el que vota. Bancarse reproches p\u00fablicos (por deslealtades o traiciones) le har\u00eda mucho bien a m\u00e1s de uno. Y adem\u00e1s ser\u00eda higi\u00e9nico que muchos mariscales de las derrotas en 2015 y 2017 den un paso al costado, para que los puestos dirigenciales los ocupen tambi\u00e9n mujeres y j\u00f3venes peronistas, que son much\u00edsimos y est\u00e1n hartos\/as, y con raz\u00f3n.<\/p>\n<p>10\u00a0El pa\u00eds de la econom\u00eda seguir\u00e1 sordo, usado ad-infinitum por los medios. S\u00f3lo muy lentamente este pa\u00eds aprender\u00e1 que no tiene sentido escuchar a tanto cretino economista cuando el desastre es pol\u00edtico y social.<\/p>\n<p>Son demasiados pa\u00edses para una sola marcha, pero es posible ilusionarse con que esta vez sea un paso gigantesco en el camino de la recuperaci\u00f3n democr\u00e1tica, institucional y pac\u00edfica de nuestra naci\u00f3n.<\/p>\n<p>Esta marcha ser\u00e1 multitudinaria, aunque no quebrar\u00e1 la sordera del gobierno. Pero acaso sirva para lanzar un Programa Com\u00fan para la Recuperaci\u00f3n Nacional, que firmen todos los sectores p\u00fablicamente y dando la cara. S\u00f3lo as\u00ed recuperar\u00e1n credibilidad los que la perdieron, y ser\u00e1n a\u00fan m\u00e1s respetables los que no.<\/p>\n<p>Bien dec\u00eda Per\u00f3n, como repite a diario mi paisano Coqui Capitanich, que \u201cgobernar no es ordenar; gobernar es persuadir\u201d. El campo nacional y popular debe aprenderlo para que en las elecciones de 2019 nos encolumnemos, como pasado ma\u00f1ana, en lo que El Manifiesto Argentino define desde hace mucho como una gran \u201cConfluencia Nacional y Popular\u201d. Esa suma de afluentes que forman el inmenso r\u00edo indetenible.<\/p>\n<p>Por\u00a0Mempo Giardinelli<\/p>\n<h6>Fuente: P\u00e1gina 12<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Ante la marcha de pasado ma\u00f1ana, he aqu\u00ed una conjetural mirada panor\u00e1mica:\u00a0<\/p>\n","protected":false},"author":2,"featured_media":73109,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[21],"class_list":["post-73108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opiniones","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/73108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=73108"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/73108\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/73109"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=73108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=73108"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=73108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}