{"id":73114,"date":"2018-02-19T06:52:22","date_gmt":"2018-02-19T09:52:22","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=73114"},"modified":"2018-02-19T06:52:22","modified_gmt":"2018-02-19T09:52:22","slug":"municipales-santa-fe-alerta-esperan-la-convocatoria-paritarias","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/municipales-santa-fe-alerta-esperan-la-convocatoria-paritarias\/","title":{"rendered":"Municipales de Santa Fe en alerta esperan la convocatoria a Paritarias"},"content":{"rendered":"<p>SEMANA CLAVE PARA RESOLVER LAS MEDIDAS A SEGUIR. RECHAZAN EL PISO DEL 15 % Y EXIGIR\u00c1N LA VIGENCIA DE LA CL\u00c1USULA GATILLO. MOVILIZAN EL 21 A LA MARCHA NACIONAL.<\/p>\n<p>El Plenario de Secretarios Generales de los Sindicatos de Trabajadores Municipales y Comunales de la Provincia de Santa Fe, se reuni\u00f3 en la sede de FESTRAM para analizar las estrategias sindicales con el objetivo puesto en las negociaciones paritarias.<\/p>\n<p>Con la confirmaci\u00f3n del Gobierno Provincial, a trav\u00e9s de la Secretar\u00eda de Regiones, Municipios y Comunas, que ha convocado para la semana entrante a la elecci\u00f3n de los representantes de las Intendencias para constituir la Mesa Paritaria del Sector, el Plenario facult\u00f3 a sus representantes a establecer las medidas que consideren conducentes para iniciar a la mayor brevedad las discusiones salariales.<\/p>\n<p>Por otra parte, se rechaz\u00f3 por unanimidad las intenciones del Gobierno Nacional de establecer un tope salarial del 15% y ratificaron que s\u00f3lo la vigencia de la cl\u00e1usula gatillo garantizar\u00e1 un acuerdo viable, en el medio de un proceso inflacionario descontrolado que est\u00e1 pulverizando el poder adquisitivo de los salarios.<\/p>\n<p>Frente a las medidas que impulsa el Gobierno de Macri en materia salarial, apresurando acuerdos paritarios a la baja, e impulsando una Reforma Laboral por Decreto, se decidi\u00f3 reclamar \u00a0la derogaci\u00f3n de la Reforma Previsional, en solidaridad con los miles de trabajadores despedidos y en resistencia al ajuste. En consecuencia el Plenario resolvi\u00f3 que los Sindicatos procedan a organizarse para concurrir a la movilizaci\u00f3n convocada por el Movimiento Obrero, el pr\u00f3ximo 21 de Febrero a la ciudad de Buenos Aires.<\/p>\n<p>FESTRAM expres\u00f3 su apoyo al Documento \u201cDefensa de la Producci\u00f3n y el Trabajo Nacional. \u00a0Movilizaci\u00f3n del 21\/2\u201d impulsado desde la Corriente Federal de Trabajadores y que cuenta con la adhesi\u00f3n de \u00a0las CTA, Delegaciones Regionales de la CGT, Movimiento de Jubilados, Agrupaciones Estudiantiles, C\u00e1mara de Empresarios, Movimientos Sociales y Gremios adheridos a la CGT entre ellos la Confederaci\u00f3n de Trabajadores Municipales de la Rep\u00fablica Argentina (CTM).<\/p>\n<p>Adem\u00e1s el Plenario resolvi\u00f3 adherir al paro de Mujeres el pr\u00f3ximo 8 de Marzo, que se implementar\u00e1 respetando la modalidad que adopte cada Sindicato para reivindicar las luchas de las Mujeres Trabajadoras, la vigencia de sus Derechos y contra la Violencia de g\u00e9nero.<\/p>\n<p>Por \u00faltimo, expresaron su repudio a la decisi\u00f3n de la Legislatura santafesina de avalar el Pacto Fiscal firmado por el Gobernador de la Provincia y el Presidente de la Naci\u00f3n, y se comprometieron a avanzar en el an\u00e1lisis de un Plan de Lucha contra las medidas que deriven de ese acuerdo, como as\u00ed tambi\u00e9n por la urgente actualizaci\u00f3n de las Asignaciones Familiares que mantienen s\u00f3lo un valor simb\u00f3lico e inconstitucional.<\/p>\n<h6>PRENSA FESTRAM<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>SEMANA CLAVE PARA RESOLVER LAS MEDIDAS A SEGUIR. RECHAZAN EL PISO DEL 15 % Y EXIGIR\u00c1N LA VIGENCIA DE LA CL\u00c1USULA GATILLO. MOVILIZAN EL 21 A LA MARCHA NACIONAL.<\/p>\n","protected":false},"author":2,"featured_media":73115,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[10],"class_list":["post-73114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-sindical","tag-santa-fe"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/73114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=73114"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/73114\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/73115"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=73114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=73114"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=73114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}