{"id":73227,"date":"2018-02-20T07:22:54","date_gmt":"2018-02-20T10:22:54","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=73227"},"modified":"2018-02-20T07:22:54","modified_gmt":"2018-02-20T10:22:54","slug":"rio-los-militares-licencia-matar","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/rio-los-militares-licencia-matar\/","title":{"rendered":"R\u00edo: Los militares, con licencia para matar"},"content":{"rendered":"<p>La intervenci\u00f3n militar en R\u00edo instal\u00f3 una pol\u00e9mica por la aplicaci\u00f3n de una ley seg\u00fan la cual quienes cometan delitos en la operaci\u00f3n, entre ellos violaciones a los derechos humanos, ser\u00e1n juzgados por la Justicia castrense.<\/p>\n<p>La inminente intervenci\u00f3n militar en R\u00edo de Janeiro instal\u00f3 en Brasil una pol\u00e9mica por la aplicaci\u00f3n de una ley seg\u00fan la cual quienes cometan delitos en la operaci\u00f3n, entre ellos violaciones a los derechos humanos, ser\u00e1n juzgados por la Justicia castrense en lugar de la civil ordinaria.<\/p>\n<p>\u201cEsto es una licencia para matar, porque es darle a los militares un tribunal de excepci\u00f3n, para juzgarse a s\u00ed mismos\u201d, dijo el abogado Ariel de Castro Alves, especialista en seguridad p\u00fablica de la Pontificia Universidad Cat\u00f3lica y miembro del Movimiento Nacional de Derechos Humanos.<\/p>\n<p>La ley castrense vigente hab\u00eda sido reclamada por el jefe del Ej\u00e9rcito, general Eduardo Vilas Boas, a ra\u00edz de la participaci\u00f3n de esa fuerza armada en la seguridad p\u00fablica durante los Juegos Ol\u00edmipicos de R\u00edo de Janeiro 2016.<\/p>\n<p>El pedido de Vilas Boas se fund\u00f3 tambi\u00e9n en la actuaci\u00f3n de los militares como apoyo a la Polic\u00eda carioca durante el segundo semestre del a\u00f1o pasado.<\/p>\n<p>Por la nueva ley promulgada el 16 de octubre por el gobierno de Michel Temer, cualquier miembro de la Fuerza A\u00e9rea, Ej\u00e9rcito o Marina que cometa un homicidio en un operativo en su propio territorio ser\u00e1 juzgado por tribunales militares, muchas veces ocupados por jefes castrenses que no son juristas.<\/p>\n<p>\u201cBuscamos con la ley \u2013explic\u00f3 el diputado Espiridao Amin del conservador Partido Progresista y autor del proyecto\u2013 darle seguridad jur\u00eddica a los militares, porque la normativa no especificaba sus atribuciones en operaciones internas\u201d.<\/p>\n<p>El militar que agreda o mate a alguien fuera de su horario de trabajo o de operaciones internas deber\u00e1 ser juzgado por la justicia ordinaria y no por los tribunales castrenses.<\/p>\n<p>\u201cEl asunto deber ser abordado por el Supremo Tribunal Federal, porque es inconstitucional que haya tribunales especiales para algunos brasile\u00f1os\u201d, sostuvo el abogado Castro Alves. \u201cEs una licencia para matar, porque la justicia militar es corporativa, resuelve sus mismos problemas\u201d, insisti\u00f3.<\/p>\n<p>Organismos defensores de los derechos humanos, como la estadounidense Human Rights Watch y la brit\u00e1nica Amnist\u00eda Internacional, repudiaron esa medida por considerar que viola los acuerdos internacionales de Brasil.<\/p>\n<p>Castro Alves dijo que la operaci\u00f3n del Ej\u00e9rcito corre el riesgo de fracasar como las Unidades de Polic\u00edas Pacificadoras que se instalaron en 2008 hasta la actualidad recuperando territorio a los narcotraficantes en las favelas cariocas.<\/p>\n<p>\u201cLos militares est\u00e1n entrenados para la guerra, no para el conflicto de la delincuencia. Una intervenci\u00f3n deber\u00eda ser tambi\u00e9n en pol\u00edticas p\u00fablicas generales, salud, educaci\u00f3n, ocio, deportes, tratamiento de pacientes qu\u00edmicos\u201d, subray\u00f3.<\/p>\n<p>\u201cNo se puede esperar que un chico que no tiene banco en la escuela de su barrio no acepte ser parte del narcotr\u00e1fico por lo que ser\u00eda unos 80 d\u00f3lares por d\u00eda\u201d, agreg\u00f3 el especialista de la Pontificia Universidad Cat\u00f3lica. Apunt\u00f3 que uno de los problemas de R\u00edo es la corrupci\u00f3n policial pero tambi\u00e9n la falta de inversi\u00f3n en inteligencia e investigaci\u00f3n: apenas 10% de los homicidios se esclarecen en ese estado.<\/p>\n<p>Otro punto al que varios especialistas apuntan es que la mayor parte de los soldados del Ej\u00e9rcito son j\u00f3venes con domicilios en favelas y buscar\u00e1n protecci\u00f3n extra para participar de las operaciones, de modo de proteger a sus familias del narcotr\u00e1fico o de los grupos parapoliciales.<\/p>\n<p>La cuesti\u00f3n de los tribunales militares se da en un contexto en el que se dispar\u00f3 la popularidad del diputado Jair Bolsonaro, un ex capit\u00e1n del Ej\u00e9rcito que pide mano dura y reivindica los reg\u00edmenes de facto.<\/p>\n<p>Bolsonaro aparece como segundo favorito en las encuestas para las elecciones presidenciales brasile\u00f1as, detr\u00e1s de Luiz In\u00e1cio Lula da Silva, del opositor Partido e los Trabajadores.<\/p>\n<p>En Brasil, los militares que cometieron torturas, muertes y desapariciones durante la \u00faltima dictadura militar est\u00e1n bajo protecci\u00f3n de la ley de Amnist\u00eda de 1979, que el propio r\u00e9gimen castrense aprob\u00f3 como parte de su apertura pol\u00edtica para el retorno a la democracia.<\/p>\n<p>La semana pasada, la fiscal general, Raquel Dodge, pidi\u00f3 al Supremo Tribunal Federal revisar la ley de Amnist\u00eda para poder juzgar a los autores de la muerte y ocultaci\u00f3n del cad\u00e1ver del diputado Rubens Paiva, en 1971 en R\u00edo de Janeiro. Las asociaciones de militares retirados se pronunciaron en contra del pedido de la fiscal general.<\/p>\n<h6>Fuente: P\u00e1gina 12<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La intervenci\u00f3n militar en R\u00edo instal\u00f3 una pol\u00e9mica por la aplicaci\u00f3n de una ley seg\u00fan la cual quienes cometan delitos en la operaci\u00f3n, entre ellos violaciones a los derechos humanos, ser\u00e1n juzgados por la Justicia castrense.<\/p>\n","protected":false},"author":2,"featured_media":73228,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[57],"class_list":["post-73227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-mundo","tag-el-mundo"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/73227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=73227"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/73227\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/73228"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=73227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=73227"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=73227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}