{"id":73436,"date":"2018-02-26T06:33:28","date_gmt":"2018-02-26T09:33:28","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=73436"},"modified":"2018-02-26T07:35:08","modified_gmt":"2018-02-26T10:35:08","slug":"dujovne-paso-mal-momento-madrid","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/dujovne-paso-mal-momento-madrid\/","title":{"rendered":"Dujovne pas\u00f3 un mal momento en Madrid"},"content":{"rendered":"<p>El ministro dijo que la pobreza hab\u00eda bajado y le retrucaron que los datos de la UCA, antes destacados por Cambiemos, muestran una suba. \u201c\u00bfC\u00f3mo espera que vayan las inversiones a la Argentina si usted mantiene su patrimonio en offshore?\u201d, fue otra pregunta inc\u00f3moda.<\/p>\n<p>\u201c\u00bfC\u00f3mo espera que vayan las inversiones a la Argentina si usted mantiene su patrimonio en offshore?\u201d, le pregunt\u00f3 un docente de la Universidad Complutense de Madrid al ministro de Hacienda, Nicol\u00e1s Dujovne, en el \u00faltimo evento de su visita oficial a Espa\u00f1a. \u201cMi patrimonio est\u00e1 correctamente declarado, a diferencia de lo que suced\u00eda con el gobierno anterior\u201d, fue la sint\u00e9tica respuesta del titular del Palacio de Hacienda al referirse a los 55 millones de pesos en activos que inform\u00f3 tener en el exterior. Los cuestionamientos tambi\u00e9n alcanzaron a las mediciones oficiales de pobreza que dan cuenta de una mejora. \u201cUsted est\u00e1 mintiendo\u201d, le achac\u00f3 el docente desde el p\u00fablico al contrastar su intervenci\u00f3n con los datos elaborados por el Observatorio de la Deuda Social de la UCA. Finalizado el evento, Dujovne rest\u00f3 relevancia a la proliferaci\u00f3n de sociedades offshore vinculadas a funcionarios del gobierno de Mauricio Macri. \u201cEs una excepci\u00f3n a la regla\u201d, consider\u00f3 al referirse a la cuenta bancaria no declarada con 1,2 mill\u00f3n de d\u00f3lares controlada en Andorra por el desplazado subsecretario general de la Presidencia, Valent\u00edn D\u00edaz Gilligan.<\/p>\n<p>\u201cEs una omisi\u00f3n vinculada a su actividad privada previa a la actividad p\u00fablica. No es un caso de corrupci\u00f3n, sino de omisi\u00f3n en su declaraci\u00f3n de impuestos\u201d, asegur\u00f3 el titular del Palacio de Hacienda al defender el accionar de su ex compa\u00f1ero de gabinete. A pesar de la confianza de Dujovne en D\u00edaz Gilligan, la participaci\u00f3n del renunciante en el mundo offshore hasta noviembre de 2014 coincidi\u00f3 con su desempe\u00f1o como directivo del Ente de Turismo porte\u00f1o cuando Mauricio Macri era jefe de Gobierno de la Ciudad de Buenos Aires. \u201cHa sido un caso aislado dentro de un gobierno que est\u00e1 cumpliendo con est\u00e1ndares en t\u00e9rminos de informaci\u00f3n y \u00e9tica superiores al pasado\u201d, consider\u00f3 Dujovne al ser consultado por medios argentinos al finalizar el evento realizado en Casa Am\u00e9rica que organiz\u00f3 Tribuna EFE.<\/p>\n<p>Como sucedi\u00f3 anteayer, el ministro destac\u00f3 la necesidad de nuevas inversiones espa\u00f1olas, promocion\u00f3 los beneficios para grandes empresas previstos en la \u00faltima reforma fiscal y celebr\u00f3 la apertura comercial. \u201cTenemos muy pocas herramientas para luchar contra la inflaci\u00f3n, pero una voluntad de hierro, vamos a derrotarla\u201d, alent\u00f3 el funcionario el jueves en un encuentro con empresarios donde intent\u00f3 incentivar la llegada de inversiones extranjeras al pa\u00eds.<\/p>\n<p>Durante la ronda de preguntas que sigui\u00f3 a su \u00faltima presentaci\u00f3n el funcionario fue consultado sobre un incremento en los niveles de pobreza. \u201cCreo que el problema del profesor este de la Complutense es que est\u00e1 utilizando los datos del Indec cuando era manipulado por el gobierno anterior\u201d, comenz\u00f3 a responder el ministro Dujovne que r\u00e1pidamente fue interrumpido por el autor de la pregunta. \u201cLos datos son de la Universidad Cat\u00f3lica Argentina, que es el mejor informe, y que ustedes siempre han utilizado como referencia. Antes val\u00edan y ahora no. Usted est\u00e1 mintiendo y lo sabe\u201d, expres\u00f3 Jorge Fonseca, el docente argentino de la UCM que tambi\u00e9n lo interpel\u00f3 sobre su patrimonio declarado fuera del pa\u00eds.<\/p>\n<p>Los datos elaborados por el Observatorio de la Deuda Social de la UCA pasaron de 29 a 31,4 por ciento desde el recambio presidencial, mientras que al retomar la publicaci\u00f3n de los datos despu\u00e9s del apag\u00f3n estad\u00edstico y cambios metodol\u00f3gicos el Indec mostr\u00f3 una mejora. Los datos del Indec fueron utilizados por Dujovne para avanzar en su comentario.\u201cEl Indec no med\u00eda la pobreza durante el kirchnerismo\u201d, consider\u00f3 el funcionario. \u201cAhora tampoco\u201d, respondi\u00f3 Fonseca que tambi\u00e9n es miembro de la Asociaci\u00f3n por la Tasaci\u00f3n de las Transacciones financieras y por la Acci\u00f3n Ciudadana (Attac). \u201cDebemos tomar la primera cifra del Indec, luego de la intervenci\u00f3n, que es superior al 32 por ciento y ahora se sit\u00faa en el 28 por ciento\u201d, sostuvo Dujovne.<\/p>\n<h6>Fuente: Pagina 12<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El ministro dijo que la pobreza hab\u00eda bajado y le retrucaron que los datos de la UCA, antes destacados por Cambiemos, muestran una suba. \u201c\u00bfC\u00f3mo espera que vayan las inversiones a la Argentina si usted mantiene su patrimonio en offshore?\u201d, fue otra pregunta inc\u00f3moda.<\/p>\n","protected":false},"author":2,"featured_media":73437,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[21],"class_list":["post-73436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-nacional","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/73436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=73436"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/73436\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/73437"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=73436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=73436"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=73436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}