{"id":73478,"date":"2018-02-26T06:29:07","date_gmt":"2018-02-26T09:29:07","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=73478"},"modified":"2018-02-26T08:31:59","modified_gmt":"2018-02-26T11:31:59","slug":"dura-advertencia-nacion-las-provincias-se-excedan-los-acuerdos-salariales","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/dura-advertencia-nacion-las-provincias-se-excedan-los-acuerdos-salariales\/","title":{"rendered":"Dura advertencia de Naci\u00f3n a las provincias que se excedan en los acuerdos salariales"},"content":{"rendered":"<p>As\u00ed lo plasmaron funcionarios de Econom\u00eda del Gobierno nacional a sus pares de las provincias durante el encuentro llevado a cabo la semana pasada. Advirtieron que no habr\u00e1 alivios a la ley de Responsabilidad Fiscal a la que adhirieron la mayor\u00eda de las provincias si se exceden en acuerdos salariales por encima del 15%. \u201cNo marcaremos pauta\u201d se\u00f1alaron desde el Palacio de Hacienda, pero s\u00ed aclararon que \u201ctampoco habr\u00e1 excepciones a la ley\u201d.<\/p>\n<p>Los representantes del Ministerio de Econom\u00eda de la Naci\u00f3n advirtieron a sus pares de las distintas provincias que \u201cno flexibilizar\u00e1n\u201d la Ley de Responsabilidad Fiscal para aquellas jurisdicciones que se excedan en otorgar aumentos por encima del 15%.<br \/>\nDicha advertencia fue realizada durante la reuni\u00f3n del Comit\u00e9 Ejecutivo del Consejo Federal de Responsabilidad Fiscal que se realiz\u00f3 la semana pasada en Buenos Aires. Por Tierra del Fuego asisti\u00f3 al encuentro la secretaria de Hacienda, Romina Buearc.<br \/>\n\u201cNo marcaremos pauta ni habr\u00e1 excepciones a ley\u201d, se\u00f1alaron los funcionarios nacionales exhibiendo una l\u00ednea dura ante los enviados econ\u00f3micos de los mandatarios de las distintas provincias, inform\u00f3 el diario \u00c1mbito Financiero.<br \/>\nDurante el encuentro algunas provincias plantearon a Naci\u00f3n la necesidad de no contemplar el efecto arrastre de las subas salariales de 2017 a la hora de calcular el margen que ley fiscal les otorga para definir los incrementos de este a\u00f1o, a partir de la obligaci\u00f3n de no aumentar el gasto primario corriente por encima de la inflaci\u00f3n, pautada en el 15,7%.<br \/>\n\u00abHubo algunos pedidos de flexibilizar el tema de qu\u00e9 se va a tener en cuenta a la hora de medir las pautas de gasto, pero no vamos a empezar con las excepciones porque si no la ley se convierte en una herramienta sin utilidad\u00bb, argumentaron ante \u00c1mbito Financiero desde despachos nacionales,<br \/>\nTambi\u00e9n enfatizaron \u00abel margen de cada provincia para definirlo va a correr por cuenta de cada una, pero siempre acompa\u00f1ado del cumplimiento de la ley\u00bb, argumentaron.<br \/>\nEl riesgo es grande para los gobernadores, porque hay penalidades por incumplir la nueva Ley de Responsabilidad Fiscal, sancionada en diciembre pasado, como la no autorizaci\u00f3n a endeudamientos y restricciones en las transferencias discrecionales de Naci\u00f3n, bajo la bandera de profundizar la embestida contra el achique del d\u00e9ficit.<br \/>\n\u00abNo va a haber ninguna excepci\u00f3n en el cumplimiento de la ley, como no tener en cuenta el efecto arrastre de los incrementos salariales del a\u00f1o pasado para el c\u00e1lculo del d\u00e9ficit\u00bb, agregaron.<\/p>\n<p>Inician las paritarias esta semana<\/p>\n<p>En medio de la advertencia de Naci\u00f3n esta semana en Tierra del Fuego dar\u00e1n comienzo las paritarias con el tema salarial como prioridad para las distintas extracciones sindicales.<br \/>\nMa\u00f1ana martes la reuni\u00f3n ser\u00e1 en R\u00edo Grande con los gremios del escalaf\u00f3n seco que incluye a toda la administraci\u00f3n central, trabajadores de Casa de Gobierno y trabajadores Pomys, de maestranza.<br \/>\nEl mi\u00e9rcoles fueron convocados los sindicatos de Salud, que estar\u00e1 representado por ATSA y al d\u00eda siguiente, el jueves, ser\u00e1 el encuentro con los gremios docentes, como SUTEF y UDA entre otros.<\/p>\n<h6>Fuente: El Diario del Fin del Mundo<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>As\u00ed lo plasmaron funcionarios de Econom\u00eda del Gobierno nacional a sus pares de las provincias durante el encuentro llevado a cabo la semana pasada.<\/p>\n","protected":false},"author":2,"featured_media":73479,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[34],"class_list":["post-73478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincias","tag-tierra-del-fuego"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/73478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=73478"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/73478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/73479"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=73478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=73478"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=73478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}