{"id":74320,"date":"2018-03-16T08:16:24","date_gmt":"2018-03-16T11:16:24","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=74320"},"modified":"2018-03-16T08:16:24","modified_gmt":"2018-03-16T11:16:24","slug":"godoy-cruz-se-adelanta-construira-primer-metrobus","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/godoy-cruz-se-adelanta-construira-primer-metrobus\/","title":{"rendered":"Godoy Cruz se adelanta y construir\u00e1 el primer \u00abMetrob\u00fas\u00bb"},"content":{"rendered":"<p>El municipio pondr\u00e1 carriles exclusivos y 20 paradores en buena parte de la avenida San Mart\u00edn y San Mart\u00edn Sur.<\/p>\n<p>Mientras se desarrollan las obras para la reconstrucci\u00f3n y refuncionalizaci\u00f3n del carril Godoy Cruz, en Guaymall\u00e9n, el otro &#8216;Godoy Cruz&#8217; le ganar\u00e1 de mano a ese municipio respecto al \u00abMetrob\u00fas\u00bb para el transporte p\u00fablico.<\/p>\n<p>El municipio comandado por Tadeo Garc\u00eda Zalazar, anunci\u00f3 la puesta de carriles exclusivos con paradores urbanos sobre parte de la traza de la avenida San Mart\u00edn &#8211; San Mart\u00edn Sur, a lo largo de casi 4 kil\u00f3metros entre calles Hip\u00f3lito Yrigoyen (l\u00edmite con Ciudad) y General Paz.<\/p>\n<p>Ser\u00e1n dos carriles exclusivos (uno por sentido de circulaci\u00f3n) que estar\u00e1n al medio de la avenida, y se instalar\u00e1n 20 paradores a distancias de 400 metros cada uno, en cruces estrat\u00e9gicos.<\/p>\n<p>Este sistema tambi\u00e9n se llevar\u00e1 adelante en cuatro cuadras del eje Tiburcio Benegas &#8211; Sarmiento, entre calles Perito Moreno y Cervantes.<\/p>\n<p>Se espera que las obras comiencen a principios del segundo semestre y podr\u00edan finalizar a fin de a\u00f1o o en las primeras semanas del 2019, indicaron desde el municipio.<\/p>\n<p>Si bien no cuenta con el mismo nombre, el sistema de carriles exclusivos ideado por Godoy Cruz es muy similar al Metrob\u00fas porte\u00f1o que recorre la avenida Juan B. Justo, el primer inaugurado bajo la gesti\u00f3n del actual presidente Mauricio Macri, cuando era Jefe de Gobierno de la capital nacional.<\/p>\n<p>Tras la firma del acuerdo junto al Secretario de Servicios P\u00fablicos de la provincia, Natalio Luis Mema, Garc\u00eda Zalazar destac\u00f3 que \u00abeste es un gran paso en materia vial y en ordenamiento territorial, ya que el sistema de carriles exclusivos para colectivos, junto a las ciclov\u00edas y puentes peatonales, complementan las acciones de ciudades sustentables\u00bb.<\/p>\n<p>\u00abEste nuevo sistema de carriles exclusivos mejorar\u00e1 notablemente el flujo vehicular, no obstaculizar\u00e1 a los autos en su trayectoria ni al tr\u00e1nsito peatonal ya que las veredas quedan liberadas\u00bb, dijo el Secretario de Ambiente, Obras y Servicios, Diego Coronel.<\/p>\n<p>Por su parte la directora de Planificaci\u00f3n Urbana, Erica Pulido, destac\u00f3 que \u00abde esta manera el sistema de transporte p\u00fablico es m\u00e1s r\u00e1pido y eficiente, permitiendo brindar m\u00e1s frecuencia\u00bb. Asimismo agreg\u00f3 \u00abesta es una acci\u00f3n m\u00e1s en materia de sustentabilidad ya que el conductor mantiene una onda verde benefici\u00e1ndose en el ahorro de combustible y generando menos gases efecto invernadero\u00bb.<\/p>\n<p>La avenida San Mart\u00edn &#8211; San Mart\u00edn Sur es el principal corredor vial urbano de Godoy Cruz, atravesado por numerosas l\u00edneas de colectivos y que recorre el municipio de Norte a Sur en toda su extensi\u00f3n. Por ello, su tr\u00e1nsito es muy intenso y puede llegar a generar complicaciones, especialmente en horas pico.<\/p>\n<p>Aunque el flujo vehicular es fluido, comerciantes y peatones de la zona expresaron a\u00a0MDZsus cr\u00edticas respecto a que la avenida San Mart\u00edn no cuenta con una \u00f3ptima sincronizaci\u00f3n de sem\u00e1foros, y en determinadas horas del d\u00eda el tr\u00e1nsito puede ser bastante ca\u00f3tico. Adem\u00e1s indican que la se\u00f1alizaci\u00f3n horizontal es escasa y en algunos sectores el pavimento est\u00e1 deteriorado.<\/p>\n<p>Respecto al proyecto de carriles exclusivos, las opiniones est\u00e1n dividivas: mientras que algunos expresaron su conformidad porque \u00abordenar\u00e1 el tr\u00e1nsito\u00bb, otros consideran que la avenida \u00abes chica\u00bb para dedicarle carriles s\u00f3lo al transporte p\u00fablico, dado que dejar\u00e1 apenas dos l\u00edneas para los veh\u00edculos particulares, sin contar los espacios de estacionamiento.<\/p>\n<h6>Fuetne: MDZ Online<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El municipio pondr\u00e1 carriles exclusivos y 20 paradores en buena parte de la avenida San Mart\u00edn y San Mart\u00edn Sur.<\/p>\n","protected":false},"author":2,"featured_media":74321,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31],"class_list":["post-74320","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/74320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=74320"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/74320\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/74321"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=74320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=74320"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=74320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}