{"id":74503,"date":"2018-03-22T07:13:28","date_gmt":"2018-03-22T10:13:28","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=74503"},"modified":"2018-03-22T07:13:28","modified_gmt":"2018-03-22T10:13:28","slug":"los-pueblos-cacheuta-potrerillos-unidos-luego-19-anos","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/los-pueblos-cacheuta-potrerillos-unidos-luego-19-anos\/","title":{"rendered":"Los pueblos de Cacheuta y Potrerillos, unidos luego de 19 a\u00f1os"},"content":{"rendered":"<p>Qued\u00f3 habilitada totalmente la ruta provincial 82, con la inauguraci\u00f3n del t\u00fanel de Cacheuta, por el cual se accede al camino del perilago.<\/p>\n<p>\u201cSentir que es un soplo la vida, que 20 a\u00f1os no es nada&#8230;\u201d. Lo resume el tango, lo evidencia la alegr\u00eda y emoci\u00f3n de\u00a0casi una treintena de vecinos de Cacheuta y Potrerillos que este mi\u00e9rcoles se abrazaron entre s\u00ed y se fotografiaron con una bandera argentina de 20 metros apenas se concret\u00f3 la tan esperada reapertura del t\u00fanel que vincula ambas localidades lujaninas.<\/p>\n<p>Casi dos d\u00e9cadas despu\u00e9s de la forzada interrupci\u00f3n del tr\u00e1nsito por\u00a0la ruta provincial 82,\u00a0y tras 20 meses de trabajos en el lugar;\u00a0Cacheuta y Potrerillos recuperaron la vinculaci\u00f3n m\u00e1s directa que ten\u00edan entre s\u00ed.<\/p>\n<p>La obra comprendi\u00f3 2.200 metros de ruta -con caracoles incluidos-, de los cuales 375 son cubiertos e incluyen el t\u00fanel que atraviesa una monta\u00f1a. Y que alguna vez fuera bautizado en un documental de Discovery Channel como \u201cun fracaso de la ingenier\u00eda\u201d.<\/p>\n<p>\u201cAntes ven\u00edamos a Potrerillos seguido. Los chicos ven\u00edan a la escuela ac\u00e1, los grandes ven\u00edan al centro de salud. Pero desde que cerraron el t\u00fanel, mucha gente dej\u00f3 de venir. Yo hac\u00eda 20 a\u00f1os que no ven\u00eda\u201d, resumi\u00f3\u00a0Carina Lombino, comerciante que tiene su negocio en el play\u00f3n de Cacheuta. El mismo punto donde, hasta ayer, hab\u00eda una barrera que imped\u00eda el paso de cualquier veh\u00edculo.<\/p>\n<p>\u201cHemos vuelto a estar separados por s\u00f3lo 12 kil\u00f3metros. Con la vuelta larga, yendo por la ruta a Chile, tenemos que hacer 70 kil\u00f3metros para ir de un lugar al otro\u201d, agreg\u00f3.<\/p>\n<p>La inauguraci\u00f3n estuvo encabezada por el gobernador\u00a0Alfredo Cornejo\u00a0y las autoridades del BID, entidad que co financi\u00f3 la obra.<\/p>\n<p>\u201c\u00a1Viva Cacheuta, viva Potrerillos, viva Luj\u00e1n!\u201d repitieron una y otra vez, entre brindis y bocados los vecinos de los dos distritos.<\/p>\n<p><strong>Ansiado<\/strong><\/p>\n<p>Con la construcci\u00f3n y posterior inauguraci\u00f3n del\u00a0Dique Potrerillos, la vinculaci\u00f3n por la ruta 82 se vio trunca a fines de la d\u00e9cada del 90. \u201cDe chico ven\u00eda a la escuela en Potrerillos en bicicleta.\u00a0Pero eso pas\u00f3 a ser imposible, y la gente y los chicos tienen que ir a escuelas y centros de salud en la Ciudad de Luj\u00e1n ahora. Esperemos que con esto cambie\u201d, resumi\u00f3 Fabi\u00e1n Campusano, presidente de la Uni\u00f3n Vecinal Cacheuta.<\/p>\n<p>Del otro lado del t\u00fanel, tambi\u00e9n hubo mucha euforia.\u00a0\u201cEs una inmensa alegr\u00eda. Con el dique nos cortaron el paso, pero ahora somos dos pueblos hermanos que nos volvimos a juntar despu\u00e9s de 20 a\u00f1os\u201d, rememor\u00f3\u00a0Elsa Gonz\u00e1lez (55), quien tambi\u00e9n es comerciante, pero en Potrerillos.<\/p>\n<p>\u201cDesde que cerraron esta ruta yo no volv\u00ed a ir a Cacheuta. lo bueno es que los viajes para ir al m\u00e9dico van a ser m\u00e1s cortos ahora\u201d, acot\u00f3 su hermana\u00a0F\u00e1tima del Carmen (62), quien adem\u00e1s ostenta la corona de reina de los adultos mayores de Potrerillos y de virreina de Luj\u00e1n.<\/p>\n<p>M\u00e1s all\u00e1 de la felicidad, las dos hermanas coincidieron en que ahora va a ser necesario tambi\u00e9n que se intensifiquen los controles, porque tienen en claro que crecer\u00e1 el flujo vehicular en el lugar (aunque por el t\u00fanel est\u00e1 prohibida la circulaci\u00f3n de tr\u00e1nsito pesado).<\/p>\n<p>La Semana Santa pr\u00f3xima (del 29 de marzo al 2 de abril, inclusiva) ser\u00e1 la prueba clave para ver la capacidad de respuesta del flamante paso.\u00a0M\u00e1s teniendo en cuenta que Cacheuta es una localidad en la que viven 150 personas; pero que los fines de semana recibe a unas 3.500 (y el mencionado tendr\u00e1 5 d\u00edas).<\/p>\n<p>\u201cPas\u00f3 tanto tiempo, tantos gobiernos y tantas veces la promesa que pensamos que nunca \u00edbamos a ver el t\u00fanel reabierto\u201d, se sincer\u00f3 Graciela Gonz\u00e1lez, otra comerciante de Cacheuta.<\/p>\n<p>Luego del abrazo simb\u00f3lico y de posar para las fotos -incluso junto a Cornejo, los representantes del BID y el intendente lujanino, Omar De Marchi-,\u00a0los vecinos aprovecharon para brindar por el reencuentro y compartir unas tortitas, sanguchitos y masitas dulces en el gacebo que hab\u00edan levantado para la inauguraci\u00f3n.<\/p>\n<p>Por fuera de la ceremonia, las autoridades entregaron obsequios a las primeras personas que cruzaron de forma rutinaria por el t\u00fanel.\u00a0Ellos fueron Ignacio Osorio (en su bicicleta) y Horacio le Donne (en moto).<\/p>\n<p>\u201cSomos de\u00a0 venir seguido para Potrerillos, y ahora vamos a empezar a hacerlo por esta ruta. Es espectacular, una obra buen\u00edsima que se tendr\u00eda que haber inaugurado antes. M\u00e1s con este paisaje hermoso\u201d, resumi\u00f3 el ciclista, quien aprovech\u00f3 la ocasi\u00f3n para acotar que hubiese sido bueno que se incluya una ciclov\u00eda en el paso.<\/p>\n<p><strong>Caracter\u00edsticas del t\u00fanel<\/strong><\/p>\n<p>Si bien la ruta estuvo casi dos d\u00e9cadas cerrada, la obra propiamente dicha comenz\u00f3 en abril del 2016 y fue financiada en conjunto por la Provincia y el BID.<\/p>\n<p>Hasta el 25 de mayo la circulaci\u00f3n ser\u00e1 libre y gratuita, pero a partir de esa fecha comenzar\u00e1 a operar el sistema de telepeaje.<\/p>\n<p>El costo estar\u00e1 dado por el precio del valor del litro de nafta s\u00faper, y para un auto o camioneta equivaldr\u00e1 a un litro\u00a0(en horario no pico)\u00a0y a 2 litros\u00a0(en horario pico, que incluye fines de semana y feriados de 12 a 17 horas para quienes van hacia Potrerillos, y de 17 a 20 para quienes vuelven hacia Cacheuta).<\/p>\n<p>No tendr\u00e1 barrera ni ventanilla, por lo que se har\u00e1 la lectura electr\u00f3nica de la patente y la boleta de pago deber\u00e1 imprimirse online y ser pagada en los 5 d\u00edas posteriores. Para los usuarios frecuentes estar\u00e1 la posibilidad de pago con descuento (hasta 40%), siempre y cuando se haga por adelantado.<\/p>\n<p>Adem\u00e1s, aprovechando la inauguraci\u00f3n,\u00a0desde la Secretar\u00eda de Ambiente impulsar\u00e1n un proyecto de ley en los pr\u00f3ximos d\u00edas para fijar las pautas para emprendimientos tur\u00edsticos en el lugar\u00a0(siempre respetando que se trata de tierras fiscales y el acceso a la costa sur ser\u00e1 libre para cualquiera).<\/p>\n<p>\u201cEstamos orgullosos de haber hecho esta obra en escasos meses. Es la conexi\u00f3n entre una de las zonas m\u00e1s bellas de nuestra provincia\u201d, destac\u00f3 el gobernadorAlfredo Cornejo\u00a0durante la inauguraci\u00f3n, y aclar\u00f3 que los retrasos desde su proyecci\u00f3n se debieron a responsabilidades ajenas al BID.<\/p>\n<p>Adem\u00e1s,\u00a0destac\u00f3 que pedir\u00e1n m\u00e1s financiamiento al BID para seguir mejorando la conexi\u00f3n.\u00a0\u201cSi la ruta 82 se hubiese hecho antes, la ciudad hubiese crecido para este lado y se hubiese desarrollado\u201d, agreg\u00f3.<\/p>\n<p>Por su parte, el presidente del BID, Luis Alberto Moreno\u00a0se mostr\u00f3 contento por ver la obra concretada, \u201cEn Washington DC se ven en papeles estos proyectos, pero no es lo mismo verlo en persona. Estamos felices de ver c\u00f3mo esto va a cambiar la vida de la gente, y va a mejorar el tr\u00e1nsito internacional\u201d, sintetiz\u00f3.<\/p>\n<p><strong>Peaje a fines de mayo<\/strong><\/p>\n<p>Si bien la ruta estuvo casi dos d\u00e9cadas cerrada, la obra propiamente dicha comenz\u00f3 en abril de 2016 y fue financiada en conjunto por la Provincia y el BID.<\/p>\n<p>Hasta el 25 de mayo la circulaci\u00f3n ser\u00e1 libre y gratuita, pero a partir de esa fecha comenzar\u00e1 a operar el sistema de telepeaje. El costo estar\u00e1 dado por el precio del valor del litro de nafta s\u00faper, y para un auto o camioneta equivaldr\u00e1 a un litro (en horario no pico) y a 2 litros (en horario pico, que incluye fines de semana y feriados de 12 a 17 para quienes van hacia Potrerillos, y de 17 a 20 para quienes vuelven hacia Cacheuta).<\/p>\n<p>Se har\u00e1 la lectura electr\u00f3nica de la patente y la boleta de pago deber\u00e1 imprimirse on line y ser pagada en los 5 d\u00edas posteriores. Para usuarios frecuentes estar\u00e1 la posibilidad de pago con descuento (hasta 40%), siempre y cuando se haga por adelantado.<\/p>\n<h6>Fuente: Los Andes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Qued\u00f3 habilitada totalmente la ruta provincial 82, con la inauguraci\u00f3n del t\u00fanel de Cacheuta, por el cual se accede al camino del perilago.<\/p>\n","protected":false},"author":2,"featured_media":74504,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31],"class_list":["post-74503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/74503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=74503"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/74503\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/74504"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=74503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=74503"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=74503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}