{"id":74938,"date":"2018-04-05T05:36:50","date_gmt":"2018-04-05T08:36:50","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=74938"},"modified":"2018-04-05T07:39:35","modified_gmt":"2018-04-05T10:39:35","slug":"ya-80-trapitos-mendoza-fueron-la-municipalidad-buscar-trabajo","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/ya-80-trapitos-mendoza-fueron-la-municipalidad-buscar-trabajo\/","title":{"rendered":"Ya hay 80 \u00abtrapitos\u00bb de Mendoza que fueron a la Municipalidad a buscar trabajo"},"content":{"rendered":"<p>La comuna los est\u00e1 inscribiendo para un programa de empleo en empresas. Despu\u00e9s del 15 de abril, la multa por cuidar autos ser\u00e1 de $ 1.275.<\/p>\n<p>Pese a que a\u00fan no se empieza a aplicar la ordenanza que proh\u00edbe la presencia de cuidacoches en la Ciudad de Mendoza, el d\u00eda en que se conoci\u00f3 la novedad (martes) la comuna realiz\u00f3 acciones que -seg\u00fan explicaron- tienden a desalentar estas pr\u00e1cticas para que una vez que entre en vigencia la norma, no se tengan que aplicar sanciones econ\u00f3micas.<\/p>\n<p>Paralelamente, desde la municipalidad indicaron que unos 80 cuidacoches ya se presentaron voluntariamente para sumarse al programa de empleo formal, destinado a insertarlos, por ejemplo, en empresas que realizan obras p\u00fablicas o gastron\u00f3micas. De todas formas, un cuidacoches que representa a un grupo de ellos asegur\u00f3 que no creen en las promesas de la comuna.<\/p>\n<p>Vale recordar que el 15 de abril\u00a0la ordenanza aprobada por el Concejo Deliberante\u00a0dotar\u00e1 a los preventores municipales del poder de polic\u00eda para llevar adelante medidas de fuerza contra los mal llamados \u00abtrapitos\u00bb. Entre ellas se destacan las multas que ascender\u00e1n a los 1.275 pesos para quienes luego de ser \u00abinvitados\u00bb a retirarse, no lo hagan.<\/p>\n<p><strong>Censados<\/strong><\/p>\n<p>Como se dijo, la nueva normativa establece que nadie podr\u00e1 cobrar dinero a quienes estacionen sus veh\u00edculos fuera del sistema formal de estacionamiento. Sin embargo, hasta el 15 los preventores no podr\u00e1n detener a nadie que est\u00e9 realizando esta pr\u00e1ctica.<\/p>\n<p>Ra\u00fal Levrino, secretario de Seguridad Ciudadana, aclar\u00f3 que se empezaron con tareas para desalentar la actividad desde diciembre pasado, que incluy\u00f3 mucha presencia operativa y paralelamente se decomisaron objetos destinados al lavado de los veh\u00edculos de particulares en el marco, el c\u00f3digo de convivencia ciudadana, que ya proh\u00edbe esta actividad.<\/p>\n<p>\u201cTenemos identificados 280 cuidacoches, la mayor\u00eda con domicilio en el Gran Mendoza, que trabajaban en las distintas secciones de Ciudad. Fuimos por turnos y los fines de semana, de manera de censar a la mayor\u00eda de ellos\u201d, explic\u00f3 el secretario de seguridad.<\/p>\n<p>De ellos, 80 ya han ido a solicitar trabajo, de acuerdo al programa que tiene el municipio para sumarlos al circuito de empleo formal. \u201cLa municipalidad destinar\u00e1 5.060 pesos para cada persona contratada por las empresas durante 3 meses, m\u00e1s all\u00e1 de lo que cada una les pague por su trabajo\u201d, cont\u00f3 Levrino.<\/p>\n<p>Desde la comuna comentaron que ya hay empresas de gastronom\u00eda y de obra p\u00fablica que se est\u00e1n ofreciendo para dar trabajo a los cuidacoches. \u201cPrimero ser\u00e1n capacitados y luego incoroporados\u201d, dijeron desde el ente comunal.<\/p>\n<p>Tambi\u00e9n indicaron que seg\u00fan el perfil, estas personas tambi\u00e9n podr\u00e1n empezar a trabajar en el sistema de estacionamiento medido, presentando el certificado de escolaridad de los hijos, en caso de que los tengan, y tendr\u00e1n un seguimiento por parte de asistentes sociales.<\/p>\n<p><strong>Los cuidacoches dicen que no hay trabajo<\/strong><\/p>\n<p>Consultados por\u00a0Los Andes, cuidacoches comentaron que es no es real que la Municipalidad tenga la intenci\u00f3n de hacer algo por ellos. \u201cLo \u00fanico que est\u00e1n fomentando es el robo. La gente no nos est\u00e1 dando oportunidades de trabajo y adem\u00e1s la mayor\u00eda tiene antecedentes, por lo que el panorama se complica m\u00e1s\u201d, coment\u00f3 Estaban Zeballos que los representa desde hace 6 a\u00f1os.<\/p>\n<p>\u201cHay muchos casos particulares, una mam\u00e1 de tres hijos que qued\u00f3 viuda y tiene 22 a\u00f1os. Est\u00e1 cuidando autos y no la dejan trabajar. Adem\u00e1s hay otra mujer embarazada y un padre con 9 hijos que no tiene trabajo\u201d, describi\u00f3 Zeballos.<\/p>\n<p>Los cuidacoches dicen que la situaci\u00f3n, de proseguir como hasta ahora, puede llegar a tornarse violenta, ya que ven un futuro laboral concreto. \u201cLos tarjeteros oficiales tambi\u00e9n est\u00e1n teniendo inconvenientes, porque no les alcanza para comprar tarjetas. Muchos automovilistas se escapan y otros no tienen con qu\u00e9 hacer frente a los gastos. Algunos dicen que les van a pegar a los preventores\u201d, asegur\u00f3 el vocero de los \u00abtrapitos\u00bb.<\/p>\n<h6>Fuente: Los Andes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La comuna los est\u00e1 inscribiendo para un programa de empleo en empresas. Despu\u00e9s del 15 de abril, la multa por cuidar autos ser\u00e1 de $ 1.275.<\/p>\n","protected":false},"author":2,"featured_media":74939,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31],"class_list":["post-74938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/74938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=74938"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/74938\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/74939"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=74938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=74938"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=74938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}