{"id":74944,"date":"2018-04-05T05:49:12","date_gmt":"2018-04-05T08:49:12","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=74944"},"modified":"2018-04-05T07:51:35","modified_gmt":"2018-04-05T10:51:35","slug":"tarifazo-la-crisis-fruticola-cierra-tradicional-frigorifico-godoy-cruz","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/tarifazo-la-crisis-fruticola-cierra-tradicional-frigorifico-godoy-cruz\/","title":{"rendered":"Por el tarifazo y la crisis frut\u00edcola, cierra tradicional frigor\u00edfico de Godoy Cruz"},"content":{"rendered":"<p>Luego de 72 a\u00f1os, la empresa de venta de servicios de fr\u00edo de Godoy Cruz dejar\u00e1 de funcionar.<\/p>\n<p>Impulsado por la crisis del sector frut\u00edcola y por el incremento de la tarifa el\u00e9ctrica,\u00a0Frigor\u00edficos Aconcagua SA (FASA)\u00a0decidi\u00f3 cerrar las puertas y dejar el negocio de c\u00e1maras de fr\u00edo.<\/p>\n<p>La compa\u00f1\u00eda que inici\u00f3 su actividad en el a\u00f1o\u00a01946\u00a0logr\u00f3 ser referente en el servicio de fr\u00edo, sobre todo por la ubicaci\u00f3n y el tama\u00f1o del negocio.<\/p>\n<p>Recordemos que los galpones est\u00e1n en calle\u00a0Minuzzi y Costanera, de Godoy Cruz, y el predio ronda los\u00a022 mil\u00a0metros cuadrados.<\/p>\n<p>Jaime Campomar, uno de los propietarios de\u00a0Frigor\u00edficos Aconcagua,\u00a0habl\u00f3 con\u00a0Los Andes\u00a0y detall\u00f3 cu\u00e1les fueron los motivos del directorio para tomar esta decisi\u00f3n y que conllev\u00f3 adem\u00e1s a una reorganizaci\u00f3n total de los negocios de\u00a0FASA.<\/p>\n<p>Al dejar de lado la prestaci\u00f3n de c\u00e1maras de fr\u00edo, la empresa decidi\u00f3 utilizar su capacidad instalada e incursiona en el mercado inmobiliario alquilando las m\u00e1s de40 bodegas\u00a0-sin fr\u00edo- que tienen all\u00ed mismo.<\/p>\n<p>Adem\u00e1s, la firma tiene el\u00a050% de las acciones del Frigor\u00edfico Tunuy\u00e1n, por lo que todos aquellos productos que necesitan fr\u00edo fueron trasladados a esa c\u00e1mara, concentrando as\u00ed el negocio en un solo espacio.<\/p>\n<p>No obstante,\u00a0Campomar\u00a0aclar\u00f3 que esta \u00faltima compa\u00f1\u00eda no es ajena a los incrementos de costos de la\u00a0tarifa el\u00e9ctrica\u00a0y a la disminuci\u00f3n de materia prima frut\u00edcola y vitivin\u00edcola.<\/p>\n<p>Para ejemplificar, cont\u00f3 que esta firma pagaba boletas de\u00a0luz de\u00a0$ 700.000,\u00a0pero luego de los incrementos de diciembre comenz\u00f3 a pagar m\u00e1s de\u00a02.100.000 pesos.<\/p>\n<p>Esa misma situaci\u00f3n condujo al\u00a0cierre del frigor\u00edfico Penitentes de Tunuy\u00e1n,tambi\u00e9n perteneciente a la compa\u00f1\u00eda.<\/p>\n<p><strong>Crisis sin respuesta<\/strong><\/p>\n<p>Jaime Campomar\u00a0revel\u00f3 que Frigor\u00edficos Aconcagua tom\u00f3 la decisi\u00f3n de cerrar sus puertas luego de los incrementos tarifarios, \u201cya que las facturas aumentaron de\u00a0300 mil pesos\u00a0a m\u00e1s de\u00a0550 mil pesos\u00a0por mes\u201d.<\/p>\n<p>Sin embargo, los problemas de rentabilidad ven\u00edan de mucho antes. \u201cLa empresa se manten\u00eda a fuerza de dos sectores en crisis: fruta y vinos. Esto hac\u00eda inviable incrementar cualquier precio -por los aumentos de costos-, sumado a que la\u00a0capacidad instalada del frigor\u00edfico era cada vez menor. De hecho, el a\u00f1o pasado factur\u00e1bamos por mercader\u00eda vitivin\u00edcola cerca de\u00a0$ 1.200.000 por mes,\u00a0y hoy no llegamos a los\u00a0150 mil pesos\u201d, especific\u00f3\u00a0Campomar.<\/p>\n<p>En cuanto a la\u00a0industria frut\u00edcola, Campomar explic\u00f3 que \u201cla baja cosecha, la baja rentabilidad, los incrementos de costos y la ca\u00edda de precios provocaron que la\u00a0explotaci\u00f3n de frutales en Mendoza\u00a0cediera a cultivos anuales de hortalizas gruesas, con lo que la demanda de servicios de fr\u00edo est\u00e1 en\u00a0franca decadencia\u00a0y lo poco que hay -producci\u00f3n de peras y manzanas- para las c\u00e1maras de fr\u00edo es muy bajo. Por lo que mantener grandes estructuras de este servicio es ineficiente\u201d.<\/p>\n<p>A este cuadro planteado, Campomar sum\u00f3 que \u201ca muchos de sus clientes les resulta m\u00e1s barato\u00a0perder kilos de fruta por pudrici\u00f3n que contratar el servicio de fr\u00edo, que ha sido fuertemente incrementado por la aplicaci\u00f3n de una\u00a0pol\u00edtica de ajuste de tarifas el\u00e9ctricas\u00a0(en dos a\u00f1os se multiplicaron por 7) y en sentido contrario a la suba recientemente aplicada, la fruta de industria baj\u00f3 su valor de\u00a0$ 6 del a\u00f1o anterior a\u00a0$ 3,80 por kilo\u201d.<\/p>\n<p>El directivo mencion\u00f3 que a pesar de esto la empresa no es considerada con tarifa diferencial\u00a0por no ser considerada electrointensiva. \u201cTenemos un consumo mayor a\u00a0300 kw de potencia\u00a0y somos v\u00edctima de una absurda e injusta escala tarifaria, que resulta m\u00e1s cara que la de otros establecimientos frigor\u00edficos. Esta discriminaci\u00f3n nos quita clientes y castiga en vez de premiar la eficiencia que se deriva de un negocio de mayor escala\u201d.<\/p>\n<p>Finalmente, mencion\u00f3: \u201cLas autoridades nacionales y provinciales est\u00e1n concentradas en una gesti\u00f3n que solo piensa en c\u00f3mo recaudar y no tiene en cuenta si las empresas pueden soportar esa mayor presi\u00f3n impositiva. De hecho, en enero presentamos una nota en la que solicitamos que la\u00a0AFIP\u00a0incluya a\u00a0Frigor\u00edfico Aconcagua\u00a0entre las empresas comprendidas en la\u00a0Ley 27.354\u00a0de emergencia\u00a0econ\u00f3mica, productiva y social,\u00a0y esto no sucedi\u00f3, a pesar de formar parte de la cadena de producci\u00f3n de peras y manzanas\u201d.<\/p>\n<h6>Fuente: Los andes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Luego de 72 a\u00f1os, la empresa de venta de servicios de fr\u00edo de Godoy Cruz dejar\u00e1 de funcionar.<\/p>\n","protected":false},"author":2,"featured_media":74945,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[31],"class_list":["post-74944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-economico","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/74944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=74944"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/74944\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/74945"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=74944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=74944"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=74944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}