{"id":75791,"date":"2018-04-25T08:23:42","date_gmt":"2018-04-25T11:23:42","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=75791"},"modified":"2018-04-25T08:23:42","modified_gmt":"2018-04-25T11:23:42","slug":"los-intendentes-mendocinos-las-redes-sociales-se-meten-la-polemica-fracking","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/los-intendentes-mendocinos-las-redes-sociales-se-meten-la-polemica-fracking\/","title":{"rendered":"Los intendentes mendocinos y las redes sociales se meten en la pol\u00e9mica por el fracking"},"content":{"rendered":"<p>El jefe comunal de Alvear pidi\u00f3 que no haya \u00abposturas extremas\u00bb; y el de San Carlos dijo que es inviable este modelo con crisis h\u00eddrica.<\/p>\n<p>Anoche, y convocados por las\u00a0redes sociales, cerca de\u00a01.500 alvearenses\u00a0se congregaron en ese departamento del Sur provincial para manifestarse en contra del decreto del Ejecutivo provincial que habilita la actividad en Mendoza. Y esta noche, desde las 21, tendr\u00e1 lugar una nueva asamblea, esta vez en la terminal de Eugenio Bustos (San Carlos).<\/p>\n<p>En este contexto, los intendentes de ambos departamentos tambi\u00e9n se metieron en la tem\u00e1tica. El primero fue el\u00a0jefe comunal de General Alvear, Walther Marcolini. Tras la masiva movilizaci\u00f3n, Marcolini llam\u00f3 a las asambleas a profundizar el debate para que sea \u201cserio\u201d pero despojado de \u201cposturas extremas\u201d.<\/p>\n<p>El cacique alvearense adem\u00e1s anunci\u00f3 que la semana que viene estar\u00e1 en el departamento el secretario de Ambiente de Mendoza para armar una mesa de trabajo con la intenci\u00f3n de discutir la problem\u00e1tica. Y comprometi\u00f3 el apoyo (financiero) para que las organizaciones ambientalistas convoquen a expertos en el tema con la idea de enriquecer la discusi\u00f3n.<\/p>\n<p>Por su parte, el intendente sancarlino Jorge Difonso tambi\u00e9n rechaz\u00f3 este modelo, recordando que hace 5 a\u00f1os el Municipio que comanda aprob\u00f3 la ordenanza 1.431\/13 que declar\u00f3 a San Carlos \u201clibre de fracking\u201d.<\/p>\n<p>\u201cEl perjuicio del fracking comienza incluso antes de que se vea desde el punto de vista ambiental. Mendoza tiene una crisis h\u00eddrica centrada en la comprometida disponibilidad del recurso h\u00eddrico. Y esto ya es algo que compromete al fracking, porque este sistema requiere un uso desmedido del recurso h\u00eddrico\u201d, resumi\u00f3 Difonso.<\/p>\n<p>Adem\u00e1s, consider\u00f3 que \u201ces bastante dudosa\u201d la posibilidad de una explotaci\u00f3n no contaminante por medio de este sistema. Esto a ra\u00edz de que el Gobierno de Mendoza ha prometido realizar rigurosos controles ambientales como parte de la reglamentaci\u00f3n de esta actividad.<\/p>\n<p><strong>Control<\/strong><\/p>\n<p>\u201cLamento profundamente que a trav\u00e9s de las redes se generen situaciones de p\u00e1nico. Alvear es libre de fracking y lo que hizo la provincia es reglamentar una actividad que se realiza hace muchos a\u00f1os, poniendo controles ambientales\u201d, coment\u00f3 Marcolini luego de la manifestaci\u00f3n del lunes por la noche en la ciudad de Alvear y en el distrito de Bowen.<\/p>\n<p>En ese sentido el intendente dijo que parte del debate deber\u00eda incluir \u201cseriamente que las entidades puedan ser parte del contralor. Esto tambi\u00e9n es fundamental, hay que debatirlo. Es fundamental que haya buenos y serios controles; pero sobre todo no generar p\u00e1nico en la sociedad porque nos perjudica a todos\u201d, indic\u00f3.<\/p>\n<p>Asimismo, Marcolini destac\u00f3 que la semana pr\u00f3xima visitar\u00e1 el departamento el secretario de Ambiente, Humberto Mingorance; y que aprovechar\u00e1 para convocar a las universidades y as\u00ed \u201cconfrontar las distintas posturas\u201d.<\/p>\n<p>Por \u00faltimo el jefe comunal de Alvear pidi\u00f3 que \u201csi una persona tiene conocimiento certero que se produjo la contaminaci\u00f3n y tiene las pruebas, ser\u00eda importante que se presente en la Justicia. Sino todo se maneja en las redes y nadie pone una denuncia con pruebas\u201d, concluy\u00f3.<\/p>\n<p><strong>Libre de fracking<\/strong><\/p>\n<p>El 2 de mayo del 2013, el Concejo Deliberante de San Carlos declar\u00f3 a \u201ctodo el territorio de San Carlos, municipio libre de fractura hidr\u00e1ulica (fracking)\u201d.<\/p>\n<p>\u201cTuvimos un gran debate hace 5 a\u00f1os. Porque, adem\u00e1s de lo ambiental, se generaba en ese momento un avance de las empresas petroleras de Crist\u00f3bal L\u00f3pez, empresario vinculado al gobierno kirchnerista en la Naci\u00f3n. A los pocos meses de aprobar la ordenanza, nos notificaron de una audiencia para un proyecto que inclu\u00eda fracking en el Sur del departamento, y que pertenec\u00eda a una empresa de L\u00f3pez. Luego se suspendi\u00f3 esa audiencia, con la ordenanza nos hab\u00edamos anticipado\u201d, destac\u00f3 Difonso a\u00a0Los Andes. Adem\u00e1s, el intendente comparti\u00f3 en su perfil Facebook fotos y publicaciones de aquella ordenanza y lo que gener\u00f3.<\/p>\n<p>\u201cEntre las \u00e1reas nuevas licitadas, no hay ninguna en San Carlos. Pero mantenemos nuestra postura\u201d, sostuvo el sancarlino. \u201cSi nos detenemos en lo ambiental, y en base a experiencias en otros lados, es bastante dudoso pensar en una posibilidad de fracking no contaminante. Sobre todo en el marco del principio precautorio de la protecci\u00f3n ambiental\u201d, sintetiz\u00f3.<\/p>\n<p><strong>Campa\u00f1a en las redes<\/strong><\/p>\n<p>Durante las \u00faltimas semanas \u201cexplot\u00f3\u201d en las redes sociales una fuerte campa\u00f1a anti fracking. En distintos grupos comenzaron a circular fotos, videos y hasta una petici\u00f3n de Greenpeace juntando firmas para decirle \u201cNo a la fracturaci\u00f3n hidr\u00e1ulica\u201d.<\/p>\n<p>Incluso, uno de los videos es el fragmento de un cap\u00edtulo de Los Simpsons donde -a su modo y con su \u00e1cido humor- los personajes de Matt Groening exponen un Springfield con las consecuencias del fracking.<\/p>\n<h6>Fuente: Los Andes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El jefe comunal de Alvear pidi\u00f3 que no haya \u00abposturas extremas\u00bb; y el de San Carlos dijo que es inviable este modelo con crisis h\u00eddrica.<\/p>\n","protected":false},"author":2,"featured_media":75792,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31],"class_list":["post-75791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/75791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=75791"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/75791\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/75792"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=75791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=75791"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=75791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}