{"id":78450,"date":"2018-06-26T05:34:10","date_gmt":"2018-06-26T08:34:10","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=78450"},"modified":"2018-06-25T19:36:42","modified_gmt":"2018-06-25T22:36:42","slug":"paro-nacional-provocacion-de-la-policia-de-mendoza-contra-trabajadores-municipales-de-guaymallen","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/paro-nacional-provocacion-de-la-policia-de-mendoza-contra-trabajadores-municipales-de-guaymallen\/","title":{"rendered":"Paro nacional: provocaci\u00f3n de la Polic\u00eda de Mendoza contra trabajadores municipales de Guaymall\u00e9n"},"content":{"rendered":"<p>Trabajadores municipales de Guaymall\u00e9n se encontraban en el predio de Servicios P\u00fablicos donde, en el marco del paro nacional, realizaban una acci\u00f3n por aumento de salario y la quita de \u00edtems del sueldo, cuando la infanter\u00eda irrumpi\u00f3 en el lugar con una supuesta orden de desalojo<\/p>\n<p>En el marco del paro nacional convocado, trabajadores municipales de Guaymall\u00e9n se encontraban realizando una acci\u00f3n por aumento de salario y la quita de \u00edtems del sueldo cuando la infanter\u00eda irrumpi\u00f3 en el lugar con una supuesta orden de desalojo.<\/p>\n<p>Los trabajadores denunciaron al intendente Marcelino Iglesias por la provocaci\u00f3n y destacaron que la adhesi\u00f3n al paro en el departamento es de la totalidad de los trabajadores municipales.<\/p>\n<h6>Fuente:\u00a0http:\/\/laizquierdadiario.com<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Trabajadores municipales de Guaymall\u00e9n se encontraban en el predio de Servicios P\u00fablicos donde, en el marco del paro nacional, realizaban una acci\u00f3n por aumento de salario y la quita de \u00edtems del sueldo<\/p>\n","protected":false},"author":2,"featured_media":78451,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[31],"class_list":["post-78450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-sindical","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/78450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=78450"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/78450\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/78451"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=78450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=78450"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=78450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}