{"id":80939,"date":"2018-08-30T05:44:44","date_gmt":"2018-08-30T08:44:44","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=80939"},"modified":"2018-08-29T19:47:21","modified_gmt":"2018-08-29T22:47:21","slug":"vuoto-intendente-de-ushuaia-tenemos-que-estar-juntos-rechazando-los-brutales-recortes-de-macri","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/vuoto-intendente-de-ushuaia-tenemos-que-estar-juntos-rechazando-los-brutales-recortes-de-macri\/","title":{"rendered":"Vuoto (Intendente de Ushuaia): \u00abTenemos que estar juntos rechazando los brutales recortes de Macri\u00bb"},"content":{"rendered":"<p>El intendente Walter Vuoto una vez m\u00e1s advirti\u00f3 que el gobierno nacional que encabeza el presidente Mauricio Macri \u201cviene por nuestros recursos, por menos federalismo, por la entrega de nuestra soberan\u00eda y el empobrecimiento de nuestro pueblo\u201d.<\/p>\n<p>El intendente Walter Vuoto una vez m\u00e1s advirti\u00f3 que el gobierno nacional que encabeza el presidente Mauricio Macri\u00a0 \u201cviene por nuestros recursos, por menos federalismo, por la entrega de nuestra soberan\u00eda y el empobrecimiento de nuestro pueblo\u201d.\u00a0 Celebr\u00f3 la unidad de criterio que se mantiene en la provincia y en la regi\u00f3n para\u00a0 el firme rechazo a los \u201cbrutales recortes\u201d que intenta llevar adelante el gobierno nacional mediante decretos de necesidad y urgencia como as\u00ed tambi\u00e9n en el presupuesto 2019.<\/p>\n<p>Valor\u00f3 \u201cla f\u00e9rrea posici\u00f3n de la gobernadora de Tierra del Fuego Rosana Bertone \u201cal rechazar la quita de los fondos como por ejemplo, el de la soja que corresponde a nuestro distrito y por la posici\u00f3n que en tal sentido sostiene el ministro de Econom\u00eda, Jos\u00e9 Labrocca, en las reuniones con sus pares de provincias peronistas y los funcionarios de Naci\u00f3n, rechazando de plano los recortes que intentan ingresar en el presupuesto 2019\u201d<\/p>\n<p>\u201cEs sumamente importante que podamos analizar esta enorme crisis\u00a0 que gener\u00f3 el mismo gobierno nacional con el modelo econ\u00f3mico que sostiene en todo el pa\u00eds, que no compartimos y que fundamentalmente no tiene ni puede frenarse castigando a los sectores populares con brutales recortes\u201d, sostuvo.<\/p>\n<p>Destac\u00f3 \u201cla importancia de la unidad en el actual contexto, con las exigencias de recortes\u00a0 que impone el gobierno nacional, donde el marco de decisi\u00f3n que pretenden dejar a las provincias y municipios es un men\u00fa en el que las opciones son ajustes y mayor desocupaci\u00f3n y penurias, o paralizaci\u00f3n de obras y retroceso en derechos e infraestructura\u201d.<\/p>\n<p>\u201cSumar las acciones desde todos los \u00e1mbitos de la provincia y aunar los criterios desde la regi\u00f3n son fundamentales en este momento. La gobernadora ha sido clara al proponer un mayor esfuerzo a los sectores que se han visto favorecidos con las devaluaciones, al sector financiero entre otros y la defensa de los sectores m\u00e1s vulnerables a quienes no se puede pedir mayores esfuerzos\u201d, valor\u00f3 el intendente.<\/p>\n<p>La Municipalidad de Ushuaia participa de las acciones que lleva adelante la Federaci\u00f3n Argentina de Municipios\u00a0 (FAM) y el pr\u00f3ximo 31 estar\u00e1 en la reuni\u00f3n de ciudades patag\u00f3nicas a realizarse en la ciudad de Comodoro Rivadavia.<\/p>\n<h6>Fuente: reporte Austral<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El intendente Walter Vuoto una vez m\u00e1s advirti\u00f3 que el gobierno nacional que encabeza el presidente Mauricio Macri \u201cviene por nuestros recursos, por menos federalismo, por la entrega de nuestra soberan\u00eda y el empobrecimiento de nuestro pueblo\u201d.<\/p>\n","protected":false},"author":2,"featured_media":80940,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[34],"class_list":["post-80939","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-politico","tag-tierra-del-fuego"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/80939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=80939"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/80939\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/80940"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=80939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=80939"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=80939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}