{"id":80994,"date":"2018-08-31T06:19:45","date_gmt":"2018-08-31T09:19:45","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=80994"},"modified":"2018-08-30T18:29:18","modified_gmt":"2018-08-30T21:29:18","slug":"por-falta-de-pago-del-gobierno-1-500-personas-pobres-pierden-su-tratamiento-de-dialisis","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/por-falta-de-pago-del-gobierno-1-500-personas-pobres-pierden-su-tratamiento-de-dialisis\/","title":{"rendered":"Por falta de pago del Gobierno, 1.500 personas pobres pierden su tratamiento de di\u00e1lisis"},"content":{"rendered":"<p>Alrededor de 200 centros de salud privados dejar\u00e1n de brindar el servicio porque el gobierno nacional les debe 250 millones de pesos.<\/p>\n<p>La\u00a0Confederaci\u00f3n de Asociaciones de Di\u00e1lisis de la Rep\u00fablica Argentina (CADRA)\u00a0advirti\u00f3 que\u00a0m\u00e1s de 1.500 pacientes\u00a0que son beneficiarios del programa federal\u00a0Incluir Salud\u00a0(ex ProFe) perder\u00e1n su derecho al servicio que recib\u00edan porque el gobierno nacional les debe a unos 200 centros privados de todo el pa\u00eds la suma de 250 millones de pesos.<\/p>\n<p>La medida afecta a personas humildes que asisten a esos centros para ser tratados unas tres veces por semana. Asimismo, seg\u00fan la CADRA, hace m\u00e1s de un a\u00f1o que la gesti\u00f3n de Cambiemos dej\u00f3 de pagar.<\/p>\n<p>Seg\u00fan alertaron los especialistas m\u00e9dicos, si no reciben el tratamiento, \u201cpueden perder sus vidas en cuesti\u00f3n de semanas\u201d.<\/p>\n<p>\u201cEn sendas cartas documento enviadas al titular de la Agencia Nacional de Discapacidad,\u00a0Santiago Ibarz\u00e1bal\u00a0y al responsable del Programa Federal,\u00a0Pablo Atchabahian, los directivos de CADRA piden una soluci\u00f3n inmediata para evitar consecuencias no deseadas\u201d, se\u00f1al\u00f3 la entidad a trav\u00e9s de un comunicado.<\/p>\n<p>Al respecto, el titular de esa entidad, Dar\u00edo Zapata, asegur\u00f3 ante Radio Real Politik que \u201cel desfinanciamiento que sufren los centros de di\u00e1lisis del pa\u00eds se debe, entre otros motivos, al desfasaje de los costos de los materiales, el incremento de los honorarios profesionales y sueldos y la demora en el pago de las prestaciones\u201d.<\/p>\n<p>Incluir Salud, que pas\u00f3 a depender este a\u00f1o de la Agencia Nacional de Discapacidad, es un Sistema de Aseguramiento P\u00fablicdo de Salud que garantiza el acceso a los servicios de salud a madres de siete o m\u00e1s hijos, personas con discapacidad y adultos mayores de 70 a\u00f1os titulares de Pensiones No Contributivas (PNC).<\/p>\n<p>\u201cEl tratamiento hace que el paciente se mantenga con vida. Dej\u00e1s de dializarlo y en cuesti\u00f3n de semanas pierde su vida. Es una enfermedad extremadamente grave que pone en juego la vida del paciente\u201d, apunt\u00f3 Zapata.<\/p>\n<p>\u00abSon tres veces por semana, sesiones de cuatro horas. La dosis estandarizada es 12 horas por semana. El inicio cuesta mucho, pero tambi\u00e9n el mantenimiento. Hay costos fijos extremadamente altos, con insumos importados. Si tuvi\u00e9ramos un ajuste valor d\u00f3lar, podr\u00edamos. Pero si aument\u00f3 el 51% y nos proponen el 20%, con el atraso del a\u00f1o anterior, estamos en una situaci\u00f3n de precarizaci\u00f3n tremenda\u201d, agreg\u00f3.<\/p>\n<h6>Fuente: InfoNews<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Alrededor de 200 centros de salud privados dejar\u00e1n de brindar el servicio porque el gobierno nacional les debe 250 millones de pesos.<\/p>\n","protected":false},"author":2,"featured_media":80995,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[21],"class_list":["post-80994","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-nacional","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/80994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=80994"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/80994\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/80995"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=80994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=80994"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=80994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}