{"id":81055,"date":"2018-08-31T05:12:16","date_gmt":"2018-08-31T08:12:16","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=81055"},"modified":"2018-08-31T08:17:11","modified_gmt":"2018-08-31T11:17:11","slug":"fuerte-critica-al-gobierno-nacional-de-los-intendentes-rionegrinos-de-juntos","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/fuerte-critica-al-gobierno-nacional-de-los-intendentes-rionegrinos-de-juntos\/","title":{"rendered":"Fuerte cr\u00edtica al gobierno nacional de los intendentes rionegrinos de Juntos"},"content":{"rendered":"<p>Reunidos en R\u00edo Colorado, emitieron un duro documento por los recortes a las provincias y a las universidades.<\/p>\n<p>Los intendentes del oficialista Juntos Somos R\u00edo Negro salieron ayer, desde R\u00edo Colorado, donde realizaron una nueva reuni\u00f3n del c\u00f3nclave, con un documento muy duro frente a las medidas del gobierno nacional. Criticaron la poda de env\u00edos a las provincias, el recorte a los subsidios, la restricci\u00f3n a las universidades y denunciaron un parate en la obra p\u00fablica.<\/p>\n<p>\u201cLos intendentes de Juntos Somos R\u00edo Negro nos reunimos en R\u00edo Colorado preocupados por la situaci\u00f3n econ\u00f3mica nacional, especialmente las medidas que afectan a los rionegrinos como la quita del subsidio al gas, la quita del subsidio al transporte y la eliminaci\u00f3n del fondo sojero\u201d, dice el documento.<\/p>\n<p>\u201cLa eliminaci\u00f3n del fondo sojero afecta las econom\u00edas municipales, quitando 222 millones a los municipios y m\u00e1s de 700 millones al gobierno provincial. El dinero que las localidades recib\u00edan se utilizaba para obras p\u00fablicas permitiendo la ejecuci\u00f3n de obras de grandes dimensiones que hoy van a quedar relegadas\u201d, advirtieron.<\/p>\n<p>\u201cAdem\u00e1s, el gobierno nacional desfinancia las universidades, lleva a cabo acciones que debilitan la educaci\u00f3n, que perjudican el trabajo genuino y elevan el costo de vida de la poblaci\u00f3n\u201d, a\u00f1adieron.<\/p>\n<p>\u201cSumado a esto -contin\u00faa la declaraci\u00f3n-, nos preocupa tambi\u00e9n la paralizaci\u00f3n de la obra p\u00fablica nacional, lo que perjudica a las econom\u00edas locales que dependen de este movimiento econ\u00f3mico para llevar el pan a su mesa\u201d.<\/p>\n<p>Este diagn\u00f3stico lo contrapusieron con el reparto del \u201cgobierno de Alberto Weretilneck\u201d a los municipios con fondos provenientes del Plan Castello, financiado con la emisi\u00f3n de bonos en d\u00f3lares.<\/p>\n<p>Este plan -dijeron \u201cllevar\u00e1 a cabo 26 obras por un monto de m\u00e1s de 8.000 millones de pesos, lo que les permitir\u00e1 a los gobiernos locales mejorar la infraestructura municipal y realizar obras p\u00fablicas con este fondo, generando trabajo con mano de obra local\u201d.<\/p>\n<p>\u201cCreemos firmemente que la pol\u00edtica de Juntos Somos R\u00edo Negro es solidaria, que persigue el bienestar de cada habitante, sin importar el lugar en el que resida y con este pensamiento llevaremos adelante las gestiones que sean necesarias para poder contar nuevamente con el Fondo Sojero o encontrar la manera de contar con fondos para los municipios\u201d, termina el pronunciamiento.<\/p>\n<h6>Fuente: R\u00edo Negro<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Reunidos en R\u00edo Colorado, emitieron un duro documento por los recortes a las provincias y a las universidades.<\/p>\n","protected":false},"author":2,"featured_media":81056,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[11],"class_list":["post-81055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-politico","tag-rio-negro"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/81055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=81055"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/81055\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/81056"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=81055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=81055"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=81055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}